{"id":58803,"date":"2024-01-23T13:04:24","date_gmt":"2024-01-23T12:04:24","guid":{"rendered":"https:\/\/www.escura.com\/?p=58803"},"modified":"2024-02-14T11:51:21","modified_gmt":"2024-02-14T10:51:21","slug":"novedades-en-los-reglamentos-del-irpf-y-del-is","status":"publish","type":"post","link":"https:\/\/www.escura.com\/es\/novedades-en-los-reglamentos-del-irpf-y-del-is\/","title":{"rendered":"Novedades en los reglamentos del IRPF y del IS"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:104%;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_3_4 3_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:75%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.56%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:2.56%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-space-around fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"1920\" height=\"625\" alt=\"Novedades en los reglamentos del IRPF y del IS\" title=\"Economia\" src=\"https:\/\/www.escura.com\/wp-content\/uploads\/2022\/06\/MEDIDA-IMAGEN-CIRCULARES-9.png\" class=\"img-responsive wp-image-34241\" srcset=\"https:\/\/www.escura.com\/wp-content\/uploads\/2022\/06\/MEDIDA-IMAGEN-CIRCULARES-9-200x65.png 200w, https:\/\/www.escura.com\/wp-content\/uploads\/2022\/06\/MEDIDA-IMAGEN-CIRCULARES-9-400x130.png 400w, https:\/\/www.escura.com\/wp-content\/uploads\/2022\/06\/MEDIDA-IMAGEN-CIRCULARES-9-600x195.png 600w, https:\/\/www.escura.com\/wp-content\/uploads\/2022\/06\/MEDIDA-IMAGEN-CIRCULARES-9-800x260.png 800w, https:\/\/www.escura.com\/wp-content\/uploads\/2022\/06\/MEDIDA-IMAGEN-CIRCULARES-9-1200x391.png 1200w, https:\/\/www.escura.com\/wp-content\/uploads\/2022\/06\/MEDIDA-IMAGEN-CIRCULARES-9.png 1920w\" sizes=\"(max-width: 1024px) 100vw, (max-width: 850px) 100vw, 1920px\" \/><\/span><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:30px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-1\"><p style=\"text-align: right;\"><a href=\"https:\/\/www.escura.com\/wp-content\/uploads\/2024\/01\/06-24-NOVEDADES-EN-LOS-REGLAMENTOS-DEL-IRPF-Y-DEL-IS.pdf\">Consulte el pdf<\/a><\/p>\n<h1 class=\"\" data-fontsize=\"34\" data-lineheight=\"47.94px\">Novedades en los reglamentos del IRPF y del IS<\/h1>\n<p><strong>Mediante el Real Decreto 1008\/2023, que entr\u00f3 en vigor el 7 de diciembre de 2023<\/strong>, se adaptan los textos reglamentarios del IRPF y del IS a los cambios operados, en el caso del IRPF, por la <strong>Ley de Presupuestos Generales del Estado<\/strong> para el a\u00f1o 2023 y la Ley de fomento del ecosistema de las empresas emergentes, y, en el supuesto del IS, a los cambios producidos en la regulaci\u00f3n de las infraestructuras de post contrataci\u00f3n y en el r\u00e9gimen de aportaci\u00f3n de garant\u00edas para cubrir los riesgos de incumplimiento en la liquidaci\u00f3n de las operaciones sobre instrumentos financieros.<\/p>\n<p><strong>\u00cdndice<\/strong><\/p>\n<ol>\n<li><strong>Modificaciones del Reglamento del IRPF (RD 439\/2007)<\/strong><\/li>\n<\/ol>\n<p style=\"padding-left: 40px;\"><strong>1.1<\/strong> Exenci\u00f3n de los rendimientos del trabajo derivados de la entrega de acciones o participaciones a trabajadores (art. 43.2.1\u00ba RIRPF)<\/p>\n<p style=\"padding-left: 40px;\"><strong>1.2<\/strong> Deducci\u00f3n por maternidad (art. 80 RIRPF)<\/p>\n<p style=\"padding-left: 40px;\"><strong>1.3<\/strong> Obligaci\u00f3n de declarar (art. 61. 2 y 3 RIRPF)<\/p>\n<p style=\"padding-left: 40px;\"><strong>1.4<\/strong> Tipo de retenci\u00f3n sobre los rendimientos del trabajo derivados de la elaboraci\u00f3n de obras literarias, art\u00edsticas o cient\u00edficas (art. 80.1.4\u00ba RIRPF)<\/p>\n<p style=\"padding-left: 40px;\"><strong>1.5 <\/strong>Tipo de retenci\u00f3n de la propiedad intelectual (art. 101.2 RIRPF)<\/p>\n<p style=\"padding-left: 40px;\"><strong>1.6<\/strong> R\u00e9gimen especial aplicable a los trabajadores, profesionales, emprendedores e inversores desplazados a territorio espa\u00f1ol -r\u00e9gimen de impatriados- (Cap\u00edtulo I del T\u00edtulo VIII -arts. 113 a 119- RIRPF)<\/p>\n<p style=\"padding-left: 40px;\"><strong>1.7<\/strong> Reducci\u00f3n de los pagos a cuenta aplicables en el per\u00edodo impositivo 2023 a rendimientos obtenidos en la isla de La Palma (disp. adic. d\u00e9cima)<\/p>\n<p style=\"padding-left: 40px;\"><span style=\"background-color: var(--awb-bg-color-hover); color: var(--awb-text-color); font-family: var(--awb-text-font-family); font-size: var(--awb-font-size); font-style: var(--awb-text-font-style); letter-spacing: var(--awb-letter-spacing); text-transform: var(--awb-text-transform);\">2. <\/span><span style=\"background-color: var(--awb-bg-color-hover); color: var(--awb-text-color); font-family: var(--awb-text-font-family); font-size: var(--awb-font-size); font-style: var(--awb-text-font-style); font-weight: bolder; letter-spacing: var(--awb-letter-spacing); text-transform: var(--awb-text-transform);\">Modificaciones del Reglamento del Impuesto sobre Sociedades (RD 634\/2015)<\/span><\/p>\n<p style=\"padding-left: 40px;\"><strong>2.1<\/strong> Excepciones a la obligaci\u00f3n de retener y de ingresar a cuenta [art. 61, e) RIS]<\/p>\n<p><strong><span style=\"font-size: 18px;\" data-fusion-font=\"true\"> 1.<\/span> <\/strong><strong style=\"color: var(--h3_typography-color); font-family: var(--h3_typography-font-family); font-size: var(--h3_typography-font-size); font-style: var(--h3_typography-font-style,normal); letter-spacing: var(--h3_typography-letter-spacing); text-transform: var(--h3_typography-text-transform); text-align: var(--awb-content-alignment); background-color: var(--awb-bg-color-hover);\">Modificaciones del Reglamento del IRPF (RD 439\/2007)<\/strong><\/p>\n<p><u>1.1 Exenci\u00f3n de los rendimientos del trabajo derivados de la entrega de acciones o participaciones a trabajadores (art. 43.2.1\u00ba RIRPF)<\/u><\/p>\n<p>Se modifica el citado precepto para adaptar su contenido a los cambios introducidos en la LIRPF en relaci\u00f3n con la exenci\u00f3n de los rendimientos del trabajo derivados de la <strong>entrega de acciones o participaciones a trabajadores de empresas emergentes<\/strong>, al no exigirse en este supuesto, que la oferta se realice en las mismas condiciones para todos los trabajadores de la misma.<\/p>\n<p><u><b>1.2 Deducci\u00f3n por maternidad (art. 80 RIRPF)<\/b><\/u><\/p>\n<p>Se adapta su contenido a la nueva regulaci\u00f3n legal en la que se ha ampliado el colectivo beneficiario de la misma a las madres que en el momento del nacimiento del menor estuvieran percibiendo prestaciones por desempleo o est\u00e9n dadas de alta en el r\u00e9gimen correspondiente de la Seguridad Social o mutualidad, o, bien que, en cualquier momento posterior al nacimiento, est\u00e9n dadas de alta en el r\u00e9gimen correspondiente de la Seguridad Social o mutualidad con un per\u00edodo m\u00ednimo de 30 d\u00edas cotizados, desapareciendo la limitaci\u00f3n a las cotizaciones devengadas en el per\u00edodo impositivo. Adem\u00e1s, la norma aclara su aplicaci\u00f3n en los casos de adopci\u00f3n, acogimiento permanente o delegaci\u00f3n de guarda para la convivencia, donde se atender\u00e1 a la fecha de su inscripci\u00f3n en el Registro Civil o, en su caso, a la fecha de la resoluci\u00f3n judicial o administrativa, en lugar de la fecha de nacimiento del menor.<\/p>\n<p><u><b>1.3 Obligaci\u00f3n de declarar (art. 61. 2 y 3 RIRPF)<\/b><\/u><\/p>\n<p>Se incorpora la obligaci\u00f3n legal de declarar establecida para todas aquellas personas f\u00edsicas que en cualquier momento del per\u00edodo impositivo hubieran estado de alta, como trabajadores por cuenta propia, en <strong>el R\u00e9gimen Especial de Trabajadores<\/strong> por <strong>Cuenta Propia<\/strong> o <strong>Aut\u00f3nomos<\/strong>, o en <strong>el R\u00e9gimen Especial de la Seguridad Social<\/strong> de los Trabajadores del Mar y la elevaci\u00f3n del umbral inferior de la obligaci\u00f3n de declarar correspondiente a rendimientos de trabajo aplicable, entre otros casos, cuando tales rendimientos procedan de m\u00e1s de un pagador, de 14.000 a 15.000 euros anuales.<\/p>\n<p><u><b>1.4 Tipo de retenci\u00f3n sobre los rendimientos del trabajo derivados de la elaboraci\u00f3n de obras literarias, art\u00edsticas o cient\u00edficas (art. 80.1.4\u00ba RIRPF)<\/b><\/u><\/p>\n<p>Al igual que en la LIRPF se establece que el porcentaje de retenci\u00f3n sobre los rendimientos del trabajo derivados de la elaboraci\u00f3n de obras literarias, art\u00edsticas o cient\u00edficas ser\u00e1 del 7 por ciento cuando el volumen de tales rendimientos \u00edntegros correspondiente al ejercicio inmediato anterior sea inferior a 15.000 euros y represente m\u00e1s del 75 por ciento de la suma de los rendimientos \u00edntegros de actividades econ\u00f3micas y del trabajo obtenidos por el contribuyente en dicho ejercicio. Para la aplicaci\u00f3n de este tipo de retenci\u00f3n, los contribuyentes deber\u00e1n comunicar al pagador de los rendimientos la concurrencia de dichas circunstancias, quedando obligado el pagador a conservar la comunicaci\u00f3n debidamente firmada.<\/p>\n<p><u><b>1.5 Tipo de retenci\u00f3n de la propiedad intelectual (art. 101.2 RIRPF)<\/b><\/u><\/p>\n<p>Se aclara que el tipo de retenci\u00f3n de la propiedad intelectual sea cual sea su calificaci\u00f3n es del 15 por ciento, salvo cuando resulte de aplicaci\u00f3n el tipo de retenci\u00f3n del 7 por ciento.<\/p>\n<p><u><b>1.6 R\u00e9gimen especial aplicable a los trabajadores, profesionales, emprendedores e inversores desplazados a territorio espa\u00f1ol -r\u00e9gimen de impatriados- (Cap\u00edtulo I del T\u00edtulo VIII -arts. 113 a 119- RIRPF)<\/b><\/u><\/p>\n<p>Como consecuencia de los cambios introducidos en la LIRPF por la Ley 28\/2022, de 21 de diciembre, de fomento del ecosistema de las empresas emergentes, donde se efectu\u00f3 una extensi\u00f3n del r\u00e9gimen de impatriados a nuevos supuestos, como los relacionados con el teletrabajo, emprendedores innovadores, profesionales altamente cualificados o contribuyentes que realizan actividades de formaci\u00f3n, investigaci\u00f3n, desarrollo e innovaci\u00f3n o familiares acompa\u00f1antes, se introducen en el cap\u00edtulo que regula este r\u00e9gimen especial diversas modificaciones para adaptar su contenido a la regulaci\u00f3n legal.<\/p>\n<p>As\u00ed la <strong>r\u00fabrica del cap\u00edtulo<\/strong> que se denominaba \u00abR\u00e9gimen especial aplicable a los trabajadores desplazados a territorio espa\u00f1ol\u00bb pasa a denominarse ahora <strong>\u00abR\u00e9gimen especial aplicable a los trabajadores, profesionales, emprendedores e inversores desplazados a territorio espa\u00f1ol\u00bb.<\/strong><\/p>\n<p>En lo referente al <strong>\u00e1mbito de aplicaci\u00f3n<\/strong> regulado en el art\u00edculo 113 del RIRPF se modifica su contenido para adaptar su redacci\u00f3n al nuevo \u00e1mbito subjetivo de aplicaci\u00f3n del mismo, que como se ha indicado anteriormente se ha extendido a nuevos supuestos (teletrabajo, emprendedores innovadores, profesionales altamente cualificados o contribuyentes que realizan actividades de formaci\u00f3n, investigaci\u00f3n, desarrollo e innovaci\u00f3n o familiares acompa\u00f1antes).<\/p>\n<p>Adem\u00e1s, <strong>Se define cu\u00e1ndo una actividad se calificar\u00e1 como emprendedora<\/strong> aquella que sea innovadora y\/o tenga especial inter\u00e9s econ\u00f3mico para Espa\u00f1a y a tal efecto cuente con un informe favorable emitido por la Empresa Nacional de Innovaci\u00f3n, SME (ENISA), en los t\u00e9rminos establecidos en el art\u00edculo 70 de la Ley de apoyo a los emprendedores y su internacionalizaci\u00f3n, siendo necesario disponer de la autorizaci\u00f3n de residencia para actividad empresarial, con car\u00e1cter previo a su desplazamiento a territorio espa\u00f1ol.<\/p>\n<p>Tambi\u00e9n <strong>se define quienes son profesionales altamente cualificados<\/strong> aquellos profesionales que cuenten con la titulaci\u00f3n a la que se refiere el art\u00edculo 71 de la Ley de apoyo a los emprendedores y su internacionalizaci\u00f3n.<\/p>\n<p>Asimismo, <strong>se considerar\u00e1 que se llevan a cabo actividades de formaci\u00f3n, investigaci\u00f3n, desarrollo e innovaci\u00f3n<\/strong> cuando concurra alguno de los supuestos a que se refieren las letras a), b), c) y d) del apartado 1 del art\u00edculo 72 de la citada Ley de apoyo a los emprendedores y su internacionalizaci\u00f3n, esto es el personal investigador, el personal cient\u00edfico y t\u00e9cnico que lleve a cabo trabajos de investigaci\u00f3n cient\u00edfica, desarrollo e innovaci\u00f3n tecnol\u00f3gica, en entidades empresariales o centros de I+D+i establecidos en Espa\u00f1a, los investigadores acogidos en el marco de un convenio por organismos de investigaci\u00f3n p\u00fablicos o privados o los profesores contratados por universidades, \u00f3rganos o centros de educaci\u00f3n superior e investigaci\u00f3n, o escuelas de negocios establecidos en Espa\u00f1a.<\/p>\n<p>Se establece que, durante los per\u00edodos impositivos de aplicaci\u00f3n de este r\u00e9gimen especial, las \u00fanicas actividades econ\u00f3micas que podr\u00e1n desarrollar los contribuyentes acogidos al mismo son la actividad econ\u00f3mica de car\u00e1cter emprendedor, la prestaci\u00f3n de servicios a empresas emergentes o las actividades de formaci\u00f3n, investigaci\u00f3n, desarrollo e innovaci\u00f3n.<\/p>\n<p>Adicionalmente, <strong>se aclara el plazo para que se desplacen a territorio espa\u00f1ol los familiares del contribuyente acogido al r\u00e9gimen especial<\/strong>: antes o despu\u00e9s de que se desplace el contribuyente, siempre que, como consecuencia del referido desplazamiento, de ser anterior, estos no adquieran la residencia fiscal en Espa\u00f1a antes del primer per\u00edodo impositivo en el que a este le resulte de aplicaci\u00f3n el r\u00e9gimen especial o, de ser posterior, no hubiera finalizado este \u00faltimo.<\/p>\n<p>Se modifica el art\u00edculo 114 relativo al <strong>contenido del r\u00e9gimen especial de tributaci\u00f3n por el Impuesto sobre la Renta de no Residentes,<\/strong> para aclarar las especialidades en materia de retenciones y obligaciones formales de los nuevos supuestos legalmente establecidos de acceso al r\u00e9gimen especial.<\/p>\n<p>En relaci\u00f3n con los <strong>familiares que acompa\u00f1en al contribuyente que tambi\u00e9n se acoge al r\u00e9gimen especial,<\/strong> se adapta la duraci\u00f3n del r\u00e9gimen recogida en el art\u00edculo 115 del RIRPF, en los mismos t\u00e9rminos que los previstos legalmente (hasta el \u00faltimo periodo impositivo en que el mismo resulte aplicable al contribuyente), as\u00ed como el ejercicio de la opci\u00f3n de tributar por este r\u00e9gimen (art. 116 RIRPF) respecto de los familiares que acompa\u00f1en al contribuyente que se acoge al r\u00e9gimen especial, aclarando tanto el plazo para su ejercicio como el momento en el que han de tener en cuenta las circunstancias legalmente exigidas.<\/p>\n<p>Se modifican los art\u00edculos 117 y 118 del reglamento con el objetivo de adaptar, respectivamente, las <strong>reglas de renuncia y exclusi\u00f3n a la nueva regulaci\u00f3n legal<\/strong>. En particular, respecto de los familiares que acompa\u00f1en al contribuyente que tambi\u00e9n se acoge al r\u00e9gimen especial se establece, con car\u00e1cter general, la renuncia y la exclusi\u00f3n de manera individual, salvo en determinados supuestos en los que puede operar una exclusi\u00f3n colectiva.<\/p>\n<p>El art\u00edculo 119 establece la <strong>documentaci\u00f3n que debe acompa\u00f1ar a la comunicaci\u00f3n en el caso de aplicaci\u00f3n del r\u00e9gimen especial<\/strong> por parte de dichos contribuyentes, regulando, en particular, dicha documentaci\u00f3n en relaci\u00f3n con los nuevos supuestos de acceso al r\u00e9gimen especial establecidos legalmente.<\/p>\n<p><strong>R\u00e9gimen transitorio.<\/strong> Se introduce una nueva disposici\u00f3n transitoria vig\u00e9sima estableciendo el plazo para el ejercicio de la opci\u00f3n por dicho r\u00e9gimen para los contribuyentes que adquieran su residencia fiscal en Espa\u00f1a en el periodo impositivo 2023 como consecuencia de un desplazamiento a territorio espa\u00f1ol realizado en 2022 o en 2023 antes de la entrada en vigor de la orden ministerial que apruebe el nuevo modelo de comunicaci\u00f3n de la opci\u00f3n por el mismo: ser\u00e1 de seis meses desde la fecha de entrada en vigor de dicha Orden, salvo cuando el art\u00edculo 116 del RIRPF le otorgue un plazo superior.<\/p>\n<p>Asimismo, se aclara que los trabajadores o administradores, supuestos a los que ya era de aplicaci\u00f3n el r\u00e9gimen especial, tambi\u00e9n podr\u00e1n ejercer la opci\u00f3n por el citado r\u00e9gimen especial con anterioridad a la fecha de entrada en vigor de la citada orden.<\/p>\n<p><u><b>1.7 Reducci\u00f3n de los pagos a cuenta aplicables en el per\u00edodo impositivo 2023 a rendimientos obtenidos en la isla de La Palma (disp. adic. d\u00e9cima)<\/b><\/u><\/p>\n<p>Se adapta el reglamento, en materia de pagos a cuenta, a la deducci\u00f3n por rentas obtenidas en la isla de La Palma para contribuyentes con residencia habitual y efectiva en dicha isla en el periodo impositivo 2023, al establecer que en el referido per\u00edodo las referencias contenidas a Ceuta y Melilla en el t\u00edtulo VII del reglamento (pagos a cuenta) se entender\u00e1n igualmente efectuadas a la isla de La Palma.<\/p>\n<p><span style=\"font-family: var(--h3_typography-font-family); font-style: var(--h3_typography-font-style,normal); letter-spacing: var(--h3_typography-letter-spacing); text-transform: var(--h3_typography-text-transform); text-align: var(--awb-content-alignment); background-color: var(--awb-bg-color-hover); font-size: 18px;\" data-fusion-font=\"true\"><b>2. <\/b><\/span><strong style=\"color: var(--h3_typography-color); font-family: var(--h3_typography-font-family); font-size: var(--h3_typography-font-size); font-style: var(--h3_typography-font-style,normal); letter-spacing: var(--h3_typography-letter-spacing); text-transform: var(--h3_typography-text-transform); text-align: var(--awb-content-alignment); background-color: var(--awb-bg-color-hover);\"><span style=\"font-size: 18px;\" data-fusion-font=\"true\">Modificaciones<\/span> del Reglamento del Impuesto sobre Sociedades (RD 634\/2015)<\/strong><\/p>\n<p><u>2.1 Excepciones a la obligaci\u00f3n de retener y de ingresar a cuenta [art. 61, e) RIS]<\/u><\/p>\n<p>Se excluye de la obligaci\u00f3n de practicar retenci\u00f3n sobre los intereses procedentes del r\u00e9gimen de garant\u00edas de las ECC establecido en la Ley de los Mercados de Valores y de los Servicios de Inversi\u00f3n, en el Reglamento (UE) n\u00ba 648\/2012, y en los Reglamentos de dichas entidades y en sus circulares de desarrollo.<\/p>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-2\"><p style=\"text-align: left;\">Circular facilitada por ETL<\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_4 1_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:7.68%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:7.68%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-search-element fusion-search-element-1 fusion-search-form-clean\">\t\t<form role=\"search\" class=\"searchform fusion-search-form  fusion-search-form-clean\" method=\"get\" action=\"https:\/\/www.escura.com\/es\/\">\n\t\t\t<div class=\"fusion-search-form-content\">\n\n\t\t\t\t\n\t\t\t\t<div class=\"fusion-search-field search-field\">\n\t\t\t\t\t<label><span class=\"screen-reader-text\">Buscar:<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input type=\"search\" value=\"\" name=\"s\" class=\"s\" placeholder=\"Search...\" required aria-required=\"true\" aria-label=\"Search...\"\/>\n\t\t\t\t\t\t\t\t\t\t\t<\/label>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"fusion-search-button search-button\">\n\t\t\t\t\t<input type=\"submit\" class=\"fusion-search-submit searchsubmit\" aria-label=\"Buscar\" value=\"&#xf002;\" \/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<input type=\"hidden\" name=\"post_type[]\" value=\"post\" \/><input type=\"hidden\" name=\"post_type[]\" value=\"page\" \/><input type=\"hidden\" name=\"post_type[]\" value=\"avada_portfolio\" \/><input type=\"hidden\" name=\"post_type[]\" value=\"avada_faq\" \/><input type=\"hidden\" name=\"search_limit_to_post_titles\" value=\"0\" \/><input type=\"hidden\" name=\"add_woo_product_skus\" value=\"0\" \/><input type=\"hidden\" name=\"fs\" value=\"1\" \/>\n\t\t\t<\/div>\n\n\n\t\t\t\n\t\t<\/form>\n\t\t<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:30px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-3\"><h3><span style=\"color: #000080;\">Nuestras \u00c1reas<\/span><\/h3>\n<\/div><ul style=\"--awb-iconcolor:var(--awb-color6);--awb-line-height:27.2px;--awb-icon-width:27.2px;--awb-icon-height:27.2px;--awb-icon-margin:11.2px;--awb-content-margin:38.4px;\" class=\"fusion-checklist fusion-checklist-1 fusion-checklist-default type-icons\"><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon awb-icon-check\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<div class=\"fusion-text fusion-text-1\">\n<p data-fontsize=\"26\" data-lineheight=\"31.46px\"><a href=\"https:\/\/www.escura.com\/es\/compliance-penal\/\">Compliance Penal<\/a><\/p>\n<\/div>\n<div class=\"fusion-text fusion-text-2\"><\/div>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon awb-icon-check\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p><a href=\"https:\/\/www.escura.com\/es\/derecho-societario-mercantil\/\">Derecho Societario y Mercantil<\/a><\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon awb-icon-check\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p><a href=\"https:\/\/www.escura.com\/es\/economico-fiscal\/\">Econ\u00f3mico Fiscal<\/a><\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon awb-icon-check\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p><a href=\"https:\/\/www.escura.com\/es\/plan-de-igualdad\/\">Plan de Igualdad<\/a><\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon awb-icon-check\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p><a href=\"https:\/\/www.escura.com\/es\/proteccion-de-datos\/\">Protecci\u00f3n de Datos<\/a><\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon awb-icon-check\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p><a href=\"https:\/\/www.escura.com\/es\/recursos-humanos\/\">Recursos Humanos<\/a><\/p>\n<\/div><\/li><\/ul><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:30px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-4\"><h3><span style=\"color: #000080;\">Nuestras Oficinas<\/span><\/h3>\n<\/div><div class=\"fusion-text fusion-text-5\"><h4><a href=\"https:\/\/www.escura.com\/es\/abogados-barcelona\/\">\u2192 Abogados Barcelona\u00a0<\/a><\/h4>\n<h4><a href=\"https:\/\/www.escura.com\/es\/abogados-madrid\/\">\u2192 Abogados Madrid<\/a><\/h4>\n<h4><a href=\"https:\/\/www.escura.com\/es\/oficinas-calafell-vendrell\/\">\u2192 Abogados Tarragona<\/a><\/h4>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:30px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-6\"><h3><span style=\"color: #000080;\">Nuestras Redes<\/span><\/h3>\n<\/div><div class=\"fusion-social-links fusion-social-links-1\" style=\"--awb-margin-top:0px;--awb-margin-right:0px;--awb-margin-bottom:0px;--awb-margin-left:0px;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:rgba(0,0,0,0.8);--awb-box-colors-hover:rgba(21,59,122,0.8);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:#ffffff;font-size:14px;width:14px;background-color:#153b7a;border-color:#153b7a;border-radius:3px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.linkedin.com\/feed\/\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-instagram awb-icon-instagram\" style=\"color:#ffffff;font-size:14px;width:14px;background-color:#153b7a;border-color:#153b7a;border-radius:3px;\" data-placement=\"top\" data-title=\"Instagram\" data-toggle=\"tooltip\" title=\"Instagram\" aria-label=\"instagram\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.instagram.com\/escura_abogados\/\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-facebook awb-icon-facebook\" style=\"color:#ffffff;font-size:14px;width:14px;background-color:#153b7a;border-color:#153b7a;border-radius:3px;\" data-placement=\"top\" data-title=\"Facebook\" data-toggle=\"tooltip\" title=\"Facebook\" aria-label=\"facebook\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.facebook.com\/escura.abogados\/\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-twitter awb-icon-twitter\" style=\"color:#ffffff;font-size:14px;width:14px;background-color:#153b7a;border-color:#153b7a;border-radius:3px;\" data-placement=\"top\" data-title=\"X\" data-toggle=\"tooltip\" title=\"X\" aria-label=\"twitter\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"#\"><\/a><\/div><\/div><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:30px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-7\"><h3 class=\"\" data-fontsize=\"18\" data-lineheight=\"30.06px\"><span style=\"color: #000080;\">Solicita m\u00e1s informaci\u00f3n<\/span><\/h3>\n<h3 class=\"\" data-fontsize=\"18\" data-lineheight=\"30.06px\"><a href=\"mailto:escura@escura.com\">escura@escura.com<\/a><\/h3>\n<h3 class=\"\" data-fontsize=\"18\" data-lineheight=\"30.06px\"><a href=\"tel:934940131\">93 494 01 31<\/a><\/h3>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-background-color:#e5e5e5;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:104%;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-text fusion-text-8\"><h3 class=\"fusion-responsive-typography-calculated\" style=\"--fontsize: 18; line-height: 1.67; --minfontsize: 18;\" data-fontsize=\"18\" data-lineheight=\"30.06px\"><a href=\"https:\/\/www.escura.com\/es\/economico-fiscal\/\">M\u00e1s informaci\u00f3n en el <b>\u00c1rea de Fiscal<\/b><\/a><\/h3>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":31029,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[578,223,417],"class_list":["post-58803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiscal-contable","tag-fiscalidad","tag-impuesto-de-sociedades","tag-irpf"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Novedades en los reglamentos del IRPF y del IS<\/title>\n<meta name=\"description\" content=\"La presente circular escrita por el equipo de profesionales de Escura habla sobre las Novedades en los reglamentos del IRPF y del IS\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.escura.com\/es\/novedades-en-los-reglamentos-del-irpf-y-del-is\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novedades en los reglamentos del IRPF y del IS\" \/>\n<meta property=\"og:description\" content=\"La presente circular escrita por el equipo de profesionales de Escura habla sobre las Novedades en los reglamentos del IRPF y del IS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.escura.com\/es\/novedades-en-los-reglamentos-del-irpf-y-del-is\/\" \/>\n<meta property=\"og:site_name\" content=\"Escura | Abogados y Economistas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/escura.abogados\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-23T12:04:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-14T10:51:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.escura.com\/wp-content\/uploads\/2022\/05\/AdobeStock_234154184-1-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adminbe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:site\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminbe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/novedades-en-los-reglamentos-del-irpf-y-del-is\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/novedades-en-los-reglamentos-del-irpf-y-del-is\\\/\"},\"author\":{\"name\":\"adminbe\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/7a91eddf0c7dd9b28ddc69906b14e30e\"},\"headline\":\"Novedades en los reglamentos del IRPF y del IS\",\"datePublished\":\"2024-01-23T12:04:24+00:00\",\"dateModified\":\"2024-02-14T10:51:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/novedades-en-los-reglamentos-del-irpf-y-del-is\\\/\"},\"wordCount\":3715,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/novedades-en-los-reglamentos-del-irpf-y-del-is\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/AdobeStock_234154184-1-scaled.jpeg\",\"keywords\":[\"fiscalidad\",\"impuesto de sociedades\",\"IRPF\"],\"articleSection\":[\"Fiscal - Contable\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/novedades-en-los-reglamentos-del-irpf-y-del-is\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/novedades-en-los-reglamentos-del-irpf-y-del-is\\\/\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/novedades-en-los-reglamentos-del-irpf-y-del-is\\\/\",\"name\":\"Novedades en los reglamentos del IRPF y del IS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/novedades-en-los-reglamentos-del-irpf-y-del-is\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/novedades-en-los-reglamentos-del-irpf-y-del-is\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/AdobeStock_234154184-1-scaled.jpeg\",\"datePublished\":\"2024-01-23T12:04:24+00:00\",\"dateModified\":\"2024-02-14T10:51:21+00:00\",\"description\":\"La presente circular escrita por el equipo de profesionales de Escura habla sobre las Novedades en los reglamentos del IRPF y del IS\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/novedades-en-los-reglamentos-del-irpf-y-del-is\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/novedades-en-los-reglamentos-del-irpf-y-del-is\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/novedades-en-los-reglamentos-del-irpf-y-del-is\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/AdobeStock_234154184-1-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/AdobeStock_234154184-1-scaled.jpeg\",\"width\":2560,\"height\":1709},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/novedades-en-los-reglamentos-del-irpf-y-del-is\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novedades en los reglamentos del IRPF y del IS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"name\":\"Escura | Abogados y Economistas\",\"description\":\"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.escura.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\",\"name\":\"Escura. Abogados y economistas\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Escura. Abogados y economistas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/escura.abogados\",\"https:\\\/\\\/x.com\\\/escura_abogados\",\"https:\\\/\\\/www.instagram.com\\\/escura_abogados\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bufete-escura\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BufeteEscura\\\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/7a91eddf0c7dd9b28ddc69906b14e30e\",\"name\":\"adminbe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g\",\"caption\":\"adminbe\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Novedades en los reglamentos del IRPF y del IS","description":"La presente circular escrita por el equipo de profesionales de Escura habla sobre las Novedades en los reglamentos del IRPF y del IS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.escura.com\/es\/novedades-en-los-reglamentos-del-irpf-y-del-is\/","og_locale":"es_ES","og_type":"article","og_title":"Novedades en los reglamentos del IRPF y del IS","og_description":"La presente circular escrita por el equipo de profesionales de Escura habla sobre las Novedades en los reglamentos del IRPF y del IS","og_url":"https:\/\/www.escura.com\/es\/novedades-en-los-reglamentos-del-irpf-y-del-is\/","og_site_name":"Escura | Abogados y Economistas","article_publisher":"https:\/\/www.facebook.com\/escura.abogados","article_published_time":"2024-01-23T12:04:24+00:00","article_modified_time":"2024-02-14T10:51:21+00:00","og_image":[{"width":2560,"height":1709,"url":"https:\/\/www.escura.com\/wp-content\/uploads\/2022\/05\/AdobeStock_234154184-1-scaled.jpeg","type":"image\/jpeg"}],"author":"adminbe","twitter_card":"summary_large_image","twitter_creator":"@escura_abogados","twitter_site":"@escura_abogados","twitter_misc":{"Escrito por":"adminbe","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.escura.com\/es\/novedades-en-los-reglamentos-del-irpf-y-del-is\/#article","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/novedades-en-los-reglamentos-del-irpf-y-del-is\/"},"author":{"name":"adminbe","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/7a91eddf0c7dd9b28ddc69906b14e30e"},"headline":"Novedades en los reglamentos del IRPF y del IS","datePublished":"2024-01-23T12:04:24+00:00","dateModified":"2024-02-14T10:51:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.escura.com\/es\/novedades-en-los-reglamentos-del-irpf-y-del-is\/"},"wordCount":3715,"commentCount":0,"publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"image":{"@id":"https:\/\/www.escura.com\/es\/novedades-en-los-reglamentos-del-irpf-y-del-is\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2022\/05\/AdobeStock_234154184-1-scaled.jpeg","keywords":["fiscalidad","impuesto de sociedades","IRPF"],"articleSection":["Fiscal - Contable"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.escura.com\/es\/novedades-en-los-reglamentos-del-irpf-y-del-is\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.escura.com\/es\/novedades-en-los-reglamentos-del-irpf-y-del-is\/","url":"https:\/\/www.escura.com\/es\/novedades-en-los-reglamentos-del-irpf-y-del-is\/","name":"Novedades en los reglamentos del IRPF y del IS","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.escura.com\/es\/novedades-en-los-reglamentos-del-irpf-y-del-is\/#primaryimage"},"image":{"@id":"https:\/\/www.escura.com\/es\/novedades-en-los-reglamentos-del-irpf-y-del-is\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2022\/05\/AdobeStock_234154184-1-scaled.jpeg","datePublished":"2024-01-23T12:04:24+00:00","dateModified":"2024-02-14T10:51:21+00:00","description":"La presente circular escrita por el equipo de profesionales de Escura habla sobre las Novedades en los reglamentos del IRPF y del IS","breadcrumb":{"@id":"https:\/\/www.escura.com\/es\/novedades-en-los-reglamentos-del-irpf-y-del-is\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.escura.com\/es\/novedades-en-los-reglamentos-del-irpf-y-del-is\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/novedades-en-los-reglamentos-del-irpf-y-del-is\/#primaryimage","url":"https:\/\/www.escura.com\/wp-content\/uploads\/2022\/05\/AdobeStock_234154184-1-scaled.jpeg","contentUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2022\/05\/AdobeStock_234154184-1-scaled.jpeg","width":2560,"height":1709},{"@type":"BreadcrumbList","@id":"https:\/\/www.escura.com\/es\/novedades-en-los-reglamentos-del-irpf-y-del-is\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.escura.com\/es\/"},{"@type":"ListItem","position":2,"name":"Novedades en los reglamentos del IRPF y del IS"}]},{"@type":"WebSite","@id":"https:\/\/www.escura.com\/es\/#website","url":"https:\/\/www.escura.com\/es\/","name":"Escura | Abogados y Economistas","description":"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona","publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.escura.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.escura.com\/es\/#organization","name":"Escura. Abogados y economistas","url":"https:\/\/www.escura.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Escura. Abogados y economistas"},"image":{"@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/escura.abogados","https:\/\/x.com\/escura_abogados","https:\/\/www.instagram.com\/escura_abogados\/","https:\/\/www.linkedin.com\/company\/bufete-escura","https:\/\/www.youtube.com\/user\/BufeteEscura\/videos"]},{"@type":"Person","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/7a91eddf0c7dd9b28ddc69906b14e30e","name":"adminbe","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g","caption":"adminbe"}}]}},"_links":{"self":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/58803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/comments?post=58803"}],"version-history":[{"count":6,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/58803\/revisions"}],"predecessor-version":[{"id":59694,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/58803\/revisions\/59694"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media\/31029"}],"wp:attachment":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media?parent=58803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/categories?post=58803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/tags?post=58803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}