{"id":29316,"date":"2022-01-27T13:28:03","date_gmt":"2022-01-27T12:28:03","guid":{"rendered":"https:\/\/blog.escura.com\/?p=19081"},"modified":"2022-07-18T13:59:26","modified_gmt":"2022-07-18T11:59:26","slug":"el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni","status":"publish","type":"post","link":"https:\/\/www.escura.com\/es\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\/","title":{"rendered":"Sentencia Modelo 720 R\u00e9gimen Sancionador"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><h3 style=\"text-align: right;\"><a href=\"http:\/\/www.escura.com\/wp-content\/uploads\/2022\/01\/13-22-sentencia-modelo-720-regimen-sancionador.pdf\">Consulte el PDF<\/a><\/h3>\n<h1><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-17550\" src=\"https:\/\/blog.escura.com\/wp-content\/uploads\/2020\/04\/CC0-305-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>El TJUE ha emitido la sentencia relativa al R\u00e9gimen Sancionador de la Declaraci\u00f3n Informativa sobre bienes y derechos situados en el extranjero (Modelo 720) declar\u00e1ndolo contraria al derecho de la uni\u00f3n<\/h1>\n<p>La sentencia del TJUE C-788\/19 del 27 de enero de 2022 determina que la declaraci\u00f3n informativa sobre bienes y derechos situados en el extranjero (modelo 720) es contraria al derecho de la Uni\u00f3n Europea y declara que Espa\u00f1a ha incumplido en las obligaciones en virtud de la libre circulaci\u00f3n de capitales, concretamente en tres aspectos:<\/p>\n<ul>\n<li>Estableciendo que el incumplimiento o el cumplimiento imperfecto o extempor\u00e1neo de la obligaci\u00f3n informativa, tiene como consecuencia la imposici\u00f3n de las rentas no declaradas correspondientes al valor de esos activos como \u00abganancias patrimoniales no justificadas\u00bb en la base liquidable general del IRPF del \u00faltimo ejercicio no prescrito, sin poder acogerse a la prescripci\u00f3n.<\/li>\n<li>Sancionando el incumplimiento o el cumplimiento imperfecto o extempor\u00e1neo de la obligaci\u00f3n informativa con multas pecuniarias de hasta el 150 % del impuesto calculado sobre las cantidades correspondientes al valor de los bienes o derechos situados en el extranjero.<\/li>\n<li>Aplicando, por el incumplimiento o el cumplimiento imperfecto o extempor\u00e1neo de la obligaci\u00f3n informativa, multas de cuant\u00eda fija cuyo importe no guarda proporci\u00f3n alguna con las sanciones previstas para infracciones similares en un contexto \u00a0puramente nacional y cuyo importe total no est\u00e1 limitado (en el caso de incumplimiento de la obligaci\u00f3n de informar, aplica una multa pecuniaria fija de 5.000 euros por cada dato o conjunto de datos, con un m\u00ednimo de 10.000 euros\/ En el caso de presentaci\u00f3n fuera de plazo sanci\u00f3n de 100 euros por cada dato o conjunto de datos, con un m\u00ednimo de 1.500 euros).<\/li>\n<\/ul>\n<p>Se adjunta el comunicado de prensa del TJUE: <a href=\"https:\/\/curia.europa.eu\/jcms\/upload\/docs\/application\/pdf\/2022-01\/cp220018es.pdf\">La legislaci\u00f3n nacional que obliga a los residentes fiscales en Espa\u00f1a a declarar sus bienes o derechos situados en el extranjero es contraria al Derecho de la Uni\u00f3n (europa.eu)<\/a><\/p>\n<p>La Sentencia no determina que no deba presentarse el modelo 720, sino que establece que el r\u00e9gimen sancionador es contrario al derecho de la Uni\u00f3n Europea incumplido las obligaciones que le incumben a Espa\u00f1a en virtud de la libre circulaci\u00f3n de capitales.<\/p>\n<p>Siendo pr\u00f3xima la presentaci\u00f3n del modelo 720, os mantendremos informados de cualquier comunicado de la Agencia Tributaria debido a su importante trascendencia.<\/p>\n<p>\u00a9 La presente informaci\u00f3n es propiedad de <strong>Escura<\/strong>, <strong>abogados<\/strong> y <strong>economistas<\/strong>, quedando prohibida su reproducci\u00f3n sin permiso expreso.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last banner\" style=\"--awb-padding-top:20px;--awb-padding-right:20px;--awb-padding-bottom:20px;--awb-padding-left:20px;--awb-bg-image:url(&#039;http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/area_economico_fiscal.jpg&#039;);--awb-bg-size:cover;--awb-margin-top:40px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy fusion-column-has-bg-image\" data-bg-url=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/area_economico_fiscal.jpg\"><div class=\"fusion-text fusion-text-2\"><h3><a href=\"https:\/\/www.escura.com\/es\/economico-fiscal\/\" target=\"_blank\" rel=\"noopener\">Consulta nuestra \u00e1rea de <strong>Econ\u00f3mico Fiscal<\/strong><\/a><\/h3>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":28525,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-29316","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiscal-contable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Modelo 720 - R\u00e9gimen Sancionador | ESCURA Abogados<\/title>\n<meta name=\"description\" content=\"El TJUE ha emitido la sentencia relativa al R\u00e9gimen Sancionador de la Declaraci\u00f3n Informativa sobre bienes y derechos situados en el extranjero declar\u00e1ndolo contraria al derecho de la uni\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.escura.com\/es\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sentencia Modelo 720 R\u00e9gimen Sancionador\" \/>\n<meta property=\"og:description\" content=\"El TJUE ha emitido la sentencia relativa al R\u00e9gimen Sancionador de la Declaraci\u00f3n Informativa sobre bienes y derechos situados en el extranjero declar\u00e1ndolo contraria al derecho de la uni\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.escura.com\/es\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\/\" \/>\n<meta property=\"og:site_name\" content=\"Escura | Abogados y Economistas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/escura.abogados\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-27T12:28:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-18T11:59:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/04\/CC0-305.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"860\" \/>\n\t<meta property=\"og:image:height\" content=\"484\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"escura\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:site\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"escura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\\\/\"},\"author\":{\"name\":\"escura\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/4edd59e125b9654539921a4ec1da53b1\"},\"headline\":\"Sentencia Modelo 720 R\u00e9gimen Sancionador\",\"datePublished\":\"2022-01-27T12:28:03+00:00\",\"dateModified\":\"2022-07-18T11:59:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\\\/\"},\"wordCount\":786,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/CC0-305.jpg\",\"articleSection\":[\"Fiscal - Contable\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\\\/\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\\\/\",\"name\":\"Modelo 720 - R\u00e9gimen Sancionador | ESCURA Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/CC0-305.jpg\",\"datePublished\":\"2022-01-27T12:28:03+00:00\",\"dateModified\":\"2022-07-18T11:59:26+00:00\",\"description\":\"El TJUE ha emitido la sentencia relativa al R\u00e9gimen Sancionador de la Declaraci\u00f3n Informativa sobre bienes y derechos situados en el extranjero declar\u00e1ndolo contraria al derecho de la uni\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/CC0-305.jpg\",\"contentUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/CC0-305.jpg\",\"width\":860,\"height\":484},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sentencia Modelo 720 R\u00e9gimen Sancionador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"name\":\"Escura | Abogados y Economistas\",\"description\":\"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.escura.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\",\"name\":\"Escura. Abogados y economistas\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Escura. Abogados y economistas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/escura.abogados\",\"https:\\\/\\\/x.com\\\/escura_abogados\",\"https:\\\/\\\/www.instagram.com\\\/escura_abogados\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bufete-escura\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BufeteEscura\\\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/4edd59e125b9654539921a4ec1da53b1\",\"name\":\"escura\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"caption\":\"escura\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Modelo 720 - R\u00e9gimen Sancionador | ESCURA Abogados","description":"El TJUE ha emitido la sentencia relativa al R\u00e9gimen Sancionador de la Declaraci\u00f3n Informativa sobre bienes y derechos situados en el extranjero declar\u00e1ndolo contraria al derecho de la uni\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.escura.com\/es\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\/","og_locale":"es_ES","og_type":"article","og_title":"Sentencia Modelo 720 R\u00e9gimen Sancionador","og_description":"El TJUE ha emitido la sentencia relativa al R\u00e9gimen Sancionador de la Declaraci\u00f3n Informativa sobre bienes y derechos situados en el extranjero declar\u00e1ndolo contraria al derecho de la uni\u00f3n","og_url":"https:\/\/www.escura.com\/es\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\/","og_site_name":"Escura | Abogados y Economistas","article_publisher":"https:\/\/www.facebook.com\/escura.abogados","article_published_time":"2022-01-27T12:28:03+00:00","article_modified_time":"2022-07-18T11:59:26+00:00","og_image":[{"width":860,"height":484,"url":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/04\/CC0-305.jpg","type":"image\/jpeg"}],"author":"escura","twitter_card":"summary_large_image","twitter_creator":"@escura_abogados","twitter_site":"@escura_abogados","twitter_misc":{"Escrito por":"escura","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.escura.com\/es\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\/#article","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\/"},"author":{"name":"escura","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/4edd59e125b9654539921a4ec1da53b1"},"headline":"Sentencia Modelo 720 R\u00e9gimen Sancionador","datePublished":"2022-01-27T12:28:03+00:00","dateModified":"2022-07-18T11:59:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.escura.com\/es\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\/"},"wordCount":786,"commentCount":0,"publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"image":{"@id":"https:\/\/www.escura.com\/es\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/04\/CC0-305.jpg","articleSection":["Fiscal - Contable"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.escura.com\/es\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.escura.com\/es\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\/","url":"https:\/\/www.escura.com\/es\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\/","name":"Modelo 720 - R\u00e9gimen Sancionador | ESCURA Abogados","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.escura.com\/es\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\/#primaryimage"},"image":{"@id":"https:\/\/www.escura.com\/es\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/04\/CC0-305.jpg","datePublished":"2022-01-27T12:28:03+00:00","dateModified":"2022-07-18T11:59:26+00:00","description":"El TJUE ha emitido la sentencia relativa al R\u00e9gimen Sancionador de la Declaraci\u00f3n Informativa sobre bienes y derechos situados en el extranjero declar\u00e1ndolo contraria al derecho de la uni\u00f3n","breadcrumb":{"@id":"https:\/\/www.escura.com\/es\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.escura.com\/es\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\/#primaryimage","url":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/04\/CC0-305.jpg","contentUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/04\/CC0-305.jpg","width":860,"height":484},{"@type":"BreadcrumbList","@id":"https:\/\/www.escura.com\/es\/el-tjue-ha-emitido-la-sentencia-relativa-al-regimen-sancionador-de-la-declaracion-informativa-sobre-bienes-y-derechos-situados-en-el-extranjero-modelo-720-declarandolo-contraria-al-derecho-de-la-uni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.escura.com\/es\/"},{"@type":"ListItem","position":2,"name":"Sentencia Modelo 720 R\u00e9gimen Sancionador"}]},{"@type":"WebSite","@id":"https:\/\/www.escura.com\/es\/#website","url":"https:\/\/www.escura.com\/es\/","name":"Escura | Abogados y Economistas","description":"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona","publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.escura.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.escura.com\/es\/#organization","name":"Escura. Abogados y economistas","url":"https:\/\/www.escura.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Escura. Abogados y economistas"},"image":{"@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/escura.abogados","https:\/\/x.com\/escura_abogados","https:\/\/www.instagram.com\/escura_abogados\/","https:\/\/www.linkedin.com\/company\/bufete-escura","https:\/\/www.youtube.com\/user\/BufeteEscura\/videos"]},{"@type":"Person","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/4edd59e125b9654539921a4ec1da53b1","name":"escura","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","caption":"escura"}}]}},"_links":{"self":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/29316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/comments?post=29316"}],"version-history":[{"count":1,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/29316\/revisions"}],"predecessor-version":[{"id":33818,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/29316\/revisions\/33818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media\/28525"}],"wp:attachment":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media?parent=29316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/categories?post=29316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/tags?post=29316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}