{"id":28773,"date":"2020-03-18T09:28:37","date_gmt":"2020-03-18T08:28:37","guid":{"rendered":"https:\/\/blog.escura.com\/?p=17404"},"modified":"2020-03-18T09:28:37","modified_gmt":"2020-03-18T08:28:37","slug":"medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19","status":"publish","type":"post","link":"https:\/\/www.escura.com\/es\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\/","title":{"rendered":"Medidas urgentes extraordinarias para hacer frente al impacto econ\u00f3mico y social del COVID-19"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><h3 style=\"text-align: right;\"><a href=\"http:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/43-20-medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-coronavirus.pdf\">Consulte el PDF<\/a><\/h3>\n<p><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-17405\" src=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/03\/CC0-344-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>El Gobierno ha emitido una nota de prensa en la que anuncia un Real Decreto en que se recoger\u00e1n medidas econ\u00f3micas y sociales, entre otras, para hacer frente al impacto del coronavirus.<\/p>\n<p>Damos conocimiento de esta nota por ser de general inter\u00e9s.<\/p>\n<p>Las medidas anunciadas se estructuran en tres grupos:<\/p>\n<p><strong>PRIMER BLOQUE:<\/strong><\/p>\n<p>El primer bloque de medidas del Real Decreto-ley aprobado por el Consejo de Ministros est\u00e1 destinado a las personas mayores, las dependientes y a las familias vulnerables. En este apartado se destinan 600 millones de euros a la financiaci\u00f3n de prestaciones b\u00e1sicas de los correspondientes servicios sociales de las comunidades aut\u00f3nomas y entes locales, con especial atenci\u00f3n a la asistencia domiciliaria a personas mayores y dependientes.<\/p>\n<p>Adem\u00e1s, se ampl\u00eda la protecci\u00f3n a los suministros de energ\u00eda y de agua, garantizando los servicios p\u00fablicos esenciales. Como novedad, tambi\u00e9n se garantizan los servicios de telecomunicaciones. Todo ello para las familias vulnerables.<\/p>\n<p>Tambi\u00e9n se garantiza el derecho a la vivienda de las personas con m\u00e1s dificultades. Para ello se establece una moratoria en el pago de las cuotas de las hipotecas para los deudores hipotecarios en situaci\u00f3n de especial vulnerabilidad que vean reducirse sus ingresos. La finalidad es que ninguna persona en una situaci\u00f3n econ\u00f3mica dif\u00edcil pierda su vivienda.<\/p>\n<p><strong>SEGUNDO BLOQUE:<\/strong><\/p>\n<p>El segundo bloque de medidas refuerza la protecci\u00f3n al empleo para evitar que una crisis temporal como la actual tenga un impacto negativo permanente sobre el mercado de trabajo. Para ello el Gobierno ha acordado que:<\/p>\n<p>Los trabajadores asalariados puedan adaptar o reducir su jornada de trabajo, incluso hasta un 100%, para hacer frente a las necesidades de conciliaci\u00f3n y cuidado derivadas de esta crisis.<\/p>\n<p>Se establece el teletrabajo como medida de flexibilidad principal, cuando las circunstancias lo permitan.<\/p>\n<p>Se promover\u00e1n los ajustes temporales de plantilla a trav\u00e9s de la flexibilizaci\u00f3n de los Expedientes Temporales de Regulaci\u00f3n de Empleo. Los ERTES causados por la crisis del Coronavirus ser\u00e1n considerados de fuerza mayor y los trabajadores tendr\u00e1n derecho a la prestaci\u00f3n contributiva por desempleo, aunque no cumplan el requisito de cotizaci\u00f3n previa exigido. El cobro de esa prestaci\u00f3n no les computar\u00e1 a efectos del cobro posterior de la prestaci\u00f3n por desempleo.<\/p>\n<p>En caso de ERTEs, se exonerar\u00e1 al empresario de la aportaci\u00f3n empresarial de las cuotas de la Seguridad Social.<\/p>\n<p>Para el colectivo de aut\u00f3nomos se flexibilizar el acceso al cese de actividad para que puedan cobrar con rapidez una prestaci\u00f3n en caso de dificultad econ\u00f3mica.<\/p>\n<p><strong>TERCER BLOQUE:<\/strong><\/p>\n<p>El tercer bloque de medidas permite asegurar la liquidez de las empresas para que puedan mantenerse operativas con el objetivo de que un problema de liquidez no se convierta en un problema de solvencia. Por ello se ha aprobado la creaci\u00f3n de una l\u00ednea de avales y garant\u00edas p\u00fablicas por un valor de hasta 100.000 millones de euros. Esto va a permitir movilizar entre 150.000 y 200.000 millones de euros. El Estado ser\u00e1 el garante de las operaciones.<\/p>\n<p>Adem\u00e1s, se aprueban l\u00edneas de avales adicionales de 2.000 millones de euros para las empresas exportadoras con mecanismos \u00e1giles, favoreciendo especialmente a las peque\u00f1as y medianas empresas.<\/p>\n<p>Por otro lado, las Administraciones P\u00fablicas van a ayudar a sus empresas contratistas para mitigar las consecuencias del COVID-19 en los contratos del sector p\u00fablico. Se va a establecer un r\u00e9gimen espec\u00edfico de suspensi\u00f3n de contratos p\u00fablicos, con ampliaci\u00f3n de plazos y compensaci\u00f3n de salarios, con el fin de evitar la resoluci\u00f3n de los contratos y la consecuente p\u00e9rdida de empleo.<\/p>\n<p>Para apoyar el sistema productivo y empresarial, el Gobierno tambi\u00e9n reforma la normativa sobre inversiones exteriores, para impedir que empresas de pa\u00edses de fuera de la Uni\u00f3n Europea puedan hacerse con el control de entidades espa\u00f1olas en sectores estrat\u00e9gicos, aprovechando la ca\u00edda coyuntural del valor de sus acciones en esta situaci\u00f3n de crisis econ\u00f3mica.<\/p>\n<p>El Gobierno moviliza recursos para desarrollar una vacuna:<\/p>\n<p>El Gobierno tambi\u00e9n est\u00e1 comprometido con el refuerzo de la investigaci\u00f3n cient\u00edfica para el desarrollo de una vacuna o una cura para el COVID19. Por este motivo se van a dedicar 30 millones a la partida de investigaci\u00f3n. Este dinero ir\u00e1 dedicado a dotar al Consejo Superior de Investigaciones Cient\u00edficas y al Instituto de Salud Carlos III de los recursos precisos para hacer frente a esta emergencia sanitaria.<\/p>\n<p>\u00a9 La presente informaci\u00f3n es propiedad de <strong>Escura<\/strong>, <strong>abogados<\/strong> y <strong>economistas<\/strong>, quedando prohibida su reproducci\u00f3n sin permiso expreso.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last banner\" style=\"--awb-padding-top:20px;--awb-padding-right:20px;--awb-padding-bottom:20px;--awb-padding-left:20px;--awb-bg-image:url(&#039;http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/area_economico_fiscal.jpg&#039;);--awb-bg-size:cover;--awb-margin-top:40px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy fusion-column-has-bg-image\" data-bg-url=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/area_economico_fiscal.jpg\"><div class=\"fusion-text fusion-text-2\"><h3><a href=\"https:\/\/www.escura.com\/es\/economico-fiscal\/\" target=\"_blank\" rel=\"noopener noreferrer\">Consulta nuestra \u00e1rea de <strong>Econ\u00f3mico Fiscal<\/strong><\/a><\/h3>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":28520,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-28773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiscal-contable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Escura. Abogados y Economistas<\/title>\n<meta name=\"description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.escura.com\/es\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medidas urgentes extraordinarias para hacer frente al impacto econ\u00f3mico y social del COVID-19\" \/>\n<meta property=\"og:description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.escura.com\/es\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Escura | Abogados y Economistas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/escura.abogados\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-18T08:28:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/CC0-344-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"escura\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:site\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"escura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\\\/\"},\"author\":{\"name\":\"escura\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/4edd59e125b9654539921a4ec1da53b1\"},\"headline\":\"Medidas urgentes extraordinarias para hacer frente al impacto econ\u00f3mico y social del COVID-19\",\"datePublished\":\"2020-03-18T08:28:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\\\/\"},\"wordCount\":1092,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/CC0-344-scaled.jpg\",\"articleSection\":[\"Fiscal - Contable\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\\\/\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\\\/\",\"name\":\"Escura. Abogados y Economistas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/CC0-344-scaled.jpg\",\"datePublished\":\"2020-03-18T08:28:37+00:00\",\"description\":\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/CC0-344-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/CC0-344-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medidas urgentes extraordinarias para hacer frente al impacto econ\u00f3mico y social del COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"name\":\"Escura | Abogados y Economistas\",\"description\":\"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.escura.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\",\"name\":\"Escura. Abogados y economistas\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Escura. Abogados y economistas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/escura.abogados\",\"https:\\\/\\\/x.com\\\/escura_abogados\",\"https:\\\/\\\/www.instagram.com\\\/escura_abogados\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bufete-escura\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BufeteEscura\\\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/4edd59e125b9654539921a4ec1da53b1\",\"name\":\"escura\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"caption\":\"escura\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Escura. Abogados y Economistas","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.escura.com\/es\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\/","og_locale":"es_ES","og_type":"article","og_title":"Medidas urgentes extraordinarias para hacer frente al impacto econ\u00f3mico y social del COVID-19","og_description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","og_url":"https:\/\/www.escura.com\/es\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\/","og_site_name":"Escura | Abogados y Economistas","article_publisher":"https:\/\/www.facebook.com\/escura.abogados","article_published_time":"2020-03-18T08:28:37+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/CC0-344-scaled.jpg","type":"image\/jpeg"}],"author":"escura","twitter_card":"summary_large_image","twitter_creator":"@escura_abogados","twitter_site":"@escura_abogados","twitter_misc":{"Escrito por":"escura","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.escura.com\/es\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\/#article","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\/"},"author":{"name":"escura","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/4edd59e125b9654539921a4ec1da53b1"},"headline":"Medidas urgentes extraordinarias para hacer frente al impacto econ\u00f3mico y social del COVID-19","datePublished":"2020-03-18T08:28:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.escura.com\/es\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\/"},"wordCount":1092,"commentCount":0,"publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"image":{"@id":"https:\/\/www.escura.com\/es\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/CC0-344-scaled.jpg","articleSection":["Fiscal - Contable"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.escura.com\/es\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.escura.com\/es\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\/","url":"https:\/\/www.escura.com\/es\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\/","name":"Escura. Abogados y Economistas","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.escura.com\/es\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/www.escura.com\/es\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/CC0-344-scaled.jpg","datePublished":"2020-03-18T08:28:37+00:00","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","breadcrumb":{"@id":"https:\/\/www.escura.com\/es\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.escura.com\/es\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\/#primaryimage","url":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/CC0-344-scaled.jpg","contentUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/CC0-344-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.escura.com\/es\/medidas-urgentes-extraordinarias-para-hacer-frente-al-impacto-economico-y-social-del-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.escura.com\/es\/"},{"@type":"ListItem","position":2,"name":"Medidas urgentes extraordinarias para hacer frente al impacto econ\u00f3mico y social del COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/www.escura.com\/es\/#website","url":"https:\/\/www.escura.com\/es\/","name":"Escura | Abogados y Economistas","description":"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona","publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.escura.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.escura.com\/es\/#organization","name":"Escura. Abogados y economistas","url":"https:\/\/www.escura.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Escura. Abogados y economistas"},"image":{"@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/escura.abogados","https:\/\/x.com\/escura_abogados","https:\/\/www.instagram.com\/escura_abogados\/","https:\/\/www.linkedin.com\/company\/bufete-escura","https:\/\/www.youtube.com\/user\/BufeteEscura\/videos"]},{"@type":"Person","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/4edd59e125b9654539921a4ec1da53b1","name":"escura","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","caption":"escura"}}]}},"_links":{"self":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/28773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/comments?post=28773"}],"version-history":[{"count":0,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/28773\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media\/28520"}],"wp:attachment":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media?parent=28773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/categories?post=28773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/tags?post=28773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}