{"id":28641,"date":"2020-06-30T10:01:15","date_gmt":"2020-06-30T08:01:15","guid":{"rendered":"https:\/\/blog.escura.com\/?p=17904"},"modified":"2020-06-30T10:01:15","modified_gmt":"2020-06-30T08:01:15","slug":"real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial","status":"publish","type":"post","link":"https:\/\/www.escura.com\/es\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\/","title":{"rendered":"Real Decreto-Ley 24\/2020 \u2013 Medidas sociales de reactivaci\u00f3n del empleo y protecci\u00f3n del trabajo aut\u00f3nomo y de competitividad del sector industrial"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><h3 style=\"text-align: right;\"><a href=\"http:\/\/www.escura.com\/wp-content\/uploads\/2020\/06\/138-20-rdl-24-2020-medidas-reactivacion-empleo.pdf\">Consulte el PDF<\/a><\/h3>\n<p><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-17504\" src=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/03\/CC0-463-min-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>El BOE del 27 de junio del 2020, ha publicado en Real Decreto-Ley 24\/2020 por el se aprueban medidas en el \u00e1mbito del empleo, protecci\u00f3n del trabajo aut\u00f3nomo y de competitividad.<\/p>\n<p>Puede consultar el texto \u00edntegro del RDL 24\/2020 en el siguiente enlace:<\/p>\n<p><a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/06\/27\/pdfs\/BOE-A-2020-6838.pdf\">www.boe.es\/boe\/dias\/2020\/06\/27\/pdfs\/BOE-A-2020-6838.pdf<\/a><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Destacamos del Real Decreto-Ley las siguientes medidas:<\/p>\n<ul>\n<li><strong>Los beneficios de los ERTE se prorrogan hasta el 30 de septiembre (Art\u00edculo 1)<\/strong><\/li>\n<li><strong>Las empresas acogidas a ERTE no podr\u00e1n externalizar actividad y las personas trabajadoras no podr\u00e1n realizar horas extra. (Art\u00edculo 1.3 y 2.5)<\/strong><\/li>\n<li><strong>Procedimientos de suspensi\u00f3n y reducci\u00f3n de jornada por causas econ\u00f3micas, t\u00e9cnicas, organizativas y de producci\u00f3n. (Art\u00edculo 2)<\/strong><\/li>\n<li><strong>Medidas extraordinarias en materia de protecci\u00f3n por desempleo (Art\u00edculo 3)<\/strong><\/li>\n<li><strong>Medidas extraordinarias en materia de cotizaci\u00f3n vinculadas a los expedientes de regulaci\u00f3n temporal de empleo basados en las causas recogidas en los art\u00edculos 22 y 23 del Real Decreto-ley 8\/2020, de 17 de marzo. (Art\u00edculo 4)<\/strong><\/li>\n<li><strong>L\u00edmites relacionados con reparto de dividendos y transparencia fiscal. (Art\u00edculo 5)<\/strong><\/li>\n<li><strong>Salvaguarda del empleo (Art\u00edculo 6)<\/strong><\/li>\n<li><strong>Mantenimiento prohibici\u00f3n de despido por causas objetivas e interrupci\u00f3n computo contratos temporales. (Art\u00edculo 7)<\/strong><\/li>\n<li><strong>Rebrote del covid-19<\/strong><\/li>\n<li><strong>Medidas de apoyo a los trabajadores aut\u00f3nomos (Art\u00edculo 8 al 12)<\/strong><\/li>\n<li><strong>Los beneficios de los ERTE se prorrogan hasta el 30 de septiembre (Art\u00edculo 1)<\/strong><\/li>\n<\/ul>\n<p>Los expedientes de regulaci\u00f3n de empleo basados en el art. 22 del RDL 8\/2020, solicitados con anterioridad al 17 de marzo, se podr\u00e1n prorrogar hasta el 30 de septiembre del 2020.<\/p>\n<p>La entidad gestora de las prestaciones por desempleo prorrogar\u00e1 hasta el 30 de septiembre de 2020 la duraci\u00f3n m\u00e1xima de los derechos reconocidos en virtud de procedimientos de suspensi\u00f3n o reducci\u00f3n de empleo.<\/p>\n<ul>\n<li><strong>Las empresas acogidas a ERTE no podr\u00e1n externalizar actividad y las personas trabajadoras no podr\u00e1n realizar horas extra. (Art\u00edculo 1.3 y 2.5)<\/strong><\/li>\n<\/ul>\n<p>No podr\u00e1n realizarse horas extraordinarias, establecerse nuevas externalizaciones de la actividad ni concertarse nuevas contrataciones, sean directas o indirectas, durante la aplicaci\u00f3n de los expedientes de regulaci\u00f3n temporal de empleo.<\/p>\n<ul>\n<li><strong>Procedimientos de suspensi\u00f3n y reducci\u00f3n de jornada por causas econ\u00f3micas, t\u00e9cnicas, organizativas y de producci\u00f3n. (Art\u00edculo 2)<\/strong><\/li>\n<\/ul>\n<p>Cuando el expediente de regulaci\u00f3n temporal de empleo por causas econ\u00f3micas, t\u00e9cnicas, organizativas o de producci\u00f3n se inicie tras la finalizaci\u00f3n de un expediente temporal de regulaci\u00f3n de empleo basado en la causa prevista en el art\u00edculo 22 del Real Decreto-ley 8\/2020, de 17 de marzo, la fecha de efectos se retrotraer\u00e1 a la fecha de finalizaci\u00f3n de este.<\/p>\n<ul>\n<li><strong>Medidas extraordinarias en materia de protecci\u00f3n por desempleo (Art\u00edculo 3)<\/strong><\/li>\n<\/ul>\n<p>Las prestaciones por desempleo asociadas a los ERTE (que se conceden sin necesidad de cumplir el periodo de carencia) se mantendr\u00e1n hasta el 30 de septiembre, salvo las de los fijos discontinuos, que se prolongar\u00e1n hasta el 31 de diciembre.<\/p>\n<ul>\n<li><strong>Medidas extraordinarias en materia de cotizaci\u00f3n vinculadas a los expedientes de regulaci\u00f3n temporal de empleo basados en las causas recogidas en los art\u00edculos 22 y 23 del Real Decreto-ley 8\/2020, de 17 de marzo. (Art\u00edculo 4)<\/strong><\/li>\n<\/ul>\n<p>A los ERTE <strong>de fuerza mayor total <\/strong>vigente a la entrada en vigor del RDL 24\/2020 se les aplicar\u00e1 una exenci\u00f3n en las cotizaciones empresariales:<\/p>\n<p>A las empresas de menos de 50 trabajadores: la exoneraci\u00f3n de cuotas ser\u00e1 del 70% en julio, del 60% en agosto y del 35% en septiembre.<\/p>\n<p>A las empresas de m\u00e1s de 50 trabajadores: la exoneraci\u00f3n de cuotas ser\u00e1 del 50% en julio, del 40% en agosto y del 25% en septiembre.<\/p>\n<p>Estos porcentajes se modifican con los vigentes hasta el 30 de junio que eran del 100% para las empresas con menos de 50 trabajadores y del 75% para las de m\u00e1s de 50.<\/p>\n<p>A los ERTE de <strong>fuerza mayor parcial y los ERTEs por causas objetivas<\/strong> (t\u00e9cnicas, organizativas, econ\u00f3micas y de producci\u00f3n), las exoneraciones a las empresas ser\u00e1n las mismas que las actualmente vigentes:<\/p>\n<p>A las empresas de menos de 50 trabajadores: 60% por los trabajadores que volvieran a la actividad y el 35% por los que siguieran en el ERTE.<\/p>\n<p>A las empresas de m\u00e1s de 50 trabajadores: 40% por cada trabajador que se reincorporara a su puesto y del 25% por el que siguiera en el ERTE.<\/p>\n<p>Esta medida supone a una novedad al establecer exenciones de cuotas para este tipo de ERTEs, antes s\u00f3lo aplicables a los ERTE de fuerza mayor, con el objeto de facilitar la transici\u00f3n de los mismos.<\/p>\n<ul>\n<li><strong>L\u00edmites relacionados con reparto de dividendos y transparencia fiscal. (Art\u00edculo 5)<\/strong><\/li>\n<\/ul>\n<p>La nueva regulaci\u00f3n que se da hasta septiembre extiende a los ERTE por causas objetivas la prohibici\u00f3n de acogerse a este procedimiento si la empresa tiene domicilio en un para\u00edso fiscal. Tampoco podr\u00e1 repartir dividendos, salvo si abona previamente el importe de las exoneraciones disfrutadas. Esta limitaci\u00f3n no ser\u00e1 de aplicaci\u00f3n a las empresas que, a 29 de febrero de este a\u00f1o, tuvieran menos de 50 trabajadores en plantilla.<\/p>\n<ul>\n<li><strong>Salvaguarda del empleo (Art\u00edculo 6)<\/strong><\/li>\n<\/ul>\n<p>Se extiende el compromiso de mantenimiento del empleo de seis meses a las empresas que realicen ERTE por causas objetivas. Para las empresas que se beneficien por primera vez de las exoneraciones de cotizaciones asociadas a estos ERTE, el plazo de seis meses en el que estar\u00e1n obligadas a mantener el empleo se computar\u00eda a partir de entra en vigor del nuevo decreto.<\/p>\n<ul>\n<li><strong>Mantenimiento prohibici\u00f3n de despido por causas objetivas e interrupci\u00f3n computo contratos temporales. (Art\u00edculo 7)<\/strong><\/li>\n<\/ul>\n<p>El RDL 24\/2020 mantiene hasta el 30 de septiembre la \u00abprohibici\u00f3n\u00bb al despido por causas objetivas y la suspensi\u00f3n de los contratos temporales, incluidos los formativos, de relevo e interinidad, que estableci\u00f3 los art\u00edculos 2 y 5 del RDL 9\/2020 de 27 de marzo (que se transcriben seguidamente)<\/p>\n<p><em>Art\u00edculo 2. Medidas extraordinarias para la protecci\u00f3n del empleo. La fuerza mayor y las causas econ\u00f3micas, t\u00e9cnicas, organizativas y de producci\u00f3n en las que se amparan las medidas de suspensi\u00f3n de contratos y reducci\u00f3n de jornada previstas en los art\u00edculos 22 y 23 del Real Decreto-ley 8\/2020, de 17 de marzo, no se podr\u00e1n entender como justificativas de la extinci\u00f3n del contrato de trabajo ni del despido.<\/em><\/p>\n<p><em>Art\u00edculo 5. Interrupci\u00f3n del c\u00f3mputo de la duraci\u00f3n m\u00e1xima de los contratos temporales. La suspensi\u00f3n de los contratos temporales, incluidos los formativos, de relevo e interinidad, por las causas previstas en los art\u00edculos 22 y 23 del Real Decreto-ley 8\/2020, de 17 de marzo, supondr\u00e1 la interrupci\u00f3n del c\u00f3mputo, tanto de la duraci\u00f3n de estos contratos, como de los periodos de referencia equivalentes al periodo suspendido, en cada una de estas modalidades contractuales, respecto de las personas trabajadoras afectadas por estas.<\/em><\/p>\n<ul>\n<li><strong>Rebrote del covid-19<\/strong><\/li>\n<\/ul>\n<p>En el caso de empresas que actualmente est\u00e1n activas pero que se vean obligadas a cerrar como consecuencia de un rebrote del virus, se permitir\u00e1 que puedan acogerse a un ERTE de fuerza mayor total, que contar\u00eda con una exoneraci\u00f3n de cuotas para las empresas del 80% si su plantilla es inferior a 50 trabajadores y del 60% si tiene m\u00e1s de 50 trabajadores.<\/p>\n<ul>\n<li><strong>Medidas de apoyo a los trabajadores aut\u00f3nomos (Art\u00edculo 8 al 12)<\/strong><\/li>\n<\/ul>\n<p>Se aprueba una pr\u00f3rroga hasta el 30 de septiembre de la prestaci\u00f3n extraordinaria para trabajadores aut\u00f3nomos que se habilit\u00f3 para aquellos aut\u00f3nomos con unas p\u00e9rdidas significativas n sus ingresos con motivo del COVID.<\/p>\n<p>Las medidas aprobadas incluyen una pr\u00f3rroga de la exenci\u00f3n de las cuotas de la Seguridad Social para los aut\u00f3nomos que vinieran percibiendo la prestaci\u00f3n extraordinaria hasta el 30 de junio.<\/p>\n<ol>\n<li>a) 100 por cien de las cotizaciones correspondientes al mes de julio.<\/li>\n<li>b) 50 por ciento de las cotizaciones correspondientes al mes de agosto.<\/li>\n<li>c) 25 por ciento de las cotizaciones correspondientes al mes de septiembre.<\/li>\n<\/ol>\n<p>Para aquellos cuya actividad a\u00fan siga muy afectada por los efectos de la pandemia, podr\u00e1n acceder a la prestaci\u00f3n ordinaria por cese de actividad si su facturaci\u00f3n en el tercer trimestre es un 75% menor que en el mismo periodo del a\u00f1o pasado, siempre y cuando sus rendimientos netos en el periodo no superen una cuant\u00eda equivalente a 1,75 veces el SMI del trimestre. Los trabajadores aut\u00f3nomos que tributen en el Impuesto sobre la Renta de las Personas F\u00edsicas (IRPF) por estimaci\u00f3n objetiva (modelo 131) deber\u00e1n aportar la documentaci\u00f3n necesaria o cualquier otro medio de prueba que sirva para acreditar los ingresos.<\/p>\n<p>Para acceder a esta prestaci\u00f3n ordinaria compatible con la actividad no ser\u00e1 necesario esperar a que termine el trimestre, pues se podr\u00e1 solicitar en cualquier momento y posteriormente se realizar\u00e1 una verificaci\u00f3n del cumplimiento de los requisitos. Los aut\u00f3nomos tienen la posibilidad de renunciar a la prestaci\u00f3n durante esos tres meses si ven recuperada su actividad (antes del 31 de agosto del 2020).<\/p>\n<p>Para los aut\u00f3nomos de temporada (Art\u00edculo 10) se prev\u00e9 que podr\u00e1n acceder a la prestaci\u00f3n extraordinaria (del 70% de la base reguladora m\u00e1s la exoneraci\u00f3n de las cotizaciones sociales) con efectos desde el 1 de junio hasta el 31 de octubre.<\/p>\n<p>Podr\u00e1n solicitar estas ayudas los aut\u00f3nomos cuyo \u00fanico trabajo a lo largo de los \u00faltimos dos a\u00f1os se hubiera desarrollado en el R\u00e9gimen Especial de Trabajadores Aut\u00f3nomos o en el R\u00e9gimen Especial de Trabajadores del Mar durante los meses de marzo a octubre y hayan permanecido en alta en los citados reg\u00edmenes como trabajadores aut\u00f3nomos durante al menos cinco meses al a\u00f1o durante ese periodo. Los ingresos de estos trabajadores aut\u00f3nomos en 2020 no podr\u00e1n superar 1,75 veces el SMI (23.275 euros).<\/p>\n<p>\u00a9 La presente informaci\u00f3n es propiedad de <strong>Escura<\/strong>, <strong>abogados<\/strong> y <strong>economistas<\/strong>, quedando prohibida su reproducci\u00f3n sin permiso expreso.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last banner\" style=\"--awb-padding-top:20px;--awb-padding-right:20px;--awb-padding-bottom:20px;--awb-padding-left:20px;--awb-bg-image:url(&#039;http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/area_recursos_humanosv2.jpg&#039;);--awb-bg-size:cover;--awb-margin-top:40px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy fusion-column-has-bg-image\" data-bg-url=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/area_recursos_humanosv2.jpg\"><div class=\"fusion-text fusion-text-2\"><h3><a href=\"https:\/\/www.escura.com\/es\/recursos-humanos\/\" target=\"_blank\" rel=\"noopener noreferrer\">Consulta nuestra \u00e1rea de <strong>Recursos Humanos<\/strong><\/a><\/h3>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":28304,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,27],"tags":[],"class_list":["post-28641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiscal-contable","category-recursos-humanos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Escura. Abogados y Economistas<\/title>\n<meta name=\"description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.escura.com\/es\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Real Decreto-Ley 24\/2020 \u2013 Medidas sociales de reactivaci\u00f3n del empleo y protecci\u00f3n del trabajo aut\u00f3nomo y de competitividad del sector industrial\" \/>\n<meta property=\"og:description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.escura.com\/es\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\/\" \/>\n<meta property=\"og:site_name\" content=\"Escura | Abogados y Economistas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/escura.abogados\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-30T08:01:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/CC0-463-min-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"escura\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:site\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"escura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\\\/\"},\"author\":{\"name\":\"escura\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/4edd59e125b9654539921a4ec1da53b1\"},\"headline\":\"Real Decreto-Ley 24\\\/2020 \u2013 Medidas sociales de reactivaci\u00f3n del empleo y protecci\u00f3n del trabajo aut\u00f3nomo y de competitividad del sector industrial\",\"datePublished\":\"2020-06-30T08:01:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\\\/\"},\"wordCount\":1945,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/CC0-463-min-1-scaled.jpg\",\"articleSection\":[\"Fiscal - Contable\",\"Recursos Humanos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\\\/\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\\\/\",\"name\":\"Escura. Abogados y Economistas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/CC0-463-min-1-scaled.jpg\",\"datePublished\":\"2020-06-30T08:01:15+00:00\",\"description\":\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/CC0-463-min-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/CC0-463-min-1-scaled.jpg\",\"width\":1707,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Real Decreto-Ley 24\\\/2020 \u2013 Medidas sociales de reactivaci\u00f3n del empleo y protecci\u00f3n del trabajo aut\u00f3nomo y de competitividad del sector industrial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"name\":\"Escura | Abogados y Economistas\",\"description\":\"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.escura.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\",\"name\":\"Escura. Abogados y economistas\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Escura. Abogados y economistas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/escura.abogados\",\"https:\\\/\\\/x.com\\\/escura_abogados\",\"https:\\\/\\\/www.instagram.com\\\/escura_abogados\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bufete-escura\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BufeteEscura\\\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/4edd59e125b9654539921a4ec1da53b1\",\"name\":\"escura\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"caption\":\"escura\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Escura. Abogados y Economistas","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.escura.com\/es\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\/","og_locale":"es_ES","og_type":"article","og_title":"Real Decreto-Ley 24\/2020 \u2013 Medidas sociales de reactivaci\u00f3n del empleo y protecci\u00f3n del trabajo aut\u00f3nomo y de competitividad del sector industrial","og_description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","og_url":"https:\/\/www.escura.com\/es\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\/","og_site_name":"Escura | Abogados y Economistas","article_publisher":"https:\/\/www.facebook.com\/escura.abogados","article_published_time":"2020-06-30T08:01:15+00:00","og_image":[{"width":1707,"height":2560,"url":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/CC0-463-min-1-scaled.jpg","type":"image\/jpeg"}],"author":"escura","twitter_card":"summary_large_image","twitter_creator":"@escura_abogados","twitter_site":"@escura_abogados","twitter_misc":{"Escrito por":"escura","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\/#article","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\/"},"author":{"name":"escura","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/4edd59e125b9654539921a4ec1da53b1"},"headline":"Real Decreto-Ley 24\/2020 \u2013 Medidas sociales de reactivaci\u00f3n del empleo y protecci\u00f3n del trabajo aut\u00f3nomo y de competitividad del sector industrial","datePublished":"2020-06-30T08:01:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\/"},"wordCount":1945,"commentCount":0,"publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"image":{"@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/CC0-463-min-1-scaled.jpg","articleSection":["Fiscal - Contable","Recursos Humanos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.escura.com\/es\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\/","url":"https:\/\/www.escura.com\/es\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\/","name":"Escura. Abogados y Economistas","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\/#primaryimage"},"image":{"@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/CC0-463-min-1-scaled.jpg","datePublished":"2020-06-30T08:01:15+00:00","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","breadcrumb":{"@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.escura.com\/es\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\/#primaryimage","url":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/CC0-463-min-1-scaled.jpg","contentUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/CC0-463-min-1-scaled.jpg","width":1707,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-24-2020-medidas-sociales-de-reactivacion-del-empleo-y-proteccion-del-trabajo-autonomo-y-de-competitividad-del-sector-industrial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.escura.com\/es\/"},{"@type":"ListItem","position":2,"name":"Real Decreto-Ley 24\/2020 \u2013 Medidas sociales de reactivaci\u00f3n del empleo y protecci\u00f3n del trabajo aut\u00f3nomo y de competitividad del sector industrial"}]},{"@type":"WebSite","@id":"https:\/\/www.escura.com\/es\/#website","url":"https:\/\/www.escura.com\/es\/","name":"Escura | Abogados y Economistas","description":"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona","publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.escura.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.escura.com\/es\/#organization","name":"Escura. Abogados y economistas","url":"https:\/\/www.escura.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Escura. Abogados y economistas"},"image":{"@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/escura.abogados","https:\/\/x.com\/escura_abogados","https:\/\/www.instagram.com\/escura_abogados\/","https:\/\/www.linkedin.com\/company\/bufete-escura","https:\/\/www.youtube.com\/user\/BufeteEscura\/videos"]},{"@type":"Person","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/4edd59e125b9654539921a4ec1da53b1","name":"escura","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","caption":"escura"}}]}},"_links":{"self":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/28641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/comments?post=28641"}],"version-history":[{"count":0,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/28641\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media\/28304"}],"wp:attachment":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media?parent=28641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/categories?post=28641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/tags?post=28641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}