{"id":28632,"date":"2020-06-02T12:27:11","date_gmt":"2020-06-02T10:27:11","guid":{"rendered":"https:\/\/blog.escura.com\/?p=17842"},"modified":"2020-06-02T12:27:11","modified_gmt":"2020-06-02T10:27:11","slug":"real-decreto-ley-20-2020-ingreso-minimo-vital","status":"publish","type":"post","link":"https:\/\/www.escura.com\/es\/real-decreto-ley-20-2020-ingreso-minimo-vital\/","title":{"rendered":"Real Decreto-Ley 20\/2020 \u2013 Ingreso m\u00ednimo vital"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><h3 style=\"text-align: right;\"><a href=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/06\/127-20-ingreso-minimo-vital.pdf\">Consulte el PDF<\/a><\/h3>\n<p><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-17843\" src=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/06\/CC0-479-min-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>El Bolet\u00edn Oficial del Estado de 1 de junio del 2020, ha publicado el Real Decreto-ley 20\/2020, por el que se establece el ingreso m\u00ednimo vital.<\/p>\n<p>El Real Decreto-ley tiene por objeto la creaci\u00f3n y regulaci\u00f3n de un ingreso mediante una prestaci\u00f3n econ\u00f3mica para determinadas personas y bajo determinados requisitos y condiciones.<\/p>\n<p>Puede acceder en el siguiente enlace al texto \u00edntegro del Real Decreto Ley:<\/p>\n<p><a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/06\/01\/pdfs\/BOE-A-2020-5493.pdf\">https:\/\/www.boe.es\/boe\/dias\/2020\/06\/01\/pdfs\/BOE-A-2020-5493.pdf<\/a><\/p>\n<p>El Ministerio de Trabajo y Econom\u00eda Social, a trav\u00e9s del Servicio P\u00fablico de Empleo Estatal (SEPE) ha emitido una nota en la que se exponen, de manera sucinta, los siguientes aspectos:<\/p>\n<ul>\n<li><strong>\u00bfEn qu\u00e9 consiste y qui\u00e9n lo puede solicitar?<\/strong><\/li>\n<li><strong>Objetivos<\/strong><\/li>\n<li><strong>\u00bfQu\u00e9 organismo se encarga de tramitarlo?<\/strong><\/li>\n<li><strong>\u00bfC\u00f3mo y d\u00f3nde se presenta la solicitud?<\/strong><\/li>\n<li><strong>R\u00e9gimen de compatibilidad del ingreso m\u00ednimo vital con el empleo<\/strong><\/li>\n<li><strong>Duraci\u00f3n de la prestaci\u00f3n<\/strong><\/li>\n<li><strong>Plazo de solicitud<\/strong><\/li>\n<li><strong>Cooperaci\u00f3n entre las administraciones p\u00fablicas<\/strong><\/li>\n<li><strong>Entrada en vigor<\/strong><\/li>\n<\/ul>\n<p>Consideramos de inter\u00e9s general la nota del SEPE, por lo procedemos a su divulgaci\u00f3n: Mediante este Real Decreto-ley se establece una prestaci\u00f3n de naturaleza econ\u00f3mica que garantiza un nivel m\u00ednimo de renta a quienes se encuentren en situaci\u00f3n de vulnerabilidad econ\u00f3mica, permitiendo que todas las personas y familias puedan atender las necesidades b\u00e1sicas de sus hogares.<\/p>\n<p><strong>\u00bfEn qu\u00e9 consiste y qui\u00e9n lo puede solicitar?<\/strong><\/p>\n<p>El ingreso m\u00ednimo vital es una prestaci\u00f3n para hogares de cualquier tama\u00f1o, tambi\u00e9n los unipersonales. En cada hogar habr\u00e1 un titular que solicitar\u00e1 la prestaci\u00f3n. Si el hogar est\u00e1 formado por una sola persona el titular tendr\u00e1 entre 23 y 65 a\u00f1os y llevar al menos tres a\u00f1os constituido como hogar. Si el hogar tiene dos o m\u00e1s miembros, de manera general la edad del titular estar\u00e1 entre 23 y 65 a\u00f1os salvo en los casos en que se cuente con menores a cargo. Estos hogares deber\u00e1n llevar constituidos al menos un a\u00f1o.<\/p>\n<p>Para todos los tipos de hogar se requerir\u00e1 al menos un a\u00f1o ininterrumpido de residencia legal y efectiva en Espa\u00f1a, excepto en las situaciones de violencia de g\u00e9nero, trata y explotaci\u00f3n sexual.<\/p>\n<p>Para que le sea reconocida la prestaci\u00f3n, el hogar debe tener unos ingresos totales inferiores a la renta garantizada para su tipo de unidad de convivencia. Adem\u00e1s, para certificar que el Ingreso M\u00ednimo Vital llegue a los hogares m\u00e1s vulnerables, se exigir\u00e1 un patrimonio (descontando la vivienda habitual) inferior a 3 veces la renta garantizada anual para un hogar unipersonal, con una escala de incrementos por n\u00famero de miembros en el hogar.<\/p>\n<p><strong>No computar\u00e1n como ingresos<\/strong>\u00a0los salarios sociales, rentas m\u00ednimas de inserci\u00f3n o ayudas an\u00e1logas de asistencia social concedidas por las comunidades aut\u00f3nomas, y otros ingresos y rentas de acuerdo con lo previsto en el art\u00edculo 18 de esta disposici\u00f3n<\/p>\n<p><strong>Objetivos<\/strong><\/p>\n<ul>\n<li>Garantizar un nivel de ingresos m\u00ednimo a todos los hogares con independencia del lugar de residencia.<\/li>\n<li>Incentivar la incorporaci\u00f3n al mercado laboral de las personas en situaci\u00f3n o riesgo de exclusi\u00f3n social, as\u00ed como reducir el riesgo de cronificaci\u00f3n de la pobreza, mediante incorporaci\u00f3n de un complemento al empleo para las personas beneficiarias del ingreso m\u00ednimo vital, que se definir\u00e1 en desarrollo reglamentario.<\/li>\n<li>Fomentar la inclusi\u00f3n social de las personas en situaci\u00f3n o riesgo de exclusi\u00f3n social.<\/li>\n<li>Reducir la pobreza y promover una mayor redistribuci\u00f3n de rentas.<\/li>\n<\/ul>\n<p><strong>\u00bfQu\u00e9 organismo se encarga de tramitarlo?<\/strong><\/p>\n<p>La competencia para el reconocimiento y el control de la prestaci\u00f3n econ\u00f3mica no contributiva, como parte de la acci\u00f3n protectora del sistema de la Seguridad Social, corresponde al\u00a0<strong>Instituto Nacional de la Seguridad Social.<\/strong><\/p>\n<p>Mediante convenio se posibilita que comunidades aut\u00f3nomas y entidades locales puedan iniciar el expediente administrativo y realizar la posterior tramitaci\u00f3n y gesti\u00f3n previas a la resoluci\u00f3n del expediente.<\/p>\n<p><strong>\u00bfC\u00f3mo y d\u00f3nde se presenta la solicitud?<\/strong><\/p>\n<p>La solicitud se realizar\u00e1 en el modelo normalizado establecido al efecto, acompa\u00f1ada de la documentaci\u00f3n necesaria para justificar el cumplimiento de los requisitos establecidos en este real decreto-ley y en sus normas de desarrollo. Se podr\u00e1 presentar a trav\u00e9s de la\u00a0<strong>sede electr\u00f3nica de la Seguridad Social\u00a0<\/strong>o a trav\u00e9s de aquellos otros canales de comunicaci\u00f3n telem\u00e1tica que el Instituto Nacional de la Seguridad Social tenga habilitados al efecto. Adem\u00e1s, se permitir\u00e1 el acceso a trav\u00e9s de los ayuntamientos una vez se firmen los convenios previstos y en los Centros de Atenci\u00f3n e Informaci\u00f3n de la Seguridad Social cuando retomen la atenci\u00f3n al p\u00fablico.\u00a0Para facilitar informaci\u00f3n a los posibles beneficiarios, se pondr\u00e1 en marcha un tel\u00e9fono 900 y un simulador en la p\u00e1gina web de la Seguridad Social.<\/p>\n<p><strong>R\u00e9gimen de compatibilidad del ingreso m\u00ednimo vital con el empleo<\/strong><\/p>\n<p>Se prev\u00e9 el\u00a0r\u00e9gimen de compatibilidad del ingreso m\u00ednimo vital con el empleo de forma que la percepci\u00f3n de esta prestaci\u00f3n no desincentive la participaci\u00f3n en el mercado laboral.<\/p>\n<p>El ingreso m\u00ednimo vital, al ser compatible con los rendimientos del trabajo y estar acompa\u00f1ado de un mecanismo incentivador al empleo, as\u00ed como de las obligaciones de los beneficiarios de participar en las estrategias de inclusi\u00f3n que promueva el Ministerio de Inclusi\u00f3n, Seguridad Social y Migraciones, y de figurar como demandantes de empleo en caso de no trabajar, brindar\u00e1 la oportunidad de incorporarse a la econom\u00eda formal a personas y colectivos que tradicionalmente han venido trabajando fuera de este \u00e1mbito. La incorporaci\u00f3n al trabajo formal y el disfrute de los beneficios sociales y econ\u00f3micos que esto supone actuar\u00e1 en muchos casos como barrera para la vuelta de estas personas a la econom\u00eda informal, con los beneficios individuales y colectivos que ello comporta para la sociedad en su conjunto.<\/p>\n<p><strong>Duraci\u00f3n de la prestaci\u00f3n<\/strong><\/p>\n<p>El derecho a percibir la prestaci\u00f3n econ\u00f3mica del ingreso m\u00ednimo vital se mantendr\u00e1 mientras subsistan los motivos que dieron lugar a su concesi\u00f3n y se cumplan los requisitos y obligaciones previstos en este real decreto-ley.<\/p>\n<p>La prestaci\u00f3n se percibir\u00e1 mensualmente y se cobrar\u00e1 en 12 pagas.<\/p>\n<p><strong>Plazo de solicitud<\/strong><\/p>\n<p>Se podr\u00e1 solicitar a partir del 15 de junio, aunque, para las solicitudes presentadas en los tres primeros meses, se conceder\u00e1 con efectos retroactivos al 1 de junio. Adem\u00e1s, durante el primer mes de vigencia de la prestaci\u00f3n, se actuar\u00e1 de oficio para que se abone a unos 100.000 hogares que cumplen los requisitos, sin que sea necesario que la soliciten.<\/p>\n<p><strong>Cooperaci\u00f3n entre las administraciones p\u00fablicas<\/strong><\/p>\n<p>El Ministerio de Inclusi\u00f3n, Seguridad Social y Migraciones promover\u00e1, en el \u00e1mbito de sus competencias, estrategias de inclusi\u00f3n de las personas beneficiarias del ingreso m\u00ednimo vital mediante la cooperaci\u00f3n y colaboraci\u00f3n con los departamentos ministeriales, las comunidades aut\u00f3nomas, las entidades locales, las organizaciones empresariales y sindicales m\u00e1s representativas, as\u00ed como con las entidades del Tercer Sector de Acci\u00f3n Social.<\/p>\n<p>A estos efectos, se crea la Comisi\u00f3n de seguimiento del ingreso m\u00ednimo vital como \u00f3rgano de cooperaci\u00f3n administrativa para el seguimiento de la aplicaci\u00f3n del contenido de este real decreto-ley.<\/p>\n<p><strong>Entrada en vigor<\/strong><\/p>\n<p>El presente real decreto-ley entrar\u00e1 en vigor el mismo d\u00eda de su publicaci\u00f3n en el \u00abBolet\u00edn Oficial del Estado\u00bb.<\/p>\n<p>\u00a9 La presente informaci\u00f3n es propiedad de <strong>Escura<\/strong>, <strong>abogados<\/strong> y <strong>economistas<\/strong>, quedando prohibida su reproducci\u00f3n sin permiso expreso.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last banner\" style=\"--awb-padding-top:20px;--awb-padding-right:20px;--awb-padding-bottom:20px;--awb-padding-left:20px;--awb-bg-image:url(&#039;http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/area_economico_fiscal.jpg&#039;);--awb-bg-size:cover;--awb-margin-top:40px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy fusion-column-has-bg-image\" data-bg-url=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/area_economico_fiscal.jpg\"><div class=\"fusion-text fusion-text-2\"><h3><a href=\"https:\/\/www.escura.com\/es\/economico-fiscal\/\" target=\"_blank\" rel=\"noopener noreferrer\">Consulta nuestra \u00e1rea de <strong>Econ\u00f3mico Fiscal<\/strong><\/a><\/h3>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,27],"tags":[],"class_list":["post-28632","post","type-post","status-publish","format-standard","hentry","category-fiscal-contable","category-recursos-humanos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Escura. Abogados y Economistas<\/title>\n<meta name=\"description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.escura.com\/es\/real-decreto-ley-20-2020-ingreso-minimo-vital\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Real Decreto-Ley 20\/2020 \u2013 Ingreso m\u00ednimo vital\" \/>\n<meta property=\"og:description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.escura.com\/es\/real-decreto-ley-20-2020-ingreso-minimo-vital\/\" \/>\n<meta property=\"og:site_name\" content=\"Escura | Abogados y Economistas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/escura.abogados\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-02T10:27:11+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/06\/CC0-479-min-150x150.jpg\" \/>\n<meta name=\"author\" content=\"escura\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:site\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"escura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-20-2020-ingreso-minimo-vital\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-20-2020-ingreso-minimo-vital\\\/\"},\"author\":{\"name\":\"escura\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/4edd59e125b9654539921a4ec1da53b1\"},\"headline\":\"Real Decreto-Ley 20\\\/2020 \u2013 Ingreso m\u00ednimo vital\",\"datePublished\":\"2020-06-02T10:27:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-20-2020-ingreso-minimo-vital\\\/\"},\"wordCount\":1591,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-20-2020-ingreso-minimo-vital\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/blog.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/CC0-479-min-150x150.jpg\",\"articleSection\":[\"Fiscal - Contable\",\"Recursos Humanos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-20-2020-ingreso-minimo-vital\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-20-2020-ingreso-minimo-vital\\\/\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-20-2020-ingreso-minimo-vital\\\/\",\"name\":\"Escura. Abogados y Economistas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-20-2020-ingreso-minimo-vital\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-20-2020-ingreso-minimo-vital\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/blog.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/CC0-479-min-150x150.jpg\",\"datePublished\":\"2020-06-02T10:27:11+00:00\",\"description\":\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-20-2020-ingreso-minimo-vital\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-20-2020-ingreso-minimo-vital\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-20-2020-ingreso-minimo-vital\\\/#primaryimage\",\"url\":\"http:\\\/\\\/blog.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/CC0-479-min-150x150.jpg\",\"contentUrl\":\"http:\\\/\\\/blog.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/CC0-479-min-150x150.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-20-2020-ingreso-minimo-vital\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Real Decreto-Ley 20\\\/2020 \u2013 Ingreso m\u00ednimo vital\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"name\":\"Escura | Abogados y Economistas\",\"description\":\"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.escura.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\",\"name\":\"Escura. Abogados y economistas\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Escura. Abogados y economistas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/escura.abogados\",\"https:\\\/\\\/x.com\\\/escura_abogados\",\"https:\\\/\\\/www.instagram.com\\\/escura_abogados\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bufete-escura\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BufeteEscura\\\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/4edd59e125b9654539921a4ec1da53b1\",\"name\":\"escura\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"caption\":\"escura\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Escura. Abogados y Economistas","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.escura.com\/es\/real-decreto-ley-20-2020-ingreso-minimo-vital\/","og_locale":"es_ES","og_type":"article","og_title":"Real Decreto-Ley 20\/2020 \u2013 Ingreso m\u00ednimo vital","og_description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","og_url":"https:\/\/www.escura.com\/es\/real-decreto-ley-20-2020-ingreso-minimo-vital\/","og_site_name":"Escura | Abogados y Economistas","article_publisher":"https:\/\/www.facebook.com\/escura.abogados","article_published_time":"2020-06-02T10:27:11+00:00","og_image":[{"url":"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/06\/CC0-479-min-150x150.jpg","type":"","width":"","height":""}],"author":"escura","twitter_card":"summary_large_image","twitter_creator":"@escura_abogados","twitter_site":"@escura_abogados","twitter_misc":{"Escrito por":"escura","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-20-2020-ingreso-minimo-vital\/#article","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-20-2020-ingreso-minimo-vital\/"},"author":{"name":"escura","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/4edd59e125b9654539921a4ec1da53b1"},"headline":"Real Decreto-Ley 20\/2020 \u2013 Ingreso m\u00ednimo vital","datePublished":"2020-06-02T10:27:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-20-2020-ingreso-minimo-vital\/"},"wordCount":1591,"commentCount":0,"publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"image":{"@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-20-2020-ingreso-minimo-vital\/#primaryimage"},"thumbnailUrl":"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/06\/CC0-479-min-150x150.jpg","articleSection":["Fiscal - Contable","Recursos Humanos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.escura.com\/es\/real-decreto-ley-20-2020-ingreso-minimo-vital\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-20-2020-ingreso-minimo-vital\/","url":"https:\/\/www.escura.com\/es\/real-decreto-ley-20-2020-ingreso-minimo-vital\/","name":"Escura. Abogados y Economistas","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-20-2020-ingreso-minimo-vital\/#primaryimage"},"image":{"@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-20-2020-ingreso-minimo-vital\/#primaryimage"},"thumbnailUrl":"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/06\/CC0-479-min-150x150.jpg","datePublished":"2020-06-02T10:27:11+00:00","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","breadcrumb":{"@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-20-2020-ingreso-minimo-vital\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.escura.com\/es\/real-decreto-ley-20-2020-ingreso-minimo-vital\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-20-2020-ingreso-minimo-vital\/#primaryimage","url":"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/06\/CC0-479-min-150x150.jpg","contentUrl":"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/06\/CC0-479-min-150x150.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-20-2020-ingreso-minimo-vital\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.escura.com\/es\/"},{"@type":"ListItem","position":2,"name":"Real Decreto-Ley 20\/2020 \u2013 Ingreso m\u00ednimo vital"}]},{"@type":"WebSite","@id":"https:\/\/www.escura.com\/es\/#website","url":"https:\/\/www.escura.com\/es\/","name":"Escura | Abogados y Economistas","description":"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona","publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.escura.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.escura.com\/es\/#organization","name":"Escura. Abogados y economistas","url":"https:\/\/www.escura.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Escura. Abogados y economistas"},"image":{"@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/escura.abogados","https:\/\/x.com\/escura_abogados","https:\/\/www.instagram.com\/escura_abogados\/","https:\/\/www.linkedin.com\/company\/bufete-escura","https:\/\/www.youtube.com\/user\/BufeteEscura\/videos"]},{"@type":"Person","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/4edd59e125b9654539921a4ec1da53b1","name":"escura","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","caption":"escura"}}]}},"_links":{"self":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/28632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/comments?post=28632"}],"version-history":[{"count":0,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/28632\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media?parent=28632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/categories?post=28632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/tags?post=28632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}