{"id":28630,"date":"2020-06-01T11:50:53","date_gmt":"2020-06-01T09:50:53","guid":{"rendered":"https:\/\/blog.escura.com\/?p=17835"},"modified":"2020-06-01T11:50:53","modified_gmt":"2020-06-01T09:50:53","slug":"real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019","status":"publish","type":"post","link":"https:\/\/www.escura.com\/es\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\/","title":{"rendered":"Real Decreto-Ley 19\/2020 \u2013 Intereses de demora en aplazamientos COVID y declaraci\u00f3n del Impuesto sobre Sociedades 2019"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><h3 style=\"text-align: right;\"><a href=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/06\/125-20-rd-19-2020-intereses-demora-aplazamientos-covid-declaracion-IS-2019.pdf\">Consulte el PDF<\/a><\/h3>\n<p><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-17490\" src=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/03\/marek-levak-lMEMH5Rd30U-unsplash-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>El Real Decreto-ley 19\/2020, de 26 de mayo, por el que se adoptan medidas complementarias en materia agraria, cient\u00edfica, econ\u00f3mica, de empleo y Seguridad Social y tributarias para paliar los efectos del COVID-19 (BOE 27 de mayo), introduce importantes novedades en el \u00e1mbito tributario:<\/p>\n<ol>\n<li><strong>Intereses de demora aplazamientos<\/strong>(Disposici\u00f3n final s\u00e9ptima, disposici\u00f3n final novena y disposici\u00f3n transitoria segunda RD-ley 19\/2020)<\/li>\n<li><strong>Cuentas anuales y Declaraci\u00f3n Impuesto sobre Sociedades 2019<\/strong>. (Apartados tres y cuatro de la Disposici\u00f3n final octava RD-ley 19\/2020)<\/li>\n<\/ol>\n<p>Puede consultar el BOE integro en el siguiente enlace:<\/p>\n<p><a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/05\/27\/pdfs\/BOE-A-2020-5315.pdf\">https:\/\/www.boe.es\/boe\/dias\/2020\/05\/27\/pdfs\/BOE-A-2020-5315.pdf<\/a><\/p>\n<p>La suspensi\u00f3n del plazo para la presentaci\u00f3n de las cuentas anuales hab\u00eda provocado una gran confusi\u00f3n en relaci\u00f3n con el plazo para la presentaci\u00f3n del IS. El RDL 19\/20 viene a clarificar el indicado plazo, manteniendo vigente el apartado 1 del art\u00edculo 124 de la Ley 27\/2014, que establece:<\/p>\n<p><em>Los contribuyentes estar\u00e1n obligados a presentar una declaraci\u00f3n por este Impuesto en el lugar y la forma que se determinen por el Ministro de Hacienda y Administraciones P\u00fablicas.<br \/>\nLa declaraci\u00f3n se presentar\u00e1 en el plazo de los 25 d\u00edas naturales siguientes a los 6 meses posteriores a la conclusi\u00f3n del per\u00edodo impositivo.<\/em><\/p>\n<p>En consecuencia, se mantiene el plazo para la presentaci\u00f3n del IS, plante\u00e1ndose una nueva duda, cual es si las cuentas anuales no est\u00e1n aprobadas, en base a que contabilidad deber\u00e1 de presentarse el IS.<\/p>\n<p>El RDL 19\/20, establece, sumariamente:<\/p>\n<p><em>Para el resto de contribuyentes, (no cotizadas) las cuentas anuales auditadas o, en su defecto, las cuentas anuales formuladas por el \u00f3rgano correspondiente, o a falta de estas \u00faltimas, <strong>la contabilidad disponible llevada de acuerdo con lo previsto en el C\u00f3digo de Comercio o con lo establecido en las normas por las que se rijan.<\/strong><\/em><\/p>\n<p>Para el caso en que el IS presentado con las cuentas provisionales, difiriera de las cuentas aprobadas por la sociedad, el RDL 19\/20, establece un segundo plazo para la regularizaci\u00f3n del IS:<\/p>\n<p><em>En el caso de que la autoliquidaci\u00f3n del Impuesto que deba resultar con arreglo a las cuentas anuales aprobadas difiera de la presentada en el plazo ordinario de declaraci\u00f3n, los contribuyentes presentar\u00e1n\u00a0<strong>una nueva autoliquidaci\u00f3n con plazo hasta el 30 de noviembre de 2020.<\/strong><\/em><\/p>\n<p>La propia Agencia Tributaria, debido a la transcendencia de la aclaraci\u00f3n introducida en el RD, ha publicado una nota que seguidamente transcribimos.<\/p>\n<ol>\n<li><strong>Intereses de demora aplazamientos<\/strong>(Disposici\u00f3n final s\u00e9ptima, disposici\u00f3n final novena y disposici\u00f3n transitoria segunda RD-ley 19\/2020)<\/li>\n<\/ol>\n<p>Se ampl\u00eda a cuatro meses el plazo de no devengo de intereses de demora para los aplazamientos de los art\u00edculos 14 del RDLey 7\/2020, de 12 de marzo, por el que se adoptan medidas urgentes para responder al impacto econ\u00f3mico del COVID-19, y 52 del RD-ley 11\/2020, de 31 de marzo, por el que se adoptan medidas urgentes complementarias en el \u00e1mbito social y econ\u00f3mico para hacer frente al COVID-19.<\/p>\n<p>Estas modificaciones se aplicar\u00e1n, respectivamente, a las solicitudes de aplazamiento que se hubieran presentado a partir de la entrada en vigor de dichos RD-ley 7\/2020, de 12 de marzo, y 11\/2020, de 31 de marzo.<\/p>\n<ol start=\"2\">\n<li><strong>Cuentas anuales y Declaraci\u00f3n Impuesto sobre Sociedades 2019<\/strong>.<\/li>\n<\/ol>\n<p><strong>2.1. Plazos de formulaci\u00f3n y aprobaci\u00f3n de cuentas anuales: se modifica el art\u00edculo 40 del RD-ley 8\/2020, de 17 de marzo.<\/strong>\u00a0(Apartados tres y cuatro de la Disposici\u00f3n final octava RD-ley 19\/2020)<\/p>\n<p>Se establece que el plazo de tres meses para formular las cuentas anuales y dem\u00e1s documentos legalmente obligatorios <strong><em><u>comenzar\u00e1 a contarse desde el 1 de junio de 2020 y no desde la finalizaci\u00f3n del estado de alarma.<\/u><\/em><\/strong><\/p>\n<p>Adicionalmente, se reduce de tres a dos meses el plazo para aprobar las cuentas anuales desde la formulaci\u00f3n, con lo que las empresas dispondr\u00e1n antes de unas cuentas aprobadas y depositadas en el Registro Mercantil y se armoniza dicho plazo para todas las sociedades, sean o no cotizadas, de modo que todas deber\u00e1n tener las cuentas aprobadas dentro de los diez primeros meses del ejercicio.<\/p>\n<p><strong>2.2. Presentaci\u00f3n de la declaraci\u00f3n del Impuesto sobre Sociedades para los contribuyentes que se ajusten, para la formulaci\u00f3n y aprobaci\u00f3n de las cuentas anuales del ejercicio, a lo dispuesto en los art\u00edculos 40 y 41 del RD-ley 8\/2020, de 17 de marzo.<\/strong>\u00a0(Art\u00edculo 12 RD-ley 19\/2020)<\/p>\n<ul>\n<li>Los contribuyentes del Impuesto sobre Sociedades cuyo plazo para la formulaci\u00f3n y aprobaci\u00f3n de las cuentas anuales del ejercicio se ajuste a lo dispuesto en los art\u00edculos 40 y 41 del RD-ley presentar\u00e1n la declaraci\u00f3n del Impuesto para el per\u00edodo impositivo correspondiente a dicho ejercicio en el plazo previsto en el apartado 1 del art\u00edculo 124 de la Ley 27\/2014, de 27 de noviembre, del Impuesto sobre Sociedades (LIS).<\/li>\n<\/ul>\n<p>Si a la finalizaci\u00f3n de este \u00faltimo plazo, las cuentas anuales no hubieran sido aprobadas, la declaraci\u00f3n se realizar\u00e1 con las cuentas anuales disponibles.<\/p>\n<p>A estos efectos, se entender\u00e1 por\u00a0<strong>cuentas anuales disponibles<\/strong>:<\/p>\n<ul>\n<li>Para las sociedades an\u00f3nimas cotizadas, las cuentas anuales auditadas a que se refiere la letra a) del art\u00edculo 41.1 del mencionado RD-ley 8\/2020.<\/li>\n<li>Para el resto de contribuyentes, las cuentas anuales auditadas o, en su defecto, las cuentas anuales formuladas por el \u00f3rgano correspondiente, o a falta de estas \u00faltimas, la contabilidad disponible llevada de acuerdo con lo previsto en el C\u00f3digo de Comercio o con lo establecido en las normas por las que se rijan.<\/li>\n<\/ul>\n<ul>\n<li>En el caso de que la autoliquidaci\u00f3n del Impuesto que deba resultar con arreglo a las cuentas anuales aprobadas difiera de la presentada en el plazo ordinario de declaraci\u00f3n, los contribuyentes presentar\u00e1n\u00a0<strong>una nueva autoliquidaci\u00f3n con plazo hasta el 30 de noviembre de 2020.<\/strong>\n<ul>\n<li><em>Nueva declaraci\u00f3n complementaria<\/em>: Esta nueva autoliquidaci\u00f3n tendr\u00e1 la consideraci\u00f3n de\u00a0<strong>complementaria<\/strong>a los efectos previstos en el art\u00edculo 122 de la Ley General Tributaria (LGT), si de ella resultase una cantidad a ingresar superior o una cantidad a devolver inferior a la derivada de la autoliquidaci\u00f3n anterior efectuada conforme a lo dispuesto en el apartado anterior.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>La cantidad a ingresar resultante devengar\u00e1 intereses de demora conforme a lo dispuesto en el art\u00edculo 26 de la LGT desde el d\u00eda siguiente a la finalizaci\u00f3n del plazo previsto en el art\u00edculo 124.1 de la LIS, sin que le resulte de aplicaci\u00f3n lo dispuesto en el art\u00edculo 27 de la LGT.<\/p>\n<ul>\n<li><em>Nueva declaraci\u00f3n en el resto de casos<\/em>: En los casos en los que la nueva declaraci\u00f3n no tenga la consideraci\u00f3n de complementaria, la nueva autoliquidaci\u00f3n producir\u00e1 efectos desde su presentaci\u00f3n, sin que resulte de aplicaci\u00f3n lo dispuesto en el art\u00edculo 120.3 de la LGT, y en los art\u00edculos 126 y siguientes del Reglamento General aprobado por Real Decreto 1065\/2007, de 27 de julio, ni se limiten las facultades de la Administraci\u00f3n para verificar o comprobar la primera y la nueva autoliquidaci\u00f3n.<\/li>\n<\/ul>\n<p>No resultar\u00e1 de aplicaci\u00f3n respecto de la nueva autoliquidaci\u00f3n las limitaciones a la rectificaci\u00f3n de las opciones a que se refiere el art\u00edculo 119.3 de la LGT.<\/p>\n<ul>\n<li>En el caso de devoluci\u00f3n de cantidades derivadas de la aplicaci\u00f3n de lo dispuesto en este art\u00edculo, se aplicar\u00e1 el art\u00edculo 127 de la LIS. A estos efectos el plazo de los 6 meses se contar\u00e1 a partir de la finalizaci\u00f3n del plazo establecido en el apartado anterior para la presentaci\u00f3n de la nueva autoliquidaci\u00f3n.<\/li>\n<\/ul>\n<p>No obstante, lo anterior, cuando de la rectificaci\u00f3n a la que se refiere la letra b) del apartado 3 del art\u00edculo 12 de este RD-Ley 19\/2020, resulte una cantidad a devolver como consecuencia de un ingreso efectivo en la autoliquidaci\u00f3n anterior, se devengar\u00e1n intereses de demora sobre dicha cantidad desde el d\u00eda siguiente a la finalizaci\u00f3n del plazo voluntario de declaraci\u00f3n a que se refiere el apartado 1 del art\u00edculo 124 de la LIS hasta la fecha en que se ordene el pago de la devoluci\u00f3n.<\/p>\n<ul>\n<li>Finalmente se indica que las autoliquidaciones presentadas por los obligados tributarios a las que se refiere este art\u00edculo 12 podr\u00e1n ser objeto de verificaci\u00f3n y comprobaci\u00f3n por la Administraci\u00f3n, que practicar\u00e1, en su caso, la liquidaci\u00f3n que proceda y que, en particular, no se derivar\u00e1 ning\u00fan efecto preclusivo de las rectificaciones a las que se refiere la letra b) del apartado 2 de este art\u00edculo.<\/li>\n<\/ul>\n<p>\u00a9 La presente informaci\u00f3n es propiedad de <strong>Escura<\/strong>, <strong>abogados<\/strong> y <strong>economistas<\/strong>, quedando prohibida su reproducci\u00f3n sin permiso expreso.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last banner\" style=\"--awb-padding-top:20px;--awb-padding-right:20px;--awb-padding-bottom:20px;--awb-padding-left:20px;--awb-bg-image:url(&#039;http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/area_derecho_societario_mercantil.jpg&#039;);--awb-bg-size:cover;--awb-margin-top:40px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy fusion-column-has-bg-image\" data-bg-url=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/area_derecho_societario_mercantil.jpg\"><div class=\"fusion-text fusion-text-2\"><h3><a href=\"https:\/\/www.escura.com\/es\/derecho-societario-mercantil\/\" target=\"_blank\" rel=\"noopener noreferrer\">Consulta nuestra \u00e1rea de <strong>Derecho Societario Mercantil<\/strong><\/a><\/h3>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":28303,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,28],"tags":[],"class_list":["post-28630","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empresa-corporate","category-fiscal-contable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Escura. Abogados y Economistas<\/title>\n<meta name=\"description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.escura.com\/es\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Real Decreto-Ley 19\/2020 \u2013 Intereses de demora en aplazamientos COVID y declaraci\u00f3n del Impuesto sobre Sociedades 2019\" \/>\n<meta property=\"og:description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.escura.com\/es\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Escura | Abogados y Economistas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/escura.abogados\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-01T09:50:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/marek-levak-lMEMH5Rd30U-unsplash-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"escura\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:site\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"escura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\\\/\"},\"author\":{\"name\":\"escura\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/4edd59e125b9654539921a4ec1da53b1\"},\"headline\":\"Real Decreto-Ley 19\\\/2020 \u2013 Intereses de demora en aplazamientos COVID y declaraci\u00f3n del Impuesto sobre Sociedades 2019\",\"datePublished\":\"2020-06-01T09:50:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\\\/\"},\"wordCount\":1737,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/marek-levak-lMEMH5Rd30U-unsplash-1-scaled.jpg\",\"articleSection\":[\"Derecho de empresa (Corporate)\",\"Fiscal - Contable\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\\\/\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\\\/\",\"name\":\"Escura. Abogados y Economistas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/marek-levak-lMEMH5Rd30U-unsplash-1-scaled.jpg\",\"datePublished\":\"2020-06-01T09:50:53+00:00\",\"description\":\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/marek-levak-lMEMH5Rd30U-unsplash-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/marek-levak-lMEMH5Rd30U-unsplash-1-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Real Decreto-Ley 19\\\/2020 \u2013 Intereses de demora en aplazamientos COVID y declaraci\u00f3n del Impuesto sobre Sociedades 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"name\":\"Escura | Abogados y Economistas\",\"description\":\"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.escura.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\",\"name\":\"Escura. Abogados y economistas\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Escura. Abogados y economistas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/escura.abogados\",\"https:\\\/\\\/x.com\\\/escura_abogados\",\"https:\\\/\\\/www.instagram.com\\\/escura_abogados\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bufete-escura\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BufeteEscura\\\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/4edd59e125b9654539921a4ec1da53b1\",\"name\":\"escura\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"caption\":\"escura\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Escura. Abogados y Economistas","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.escura.com\/es\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\/","og_locale":"es_ES","og_type":"article","og_title":"Real Decreto-Ley 19\/2020 \u2013 Intereses de demora en aplazamientos COVID y declaraci\u00f3n del Impuesto sobre Sociedades 2019","og_description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","og_url":"https:\/\/www.escura.com\/es\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\/","og_site_name":"Escura | Abogados y Economistas","article_publisher":"https:\/\/www.facebook.com\/escura.abogados","article_published_time":"2020-06-01T09:50:53+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/marek-levak-lMEMH5Rd30U-unsplash-1-scaled.jpg","type":"image\/jpeg"}],"author":"escura","twitter_card":"summary_large_image","twitter_creator":"@escura_abogados","twitter_site":"@escura_abogados","twitter_misc":{"Escrito por":"escura","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\/#article","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\/"},"author":{"name":"escura","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/4edd59e125b9654539921a4ec1da53b1"},"headline":"Real Decreto-Ley 19\/2020 \u2013 Intereses de demora en aplazamientos COVID y declaraci\u00f3n del Impuesto sobre Sociedades 2019","datePublished":"2020-06-01T09:50:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\/"},"wordCount":1737,"commentCount":0,"publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"image":{"@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/marek-levak-lMEMH5Rd30U-unsplash-1-scaled.jpg","articleSection":["Derecho de empresa (Corporate)","Fiscal - Contable"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.escura.com\/es\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\/","url":"https:\/\/www.escura.com\/es\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\/","name":"Escura. Abogados y Economistas","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\/#primaryimage"},"image":{"@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/marek-levak-lMEMH5Rd30U-unsplash-1-scaled.jpg","datePublished":"2020-06-01T09:50:53+00:00","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","breadcrumb":{"@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.escura.com\/es\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\/#primaryimage","url":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/marek-levak-lMEMH5Rd30U-unsplash-1-scaled.jpg","contentUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/marek-levak-lMEMH5Rd30U-unsplash-1-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.escura.com\/es\/real-decreto-ley-19-2020-intereses-de-demora-en-aplazamientos-covid-y-declaracion-del-impuesto-sobre-sociedades-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.escura.com\/es\/"},{"@type":"ListItem","position":2,"name":"Real Decreto-Ley 19\/2020 \u2013 Intereses de demora en aplazamientos COVID y declaraci\u00f3n del Impuesto sobre Sociedades 2019"}]},{"@type":"WebSite","@id":"https:\/\/www.escura.com\/es\/#website","url":"https:\/\/www.escura.com\/es\/","name":"Escura | Abogados y Economistas","description":"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona","publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.escura.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.escura.com\/es\/#organization","name":"Escura. Abogados y economistas","url":"https:\/\/www.escura.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Escura. Abogados y economistas"},"image":{"@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/escura.abogados","https:\/\/x.com\/escura_abogados","https:\/\/www.instagram.com\/escura_abogados\/","https:\/\/www.linkedin.com\/company\/bufete-escura","https:\/\/www.youtube.com\/user\/BufeteEscura\/videos"]},{"@type":"Person","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/4edd59e125b9654539921a4ec1da53b1","name":"escura","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","caption":"escura"}}]}},"_links":{"self":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/28630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/comments?post=28630"}],"version-history":[{"count":0,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/28630\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media\/28303"}],"wp:attachment":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media?parent=28630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/categories?post=28630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/tags?post=28630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}