{"id":28492,"date":"2020-09-28T11:58:26","date_gmt":"2020-09-28T09:58:26","guid":{"rendered":"https:\/\/blog.escura.com\/?p=18062"},"modified":"2020-09-28T11:58:26","modified_gmt":"2020-09-28T09:58:26","slug":"nueva-ley-de-trabajo-a-distancia","status":"publish","type":"post","link":"https:\/\/www.escura.com\/es\/nueva-ley-de-trabajo-a-distancia\/","title":{"rendered":"Nueva Ley de trabajo a distancia"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><h3 style=\"text-align: right;\"><a href=\"http:\/\/www.escura.com\/wp-content\/uploads\/2020\/09\/171-20-nueva-ley-trabajo-a-distancia.pdf\">Consulte el PDF<\/a><\/h3>\n<p><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-18063\" src=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/09\/CC0-495-min-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>Tras meses de negociaciones, el Ministerio de Trabajo y Econom\u00eda Social ha logrado aprobar el nuevo Real Decreto-ley 28\/2020, de 22 de septiembre, de trabajo a distancia, tras llegar a un acuerdo entre el Ejecutivo, sindicatos y patronal.<\/p>\n<p>Se entender\u00e1 que se est\u00e1 ejerciendo de forma regular el trabajo a distancia, cuando se practique en un per\u00edodo de referencia de tres meses durante un m\u00ednimo de treinta por ciento de la jornada, siendo su ejercicio <strong>voluntario y reversible<\/strong>, y debi\u00e9ndose garantizar los mismos derechos que hubieran ostentado los trabajadores si prestasen servicios en el centro de trabajo de la empresa.<\/p>\n<p>El acuerdo del trabajo a distancia que se lleve a cabo entre la empresa y el trabajador <strong>deber\u00e1 realizarse por escrito<\/strong>: ya sea con el acuerdo propiamente incorporado en el contrato de trabajo inicial o se realice en un momento posterior, siempre y cuando quede formalizado antes de que se inicie el trabajo a distancia, debi\u00e9ndose entregar una copia a la representaci\u00f3n legal de los trabajadores, en un plazo no superior a diez d\u00edas, para ser <strong>enviada a la Oficina de Empleo<\/strong>, oficina a la que tendr\u00e1 que ser remitida la copia igualmente independientemente de que haya o no representaci\u00f3n legal de los trabajadores.<\/p>\n<p>Respecto al <strong>contenido del acuerdo de trabajo a distancia<\/strong>, sin perjuicio de lo dispuesto en el convenio colectivo, deber\u00e1 incluir principalmente:<\/p>\n<ul>\n<li>El inventario de los medios, equipos y herramientas que exige el desarrollo del trabajo a distancia concertado.<\/li>\n<li>Enumeraci\u00f3n de los gastos que pudiera tener la persona trabajadora por el hecho de prestar servicios a distancia.<\/li>\n<li>Horario de trabajo, as\u00ed como el correspondiente porcentaje y distribuci\u00f3n entre trabajo presencial y a distancia.<\/li>\n<li>Lugar de trabajo a distancia elegido por la persona trabajadora.<\/li>\n<li>Los posibles medios de control empresarial de la actividad.<\/li>\n<li>Duraci\u00f3n del propio acuerdo.<\/li>\n<\/ul>\n<p>Se podr\u00e1n llevar a cabo modificaciones de las condiciones que se hubieran establecido en el acuerdo, incluido el porcentaje de presencialidad establecido, siempre que medie acuerdo entre el trabajador y la empresa, debi\u00e9ndose volver a formalizar por escrito previamente a su aplicaci\u00f3n, as\u00ed como comunicar nuevamente a los representantes de los trabajadores.<\/p>\n<p>En cuanto a los <strong>gastos que pudiera tener la persona trabajadora<\/strong> por el hecho de prestar servicios a distancia, deber\u00e1 ser <strong>sufragado o compensado por la empresa<\/strong>, y no podr\u00e1 suponer la asunci\u00f3n por parte de la persona trabajadora de posibles gastos relacionados con los equipos, herramientas y medios vinculados al desarrollo de su actividad.<\/p>\n<p>En lo que respecta al <strong>sistema de registro horario<\/strong>, deber\u00e1 reflejar fielmente el tiempo que la persona trabajadora que realiza trabajo a distancia dedica a la actividad laboral, sin perjuicio de la flexibilidad horaria, debiendo incluir, el momento de inicio y finalizaci\u00f3n de la jornada.<\/p>\n<p>La empresa tendr\u00e1 derecho a <strong>adoptar las medidas que estime m\u00e1s oportunas de vigilancia y control con el fin de poder verificar el cumplimiento de las obligaciones y deberes laborales<\/strong> de la persona trabajadora, incluy\u00e9ndose la utilizaci\u00f3n de medios telem\u00e1ticos, preservando en su adopci\u00f3n y aplicaci\u00f3n la consideraci\u00f3n debida a su dignidad.<\/p>\n<p>\u00a9 La presente informaci\u00f3n es propiedad de <strong>Escura<\/strong>, <strong>abogados<\/strong> y <strong>economistas<\/strong>, quedando prohibida su reproducci\u00f3n sin permiso expreso.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last banner\" style=\"--awb-padding-top:20px;--awb-padding-right:20px;--awb-padding-bottom:20px;--awb-padding-left:20px;--awb-bg-image:url(&#039;http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/area_recursos_humanosv2.jpg&#039;);--awb-bg-size:cover;--awb-margin-top:40px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy fusion-column-has-bg-image\" data-bg-url=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/area_recursos_humanosv2.jpg\"><div class=\"fusion-text fusion-text-2\"><h3><a href=\"https:\/\/www.escura.com\/es\/recursos-humanos\/\" target=\"_blank\" rel=\"noopener noreferrer\">Consulta nuestra \u00e1rea de <strong>Recursos Humanos<\/strong><\/a><\/h3>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":28184,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-28492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recursos-humanos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Escura. Abogados y Economistas<\/title>\n<meta name=\"description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.escura.com\/es\/nueva-ley-de-trabajo-a-distancia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nueva Ley de trabajo a distancia\" \/>\n<meta property=\"og:description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.escura.com\/es\/nueva-ley-de-trabajo-a-distancia\/\" \/>\n<meta property=\"og:site_name\" content=\"Escura | Abogados y Economistas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/escura.abogados\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-28T09:58:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/09\/CC0-495-min-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"escura\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:site\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"escura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/nueva-ley-de-trabajo-a-distancia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/nueva-ley-de-trabajo-a-distancia\\\/\"},\"author\":{\"name\":\"escura\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/4edd59e125b9654539921a4ec1da53b1\"},\"headline\":\"Nueva Ley de trabajo a distancia\",\"datePublished\":\"2020-09-28T09:58:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/nueva-ley-de-trabajo-a-distancia\\\/\"},\"wordCount\":909,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/nueva-ley-de-trabajo-a-distancia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/CC0-495-min-1.jpg\",\"articleSection\":[\"Recursos Humanos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/nueva-ley-de-trabajo-a-distancia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/nueva-ley-de-trabajo-a-distancia\\\/\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/nueva-ley-de-trabajo-a-distancia\\\/\",\"name\":\"Escura. Abogados y Economistas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/nueva-ley-de-trabajo-a-distancia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/nueva-ley-de-trabajo-a-distancia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/CC0-495-min-1.jpg\",\"datePublished\":\"2020-09-28T09:58:26+00:00\",\"description\":\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/nueva-ley-de-trabajo-a-distancia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/nueva-ley-de-trabajo-a-distancia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/nueva-ley-de-trabajo-a-distancia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/CC0-495-min-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/CC0-495-min-1.jpg\",\"width\":1000,\"height\":670},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/nueva-ley-de-trabajo-a-distancia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nueva Ley de trabajo a distancia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"name\":\"Escura | Abogados y Economistas\",\"description\":\"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.escura.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\",\"name\":\"Escura. Abogados y economistas\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Escura. Abogados y economistas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/escura.abogados\",\"https:\\\/\\\/x.com\\\/escura_abogados\",\"https:\\\/\\\/www.instagram.com\\\/escura_abogados\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bufete-escura\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BufeteEscura\\\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/4edd59e125b9654539921a4ec1da53b1\",\"name\":\"escura\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"caption\":\"escura\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Escura. Abogados y Economistas","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.escura.com\/es\/nueva-ley-de-trabajo-a-distancia\/","og_locale":"es_ES","og_type":"article","og_title":"Nueva Ley de trabajo a distancia","og_description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","og_url":"https:\/\/www.escura.com\/es\/nueva-ley-de-trabajo-a-distancia\/","og_site_name":"Escura | Abogados y Economistas","article_publisher":"https:\/\/www.facebook.com\/escura.abogados","article_published_time":"2020-09-28T09:58:26+00:00","og_image":[{"width":1000,"height":670,"url":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/09\/CC0-495-min-1.jpg","type":"image\/jpeg"}],"author":"escura","twitter_card":"summary_large_image","twitter_creator":"@escura_abogados","twitter_site":"@escura_abogados","twitter_misc":{"Escrito por":"escura","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.escura.com\/es\/nueva-ley-de-trabajo-a-distancia\/#article","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/nueva-ley-de-trabajo-a-distancia\/"},"author":{"name":"escura","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/4edd59e125b9654539921a4ec1da53b1"},"headline":"Nueva Ley de trabajo a distancia","datePublished":"2020-09-28T09:58:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.escura.com\/es\/nueva-ley-de-trabajo-a-distancia\/"},"wordCount":909,"commentCount":0,"publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"image":{"@id":"https:\/\/www.escura.com\/es\/nueva-ley-de-trabajo-a-distancia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/09\/CC0-495-min-1.jpg","articleSection":["Recursos Humanos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.escura.com\/es\/nueva-ley-de-trabajo-a-distancia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.escura.com\/es\/nueva-ley-de-trabajo-a-distancia\/","url":"https:\/\/www.escura.com\/es\/nueva-ley-de-trabajo-a-distancia\/","name":"Escura. Abogados y Economistas","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.escura.com\/es\/nueva-ley-de-trabajo-a-distancia\/#primaryimage"},"image":{"@id":"https:\/\/www.escura.com\/es\/nueva-ley-de-trabajo-a-distancia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/09\/CC0-495-min-1.jpg","datePublished":"2020-09-28T09:58:26+00:00","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","breadcrumb":{"@id":"https:\/\/www.escura.com\/es\/nueva-ley-de-trabajo-a-distancia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.escura.com\/es\/nueva-ley-de-trabajo-a-distancia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/nueva-ley-de-trabajo-a-distancia\/#primaryimage","url":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/09\/CC0-495-min-1.jpg","contentUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/09\/CC0-495-min-1.jpg","width":1000,"height":670},{"@type":"BreadcrumbList","@id":"https:\/\/www.escura.com\/es\/nueva-ley-de-trabajo-a-distancia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.escura.com\/es\/"},{"@type":"ListItem","position":2,"name":"Nueva Ley de trabajo a distancia"}]},{"@type":"WebSite","@id":"https:\/\/www.escura.com\/es\/#website","url":"https:\/\/www.escura.com\/es\/","name":"Escura | Abogados y Economistas","description":"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona","publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.escura.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.escura.com\/es\/#organization","name":"Escura. Abogados y economistas","url":"https:\/\/www.escura.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Escura. Abogados y economistas"},"image":{"@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/escura.abogados","https:\/\/x.com\/escura_abogados","https:\/\/www.instagram.com\/escura_abogados\/","https:\/\/www.linkedin.com\/company\/bufete-escura","https:\/\/www.youtube.com\/user\/BufeteEscura\/videos"]},{"@type":"Person","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/4edd59e125b9654539921a4ec1da53b1","name":"escura","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","caption":"escura"}}]}},"_links":{"self":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/28492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/comments?post=28492"}],"version-history":[{"count":0,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/28492\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media\/28184"}],"wp:attachment":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media?parent=28492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/categories?post=28492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/tags?post=28492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}