{"id":2727,"date":"2016-03-07T12:25:03","date_gmt":"2016-03-07T12:25:03","guid":{"rendered":"https:\/\/www.escura.com\/blog-escura\/?p=2727"},"modified":"2016-03-07T12:25:03","modified_gmt":"2016-03-07T12:25:03","slug":"nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p","status":"publish","type":"post","link":"https:\/\/www.escura.com\/es\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\/","title":{"rendered":"Nuevos requisitos fiscales para las Oficinas de farmacia en r\u00e9gimen de S.C.P."},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><strong>Circular de especial trascendencia para el sector y para aquellas Oficinas de farmacia en r\u00e9gimen de S.C.P.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.escura.com\/blog-escura\/wp-content\/uploads\/2015\/05\/idi.jpg\" rel=\"attachment wp-att-1702\"><img decoding=\"async\" class=\"size-thumbnail wp-image-1702 alignleft\" src=\"https:\/\/www.escura.com\/blog-escura\/wp-content\/uploads\/2015\/05\/idi-150x150.jpg\" alt=\"idi\" width=\"150\" height=\"150\" \/><\/a>Tal como les hemos ido informando, el r\u00e9gimen fiscal de las S.C.P. qued\u00f3 modificado con efectos 1 de enero de 2016, por lo que estas entidades deb\u00edan de transformarse en entidades con personalidad jur\u00eddica.<\/p>\n<p style=\"text-align: justify;\">Este sistema resultaba de imposible aplicaci\u00f3n a las Oficinas de farmacia en atenci\u00f3n a la normativa propia del sector.<\/p>\n<p style=\"text-align: justify;\">Esta circunstancia ha motivado reiteradas reuniones y consultas a la Administraci\u00f3n Tributaria. Incluso se ha planteado, por algunos colectivos, que la disposici\u00f3n del Ministerio no ser\u00eda de aplicaci\u00f3n para el sector de Oficinas de farmacia.<\/p>\n<p style=\"text-align: justify;\">Desde <strong>Bufete Escura<\/strong> hemos mantenido siempre el criterio, en base a la disposici\u00f3n legal y a los comentarios recibidos directamente de la propia Agencia Tributaria, que la modificaci\u00f3n de la Ley o su no aplicaci\u00f3n al sector de Oficinas de farmacia era totalmente un supuesto que no pod\u00eda darse puesto que la modificaci\u00f3n era para todas las S.C.P., con independencia del sector econ\u00f3mico. Otra cosa diferente era como compatibilizar el fin de las S.C.P. como figura jur\u00eddica de gesti\u00f3n tributaria con el sector farmac\u00e9utico, resultando que la figura m\u00e1s id\u00f3nea para aquellas farmacias que comparten titularidad, era y es el de las C.B. (Comunidad de Bienes).<\/p>\n<p style=\"text-align: justify;\">En este sentido ya nos pronunciamos desde <strong>Bufete Escura<\/strong> y muy especialmente en la jornada que celebramos espec\u00edficamente en el mes de noviembre de 2015.<\/p>\n<p style=\"text-align: justify;\">En base a lo anteriormente indicado, cabe destacar:<\/p>\n<p style=\"text-align: justify;\"><strong><u>TODAS LAS OFICINAS DE FARMACIA EN R\u00c9GIMEN DE SCP DEBEN TRANSFORMARSE EN CB DURANTE ESTE PRIMER TRIMESTRE DE 2016 CON EFECTOS 1 DE ENERO DE 2016.<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\">Es importante destacar que la transformaci\u00f3n debe realizarse en este primer trimestre puesto que en la declaraci\u00f3n tributaria del mes de abril debe contemplar los efectos fiscales desde el 1 de enero.<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n destacar que <strong>PARA COBRAR DEL CATSALUD ES REQUISITO IMPRESCINDIBLE DISPONER DEL NUEVO NIF COMO C.B.<\/strong><\/p>\n<p style=\"text-align: justify;\">No obstante y con car\u00e1cter previo a cumplimentar los simples tr\u00e1mites que m\u00e1s adelante indicaremos, lo que constituye un tema de <strong>EXTRAORDINARIA IMPORTANCIA ES QUE CON CAR\u00c1CTER PREVIO A LA TRANSFORMACI\u00d3N, SE ANALICE EL IMPACTO FISCAL DEL MISMO.<\/strong><\/p>\n<p style=\"text-align: justify;\">Para que todos los farmac\u00e9uticos afectados puedan entendernos:<\/p>\n<p style=\"text-align: justify;\"><strong>EJEMPLO:<\/strong><\/p>\n<p style=\"text-align: justify;\">S.C.P. en la que existen dos cotitulares con un porcentaje, uno de ellos al 90% y el otro al 10%, pero que por el acuerdo societario tributan al 50% en atenci\u00f3n al tiempo dedicado a la Oficina de farmacia.<\/p>\n<p style=\"text-align: justify;\">En el nuevo r\u00e9gimen de la C.B. se tributa por el porcentaje que se tiene, es decir, que siguiendo el mismo ejemplo anterior, <strong><u>el que tiene el 90% deber\u00e1 tributar por el 90% <\/u><\/strong>del rendimiento de la Oficina de farmacia.<\/p>\n<p style=\"text-align: justify;\">Este ejemplo pone de manifiesto la important\u00edsima trascendencia de la previa planificaci\u00f3n fiscal, sin la cual la simple trasformaci\u00f3n puede llevar a un aut\u00e9ntico problema entre los socios de la actual S.C.P.<\/p>\n<p style=\"text-align: justify;\">Les recordamos que <strong>Bufete Escura<\/strong> dispone de un departamento jur\u00eddico y fiscal especializado en Oficinas de farmacia. En atenci\u00f3n a la gran trascendencia de esta reforma y el elevado n\u00famero de consultas que estamos recibiendo hemos creado un nuevo servicio puntual consistente en:<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>SERVICIO ATENCI\u00d3N TRANSFORMACI\u00d3N S.C.P. A C.B. DE BUFETE ESCURA: <\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><u>Servicio primera visita gratuita de atenci\u00f3n al farmac\u00e9utico<\/u><\/strong>: todos los farmac\u00e9uticos afectados pueden concertar entrevista con <strong>Roc\u00edo Mart\u00edn<\/strong>, abogada, quien les\u00a0 clarificar\u00e1 la normativa y su aplicaci\u00f3n al caso concreto.<\/p>\n<p style=\"text-align: justify;\">Para la concertaci\u00f3n de entrevistas llamar al 934940131 y preguntar por Aurora Cantero.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>TR\u00c1MITES PARA LA TRANSFORMACI\u00d3N:<\/strong><\/p>\n<p style=\"text-align: justify;\">Sucintamente informar que los tr\u00e1mites a realizar son:<\/p>\n<ul>\n<li style=\"text-align: justify;\">Constituci\u00f3n de la C.B.<\/li>\n<li style=\"text-align: justify;\">Baja de la S.C.P. en la Agencia Tributaria, INSS, y otras entidades p\u00fablicas dependiendo de cada caso.<\/li>\n<li style=\"text-align: justify;\">Comunicaci\u00f3n a los empleados de la subrogaci\u00f3n empresarial.<\/li>\n<li style=\"text-align: justify;\">Cumplimentaci\u00f3n de alta censal en la Agencia Tributaria como C.B. (impreso 036)<\/li>\n<li style=\"text-align: justify;\">Comunicaciones a entidades varias (a determinar seg\u00fan cada Oficina de farmacias). En Bufete Escura disponemos de un cuestionario de entidades y empresas a las que realizar las notificaciones.<\/li>\n<li style=\"text-align: justify;\">Comunicaci\u00f3n al Colegio de Farmac\u00e9uticos.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Circular de especial trascendencia para el sector y para aquellas Oficinas de farmacia en r\u00e9gimen de S.C.P. Tal como les hemos ido informando, el r\u00e9gimen fiscal de las S.C.P. qued\u00f3 modificado con efectos 1 de enero de 2016, por lo que estas entidades deb\u00edan de transformarse en entidades con personalidad jur\u00eddica. Este sistema resultaba de imposible aplicaci\u00f3n a las Oficinas de farmacia en atenci\u00f3n a la normativa propia del sector. Esta circunstancia  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-2727","post","type-post","status-publish","format-standard","hentry","category-oficinas-de-farmacia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Escura. Abogados y Economistas<\/title>\n<meta name=\"description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.escura.com\/es\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuevos requisitos fiscales para las Oficinas de farmacia en r\u00e9gimen de S.C.P.\" \/>\n<meta property=\"og:description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.escura.com\/es\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\/\" \/>\n<meta property=\"og:site_name\" content=\"Escura | Abogados y Economistas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/escura.abogados\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-07T12:25:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.escura.com\/blog-escura\/wp-content\/uploads\/2015\/05\/idi-150x150.jpg\" \/>\n<meta name=\"author\" content=\"adminbe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:site\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminbe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\\\/\"},\"author\":{\"name\":\"adminbe\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/7a91eddf0c7dd9b28ddc69906b14e30e\"},\"headline\":\"Nuevos requisitos fiscales para las Oficinas de farmacia en r\u00e9gimen de S.C.P.\",\"datePublished\":\"2016-03-07T12:25:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\\\/\"},\"wordCount\":741,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/blog-escura\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/idi-150x150.jpg\",\"articleSection\":[\"Oficinas de Farmacia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\\\/\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\\\/\",\"name\":\"Escura. Abogados y Economistas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/blog-escura\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/idi-150x150.jpg\",\"datePublished\":\"2016-03-07T12:25:03+00:00\",\"description\":\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.escura.com\\\/blog-escura\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/idi-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.escura.com\\\/blog-escura\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/idi-150x150.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuevos requisitos fiscales para las Oficinas de farmacia en r\u00e9gimen de S.C.P.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"name\":\"Escura | Abogados y Economistas\",\"description\":\"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.escura.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\",\"name\":\"Escura. Abogados y economistas\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Escura. Abogados y economistas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/escura.abogados\",\"https:\\\/\\\/x.com\\\/escura_abogados\",\"https:\\\/\\\/www.instagram.com\\\/escura_abogados\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bufete-escura\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BufeteEscura\\\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/7a91eddf0c7dd9b28ddc69906b14e30e\",\"name\":\"adminbe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g\",\"caption\":\"adminbe\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Escura. Abogados y Economistas","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.escura.com\/es\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\/","og_locale":"es_ES","og_type":"article","og_title":"Nuevos requisitos fiscales para las Oficinas de farmacia en r\u00e9gimen de S.C.P.","og_description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","og_url":"https:\/\/www.escura.com\/es\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\/","og_site_name":"Escura | Abogados y Economistas","article_publisher":"https:\/\/www.facebook.com\/escura.abogados","article_published_time":"2016-03-07T12:25:03+00:00","og_image":[{"url":"https:\/\/www.escura.com\/blog-escura\/wp-content\/uploads\/2015\/05\/idi-150x150.jpg","type":"","width":"","height":""}],"author":"adminbe","twitter_card":"summary_large_image","twitter_creator":"@escura_abogados","twitter_site":"@escura_abogados","twitter_misc":{"Escrito por":"adminbe","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.escura.com\/es\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\/#article","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\/"},"author":{"name":"adminbe","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/7a91eddf0c7dd9b28ddc69906b14e30e"},"headline":"Nuevos requisitos fiscales para las Oficinas de farmacia en r\u00e9gimen de S.C.P.","datePublished":"2016-03-07T12:25:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.escura.com\/es\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\/"},"wordCount":741,"commentCount":0,"publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"image":{"@id":"https:\/\/www.escura.com\/es\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/blog-escura\/wp-content\/uploads\/2015\/05\/idi-150x150.jpg","articleSection":["Oficinas de Farmacia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.escura.com\/es\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.escura.com\/es\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\/","url":"https:\/\/www.escura.com\/es\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\/","name":"Escura. Abogados y Economistas","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.escura.com\/es\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\/#primaryimage"},"image":{"@id":"https:\/\/www.escura.com\/es\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/blog-escura\/wp-content\/uploads\/2015\/05\/idi-150x150.jpg","datePublished":"2016-03-07T12:25:03+00:00","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","breadcrumb":{"@id":"https:\/\/www.escura.com\/es\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.escura.com\/es\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\/#primaryimage","url":"https:\/\/www.escura.com\/blog-escura\/wp-content\/uploads\/2015\/05\/idi-150x150.jpg","contentUrl":"https:\/\/www.escura.com\/blog-escura\/wp-content\/uploads\/2015\/05\/idi-150x150.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.escura.com\/es\/nuevos-requisitos-fiscales-para-las-oficinas-de-farmacia-en-regimen-de-s-c-p\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.escura.com\/es\/"},{"@type":"ListItem","position":2,"name":"Nuevos requisitos fiscales para las Oficinas de farmacia en r\u00e9gimen de S.C.P."}]},{"@type":"WebSite","@id":"https:\/\/www.escura.com\/es\/#website","url":"https:\/\/www.escura.com\/es\/","name":"Escura | Abogados y Economistas","description":"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona","publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.escura.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.escura.com\/es\/#organization","name":"Escura. Abogados y economistas","url":"https:\/\/www.escura.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Escura. Abogados y economistas"},"image":{"@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/escura.abogados","https:\/\/x.com\/escura_abogados","https:\/\/www.instagram.com\/escura_abogados\/","https:\/\/www.linkedin.com\/company\/bufete-escura","https:\/\/www.youtube.com\/user\/BufeteEscura\/videos"]},{"@type":"Person","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/7a91eddf0c7dd9b28ddc69906b14e30e","name":"adminbe","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g","caption":"adminbe"}}]}},"_links":{"self":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/2727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/comments?post=2727"}],"version-history":[{"count":0,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/2727\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media?parent=2727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/categories?post=2727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/tags?post=2727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}