{"id":24802,"date":"2021-03-10T11:55:49","date_gmt":"2021-03-10T10:55:49","guid":{"rendered":"https:\/\/www.escura.com\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\/"},"modified":"2022-10-26T17:47:20","modified_gmt":"2022-10-26T15:47:20","slug":"como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores","status":"publish","type":"post","link":"https:\/\/www.escura.com\/es\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\/","title":{"rendered":"C\u00f3mo hacer un Plan de Igualdad cuando no hay representaci\u00f3n de los trabajadores"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:104%;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_3_4 3_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:75%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.56%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:2.56%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"1920\" height=\"625\" title=\"circular:MEDIDA IMAGEN CIRCULARES (8)\" src=\"http:\/\/www.escura.com\/wp-content\/uploads\/2021\/03\/MEDIDA-IMAGEN-CIRCULARES-8.png\" alt class=\"img-responsive wp-image-34040\" srcset=\"https:\/\/www.escura.com\/wp-content\/uploads\/2021\/03\/MEDIDA-IMAGEN-CIRCULARES-8-200x65.png 200w, https:\/\/www.escura.com\/wp-content\/uploads\/2021\/03\/MEDIDA-IMAGEN-CIRCULARES-8-400x130.png 400w, https:\/\/www.escura.com\/wp-content\/uploads\/2021\/03\/MEDIDA-IMAGEN-CIRCULARES-8-600x195.png 600w, https:\/\/www.escura.com\/wp-content\/uploads\/2021\/03\/MEDIDA-IMAGEN-CIRCULARES-8-800x260.png 800w, https:\/\/www.escura.com\/wp-content\/uploads\/2021\/03\/MEDIDA-IMAGEN-CIRCULARES-8-1200x391.png 1200w, https:\/\/www.escura.com\/wp-content\/uploads\/2021\/03\/MEDIDA-IMAGEN-CIRCULARES-8.png 1920w\" sizes=\"(max-width: 1024px) 100vw, (max-width: 850px) 100vw, 1920px\" \/><\/span><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:30px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-1\"><h3 style=\"text-align: right;\"><a href=\"http:\/\/www.escura.com\/wp-content\/uploads\/2021\/03\/28-21-plan-igualdad-cuando-no-hay-representacion-legal-de-los-trabajadores.pdf\">Consulte el PDF<\/a><\/h3>\n<\/div><div class=\"fusion-text fusion-text-2\"><h1 style=\"text-align: left;\">C\u00f3mo hacer un Plan de Igualdad cuando no hay representaci\u00f3n de los trabajadores<\/h1>\n<p>Uno de los aspectos fundamentales en la elaboraci\u00f3n de un Plan de Igualdad es la correcta constituci\u00f3n de la comisi\u00f3n negociadora o Comit\u00e9 de Igualdad.<\/p>\n<p>En un inicio, el art\u00edculo 45.1 de la Ley Org\u00e1nica 3\/2007, de 22 de marzo, para la igualdad efectiva de mujeres y hombres, estableci\u00f3 que las empresas, en la confecci\u00f3n de los planes de igualdad, deber\u00e1n \u201c(\u2026) <em>negociar, y en su caso acordar, con los <strong>representantes legales de los trabajadores<\/strong> en la forma que se determine en la legislaci\u00f3n laboral<\/em>\u201d.<\/p>\n<p>El problema surg\u00eda cuando una empresa, por el motivo que fuese, no dispon\u00eda de representaci\u00f3n legal de los trabajadores. Ante este vac\u00edo legal, y para poder dar cumplimento a la normativa de igualdad, las empresas formaban una comisi\u00f3n negociadora o comit\u00e9 <em>ad hoc<\/em> (art\u00edculo 88 del Estatuto de los Trabajadores) o negociaban directamente con las personas trabajadoras de la empresa.<\/p>\n<p>Sin embargo, desde la publicaci\u00f3n del Real Decreto 901\/2020, de 13 de octubre, por el que se regulan los planes de igualdad y su registro, estas dos opciones ya no son posibles.<\/p>\n<p>El Real Decreto 901\/2020, de 13 de octubre, solvent\u00f3 la problem\u00e1tica al establecer en su art\u00edculo 5.3 que \u201c<em>En las empresas donde no existan las representaciones legales referidas en el apartado anterior se crear\u00e1 una comisi\u00f3n negociadora constituida, de un lado, por la representaci\u00f3n de la empresa y, de otro lado, por una representaci\u00f3n de las personas trabajadoras, integrada por <strong>los sindicatos m\u00e1s representativos y por los sindicatos representativos del sector al que pertenezca la empresa<\/strong> y con legitimaci\u00f3n para formar parte de la comisi\u00f3n negociadora del convenio colectivo de aplicaci\u00f3n<\/em>\u201d.<\/p>\n<p>Por lo tanto, en la actualidad, no es posible confeccionar un plan de igualdad sin la previa negociaci\u00f3n de los representantes legales de los trabajadores o, en su caso, los sindicatos m\u00e1s representativos y los sindicatos representativos del sector al que pertenece una organizaci\u00f3n.<\/p>\n<p>Recientemente, la Confederaci\u00f3n Espa\u00f1ola de Organizaciones Empresariales (CEOE) recurri\u00f3 ante el Tribunal Supremo este procedimiento al considerar que, en aquellas empresas sin representaci\u00f3n legal de los trabajadores, se impone la negociaci\u00f3n con los sindicatos para desarrollar los planes de igualdad, sin permitir a los trabajadores buscar a otros representantes. Cabe recordar que el art\u00edculo 5 del Real Decreto fue uno de los motivos por los cuales la CEOE ya expres\u00f3 su malestar en el pasado, desmarc\u00e1ndose definitivamente de la elaboraci\u00f3n del Real Decreto y siendo aprobado por el Ministerio de Trabajo \u00fanicamente con el respaldo de los sindicatos.<\/p>\n<p>Por todo lo anterior, y para que el Plan de Igualdad sea efectivo y no se declare nulo en un ulterior procedimiento judicial, desde ESCURA recomendamos que se constituya correctamente el Comit\u00e9 de Igualdad y se sigan los procedimientos legales establecidos.<\/p>\n<p>Recordamos igualmente que, toda empresa que haya implantado un plan de igualdad de manera anterior a la entrada en vigor del Real Decreto 901\/2020, de 13 de octubre, debe adaptarse a esta nueva normativa antes del <strong>14 de enero de 2022<\/strong> (Disposici\u00f3n transitoria \u00fanica del Real Decreto 901\/2020, de 13 de octubre).<\/p>\n<\/div><div class=\"fusion-text fusion-text-3\"><p>\u00a9 La presente informaci\u00f3n es propiedad de <a href=\"https:\/\/www.escura.com\/es\/\"><strong>Escura<\/strong>,\u00a0<strong>abogados<\/strong>\u00a0y\u00a0<strong>economistas<\/strong><\/a>, quedando prohibida su reproducci\u00f3n sin permiso expreso.<\/p>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:30px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-4\"><p style=\"text-align: center;\"><strong>Encuentra m\u00e1s informaci\u00f3n sobre el plan de igualdad<\/strong><\/p>\n<\/div><div style=\"text-align:center;\"><a class=\"fusion-button button-flat fusion-button-default-size button-default fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" target=\"_self\" href=\"https:\/\/www.escura.com\/es\/plan-de-igualdad\/\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">\u00c1REA PLAN DE IGUALDAD<\/span><\/a><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_4 1_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:7.68%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:7.68%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-search-element fusion-search-element-1 fusion-search-form-clean\">\t\t<form role=\"search\" class=\"searchform fusion-search-form  fusion-search-form-clean\" method=\"get\" action=\"https:\/\/www.escura.com\/es\/\">\n\t\t\t<div class=\"fusion-search-form-content\">\n\n\t\t\t\t\n\t\t\t\t<div class=\"fusion-search-field search-field\">\n\t\t\t\t\t<label><span class=\"screen-reader-text\">Buscar:<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input type=\"search\" value=\"\" name=\"s\" class=\"s\" placeholder=\"Search...\" required aria-required=\"true\" aria-label=\"Search...\"\/>\n\t\t\t\t\t\t\t\t\t\t\t<\/label>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"fusion-search-button search-button\">\n\t\t\t\t\t<input type=\"submit\" class=\"fusion-search-submit searchsubmit\" aria-label=\"Buscar\" value=\"&#xf002;\" \/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<input type=\"hidden\" name=\"post_type[]\" value=\"post\" \/><input type=\"hidden\" name=\"post_type[]\" value=\"page\" \/><input type=\"hidden\" name=\"post_type[]\" value=\"avada_portfolio\" \/><input type=\"hidden\" name=\"post_type[]\" value=\"avada_faq\" \/><input type=\"hidden\" name=\"search_limit_to_post_titles\" value=\"0\" \/><input type=\"hidden\" name=\"add_woo_product_skus\" value=\"0\" \/><input type=\"hidden\" name=\"fs\" value=\"1\" \/>\n\t\t\t<\/div>\n\n\n\t\t\t\n\t\t<\/form>\n\t\t<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:30px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-5\"><h2><span style=\"color: #000080;\">Nuestras \u00c1reas<\/span><\/h2>\n<\/div><ul style=\"--awb-line-height:27.2px;--awb-icon-width:27.2px;--awb-icon-height:27.2px;--awb-icon-margin:11.2px;--awb-content-margin:38.4px;\" class=\"fusion-checklist fusion-checklist-1 fusion-checklist-default type-icons\"><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-folder far\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<div class=\"fusion-text fusion-text-1\">\n<p data-fontsize=\"26\" data-lineheight=\"31.46px\"><a href=\"https:\/\/www.escura.com\/es\/compliance-penal\/\">Compliance Penal<\/a><\/p>\n<\/div>\n<div class=\"fusion-text fusion-text-2\"><\/div>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-folder far\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p><a href=\"https:\/\/www.escura.com\/es\/derecho-societario-mercantil\/\">Drecho Societario y Mercantil<\/a><\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-folder far\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p><a href=\"https:\/\/www.escura.com\/es\/economico-fiscal\/\">Econ\u00f3mico Fiscal<\/a><\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-folder far\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p><a href=\"https:\/\/www.escura.com\/es\/plan-de-igualdad\/\">Plan de Igualdad<\/a><\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-folder far\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p><a href=\"https:\/\/www.escura.com\/es\/proteccion-de-datos\/\">Protecci\u00f3n de Datos<\/a><\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-folder far\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p><a href=\"https:\/\/www.escura.com\/es\/recursos-humanos\/\">Recursos Humanos<\/a><\/p>\n<\/div><\/li><\/ul><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:104%;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-6\"><h2><span style=\"color: #000080;\">\u00daltimas Novedades<\/span><\/h2>\n<\/div><div class=\"fusion-recent-posts fusion-recent-posts-1 avada-container layout-default layout-columns-4\"><section class=\"fusion-columns columns fusion-columns-4 columns-4\"><article class=\"post fusion-column column col col-lg-3 col-md-3 col-sm-3\"><div class=\"fusion-flexslider fusion-flexslider-loading flexslider flexslider-hover-type-none\"><ul class=\"slides\"><li><a href=\"https:\/\/www.escura.com\/es\/actualizacion-de-las-bases-de-cotizacion-a-la-seguridad-social-para-el-ejercicio-2026\/\" aria-label=\"Actualizaci\u00f3n de las bases de cotizaci\u00f3n a la seguridad social para el ejercicio 2026\" class=\"hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"441\" src=\"https:\/\/www.escura.com\/wp-content\/uploads\/2026\/04\/Fotos-interior-circulares-2026-04-02T095423.932-700x441.png\" class=\"attachment-recent-posts size-recent-posts\" alt=\"\" srcset=\"https:\/\/www.escura.com\/wp-content\/uploads\/2026\/04\/Fotos-interior-circulares-2026-04-02T095423.932-320x202.png 320w, https:\/\/www.escura.com\/wp-content\/uploads\/2026\/04\/Fotos-interior-circulares-2026-04-02T095423.932-700x441.png 700w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/li><\/ul><\/div><div class=\"recent-posts-content\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/www.escura.com\/es\/author\/adminbe\/\" title=\"Entradas de adminbe\" rel=\"author\">adminbe<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-04-02T09:56:30+02:00<\/span><h4 class=\"entry-title\"><a href=\"https:\/\/www.escura.com\/es\/actualizacion-de-las-bases-de-cotizacion-a-la-seguridad-social-para-el-ejercicio-2026\/\">Actualizaci\u00f3n de las bases de cotizaci\u00f3n a la seguridad social para el ejercicio 2026<\/a><\/h4><p class=\"meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/www.escura.com\/es\/author\/adminbe\/\" title=\"Entradas de adminbe\" rel=\"author\">adminbe<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-04-02T09:56:30+02:00<\/span><\/p><\/div><\/article><article class=\"post fusion-column column col col-lg-3 col-md-3 col-sm-3\"><div class=\"fusion-flexslider fusion-flexslider-loading flexslider flexslider-hover-type-none\"><ul class=\"slides\"><li><a href=\"https:\/\/www.escura.com\/es\/permiso-retribuido-de-5-dias-para-el-cuidado-de-familiares\/\" aria-label=\"Permiso retribuido de 5 d\u00edas para el cuidado de familiares\" class=\"hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"441\" src=\"https:\/\/www.escura.com\/wp-content\/uploads\/2026\/03\/Fotos-interior-circulares-50-700x441.png\" class=\"attachment-recent-posts size-recent-posts\" alt=\"\" srcset=\"https:\/\/www.escura.com\/wp-content\/uploads\/2026\/03\/Fotos-interior-circulares-50-320x202.png 320w, https:\/\/www.escura.com\/wp-content\/uploads\/2026\/03\/Fotos-interior-circulares-50-700x441.png 700w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/li><\/ul><\/div><div class=\"recent-posts-content\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/www.escura.com\/es\/author\/adminbe\/\" title=\"Entradas de adminbe\" rel=\"author\">adminbe<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-03-31T13:55:51+02:00<\/span><h4 class=\"entry-title\"><a href=\"https:\/\/www.escura.com\/es\/permiso-retribuido-de-5-dias-para-el-cuidado-de-familiares\/\">Permiso retribuido de 5 d\u00edas para el cuidado de familiares<\/a><\/h4><p class=\"meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/www.escura.com\/es\/author\/adminbe\/\" title=\"Entradas de adminbe\" rel=\"author\">adminbe<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-03-31T13:55:51+02:00<\/span><\/p><\/div><\/article><article class=\"post fusion-column column col col-lg-3 col-md-3 col-sm-3\"><div class=\"fusion-flexslider fusion-flexslider-loading flexslider flexslider-hover-type-none\"><ul class=\"slides\"><li><a href=\"https:\/\/www.escura.com\/es\/residencias-sts-205-2026-y-libre-disposicion\/\" aria-label=\"Residencias: STS 205\/2026 y libre disposici\u00f3n\" class=\"hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"441\" src=\"https:\/\/www.escura.com\/wp-content\/uploads\/2026\/03\/Fotos-interior-circulares-24-700x441.png\" class=\"attachment-recent-posts size-recent-posts\" alt=\"\" srcset=\"https:\/\/www.escura.com\/wp-content\/uploads\/2026\/03\/Fotos-interior-circulares-24-320x202.png 320w, https:\/\/www.escura.com\/wp-content\/uploads\/2026\/03\/Fotos-interior-circulares-24-700x441.png 700w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/li><\/ul><\/div><div class=\"recent-posts-content\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/www.escura.com\/es\/author\/adminbe\/\" title=\"Entradas de adminbe\" rel=\"author\">adminbe<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-03-02T09:08:02+01:00<\/span><h4 class=\"entry-title\"><a href=\"https:\/\/www.escura.com\/es\/residencias-sts-205-2026-y-libre-disposicion\/\">Residencias: STS 205\/2026 y libre disposici\u00f3n<\/a><\/h4><p class=\"meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/www.escura.com\/es\/author\/adminbe\/\" title=\"Entradas de adminbe\" rel=\"author\">adminbe<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-03-02T09:08:02+01:00<\/span><\/p><\/div><\/article><article class=\"post fusion-column column col col-lg-3 col-md-3 col-sm-3\"><div class=\"fusion-flexslider fusion-flexslider-loading flexslider flexslider-hover-type-none\"><ul class=\"slides\"><li><a href=\"https:\/\/www.escura.com\/es\/la-ia-y-la-digitalizacion-como-causas-del-despido-objetivo\/\" aria-label=\"La IA y la digitalizaci\u00f3n como causas del despido objetivo\" class=\"hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"441\" src=\"https:\/\/www.escura.com\/wp-content\/uploads\/2026\/02\/Fotos-interior-circulares-15-700x441.png\" class=\"attachment-recent-posts size-recent-posts\" alt=\"\" srcset=\"https:\/\/www.escura.com\/wp-content\/uploads\/2026\/02\/Fotos-interior-circulares-15-320x202.png 320w, https:\/\/www.escura.com\/wp-content\/uploads\/2026\/02\/Fotos-interior-circulares-15-700x441.png 700w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/li><\/ul><\/div><div class=\"recent-posts-content\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/www.escura.com\/es\/author\/adminbe\/\" title=\"Entradas de adminbe\" rel=\"author\">adminbe<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-02-27T09:42:17+01:00<\/span><h4 class=\"entry-title\"><a href=\"https:\/\/www.escura.com\/es\/la-ia-y-la-digitalizacion-como-causas-del-despido-objetivo\/\">La IA y la digitalizaci\u00f3n como causas del despido objetivo<\/a><\/h4><p class=\"meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/www.escura.com\/es\/author\/adminbe\/\" title=\"Entradas de adminbe\" rel=\"author\">adminbe<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-02-27T09:42:17+01:00<\/span><\/p><\/div><\/article><\/section><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39,282,27],"tags":[133,263,214,262],"class_list":["post-24802","post","type-post","status-publish","format-standard","hentry","category-compliance-penal","category-plan-de-igualdad","category-recursos-humanos","tag-empresa","tag-gran-empresa","tag-plan-de-igualdad","tag-representacion-de-los-trabajadores"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>C\u00f3mo hacer un Plan de Igualdad sin representaci\u00f3n de los trabajadores<\/title>\n<meta name=\"description\" content=\"Uno de los aspectos fundamentales en la elaboraci\u00f3n de un Plan de Igualdad es la correcta constituci\u00f3n de la comisi\u00f3n negociadora o Comit\u00e9 de Igualdad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.35-181-91-225.plesk.page\/es\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo hacer un Plan de Igualdad cuando no hay representaci\u00f3n de los trabajadores\" \/>\n<meta property=\"og:description\" content=\"Uno de los aspectos fundamentales en la elaboraci\u00f3n de un Plan de Igualdad es la correcta constituci\u00f3n de la comisi\u00f3n negociadora o Comit\u00e9 de Igualdad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.35-181-91-225.plesk.page\/es\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\/\" \/>\n<meta property=\"og:site_name\" content=\"Escura | Abogados y Economistas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/escura.abogados\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-10T10:55:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-26T15:47:20+00:00\" \/>\n<meta name=\"author\" content=\"adminbe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:site\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminbe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.35-181-91-225.plesk.page\\\/es\\\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.35-181-91-225.plesk.page\\\/es\\\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\\\/\"},\"author\":{\"name\":\"adminbe\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/7a91eddf0c7dd9b28ddc69906b14e30e\"},\"headline\":\"C\u00f3mo hacer un Plan de Igualdad cuando no hay representaci\u00f3n de los trabajadores\",\"datePublished\":\"2021-03-10T10:55:49+00:00\",\"dateModified\":\"2022-10-26T15:47:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.35-181-91-225.plesk.page\\\/es\\\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\\\/\"},\"wordCount\":2646,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"keywords\":[\"empresa\",\"gran empresa\",\"plan de igualdad\",\"representaci\u00f3n de los trabajadores\"],\"articleSection\":[\"Compliance Penal\",\"Plan de Igualdad\",\"Recursos Humanos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.35-181-91-225.plesk.page\\\/es\\\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.35-181-91-225.plesk.page\\\/es\\\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\\\/\",\"url\":\"https:\\\/\\\/www.35-181-91-225.plesk.page\\\/es\\\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\\\/\",\"name\":\"C\u00f3mo hacer un Plan de Igualdad sin representaci\u00f3n de los trabajadores\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\"},\"datePublished\":\"2021-03-10T10:55:49+00:00\",\"dateModified\":\"2022-10-26T15:47:20+00:00\",\"description\":\"Uno de los aspectos fundamentales en la elaboraci\u00f3n de un Plan de Igualdad es la correcta constituci\u00f3n de la comisi\u00f3n negociadora o Comit\u00e9 de Igualdad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.35-181-91-225.plesk.page\\\/es\\\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.35-181-91-225.plesk.page\\\/es\\\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.35-181-91-225.plesk.page\\\/es\\\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo hacer un Plan de Igualdad cuando no hay representaci\u00f3n de los trabajadores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"name\":\"Escura | Abogados y Economistas\",\"description\":\"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.escura.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\",\"name\":\"Escura. Abogados y economistas\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Escura. Abogados y economistas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/escura.abogados\",\"https:\\\/\\\/x.com\\\/escura_abogados\",\"https:\\\/\\\/www.instagram.com\\\/escura_abogados\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bufete-escura\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BufeteEscura\\\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/7a91eddf0c7dd9b28ddc69906b14e30e\",\"name\":\"adminbe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g\",\"caption\":\"adminbe\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"C\u00f3mo hacer un Plan de Igualdad sin representaci\u00f3n de los trabajadores","description":"Uno de los aspectos fundamentales en la elaboraci\u00f3n de un Plan de Igualdad es la correcta constituci\u00f3n de la comisi\u00f3n negociadora o Comit\u00e9 de Igualdad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.35-181-91-225.plesk.page\/es\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo hacer un Plan de Igualdad cuando no hay representaci\u00f3n de los trabajadores","og_description":"Uno de los aspectos fundamentales en la elaboraci\u00f3n de un Plan de Igualdad es la correcta constituci\u00f3n de la comisi\u00f3n negociadora o Comit\u00e9 de Igualdad.","og_url":"https:\/\/www.35-181-91-225.plesk.page\/es\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\/","og_site_name":"Escura | Abogados y Economistas","article_publisher":"https:\/\/www.facebook.com\/escura.abogados","article_published_time":"2021-03-10T10:55:49+00:00","article_modified_time":"2022-10-26T15:47:20+00:00","author":"adminbe","twitter_card":"summary_large_image","twitter_creator":"@escura_abogados","twitter_site":"@escura_abogados","twitter_misc":{"Escrito por":"adminbe","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.35-181-91-225.plesk.page\/es\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\/#article","isPartOf":{"@id":"https:\/\/www.35-181-91-225.plesk.page\/es\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\/"},"author":{"name":"adminbe","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/7a91eddf0c7dd9b28ddc69906b14e30e"},"headline":"C\u00f3mo hacer un Plan de Igualdad cuando no hay representaci\u00f3n de los trabajadores","datePublished":"2021-03-10T10:55:49+00:00","dateModified":"2022-10-26T15:47:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.35-181-91-225.plesk.page\/es\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\/"},"wordCount":2646,"commentCount":0,"publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"keywords":["empresa","gran empresa","plan de igualdad","representaci\u00f3n de los trabajadores"],"articleSection":["Compliance Penal","Plan de Igualdad","Recursos Humanos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.35-181-91-225.plesk.page\/es\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.35-181-91-225.plesk.page\/es\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\/","url":"https:\/\/www.35-181-91-225.plesk.page\/es\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\/","name":"C\u00f3mo hacer un Plan de Igualdad sin representaci\u00f3n de los trabajadores","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/#website"},"datePublished":"2021-03-10T10:55:49+00:00","dateModified":"2022-10-26T15:47:20+00:00","description":"Uno de los aspectos fundamentales en la elaboraci\u00f3n de un Plan de Igualdad es la correcta constituci\u00f3n de la comisi\u00f3n negociadora o Comit\u00e9 de Igualdad.","breadcrumb":{"@id":"https:\/\/www.35-181-91-225.plesk.page\/es\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.35-181-91-225.plesk.page\/es\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.35-181-91-225.plesk.page\/es\/como-hacer-un-plan-de-igualdad-cuando-no-hay-representacion-de-los-trabajadores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.escura.com\/es\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo hacer un Plan de Igualdad cuando no hay representaci\u00f3n de los trabajadores"}]},{"@type":"WebSite","@id":"https:\/\/www.escura.com\/es\/#website","url":"https:\/\/www.escura.com\/es\/","name":"Escura | Abogados y Economistas","description":"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona","publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.escura.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.escura.com\/es\/#organization","name":"Escura. Abogados y economistas","url":"https:\/\/www.escura.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Escura. Abogados y economistas"},"image":{"@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/escura.abogados","https:\/\/x.com\/escura_abogados","https:\/\/www.instagram.com\/escura_abogados\/","https:\/\/www.linkedin.com\/company\/bufete-escura","https:\/\/www.youtube.com\/user\/BufeteEscura\/videos"]},{"@type":"Person","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/7a91eddf0c7dd9b28ddc69906b14e30e","name":"adminbe","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g","caption":"adminbe"}}]}},"_links":{"self":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/24802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/comments?post=24802"}],"version-history":[{"count":8,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/24802\/revisions"}],"predecessor-version":[{"id":34039,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/24802\/revisions\/34039"}],"wp:attachment":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media?parent=24802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/categories?post=24802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/tags?post=24802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}