{"id":24137,"date":"2021-01-04T10:30:04","date_gmt":"2021-01-04T09:30:04","guid":{"rendered":"https:\/\/www.escura.com\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\/"},"modified":"2021-01-04T10:30:04","modified_gmt":"2021-01-04T09:30:04","slug":"entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021","status":"publish","type":"post","link":"https:\/\/www.escura.com\/es\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\/","title":{"rendered":"Entra en vigor el nuevo permiso de paternidad de 16 semanas desde el 1 de enero de 2021"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><h3 style=\"text-align: right;\"><a href=\"http:\/\/www.escura.com\/wp-content\/uploads\/2021\/01\/1-21-nuevo-permiso-paternidad-16-semanas.pdf\">Consulte el PDF<\/a><\/h3>\n<p><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-17849\" src=\"http:\/\/www.escura.com\/wp-content\/uploads\/2020\/06\/CC0-480-min-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>La publicaci\u00f3n del Real Decreto-ley 6\/2019, de 1 de marzo, de medidas urgentes para garant\u00eda de la igualdad de trato y de oportunidades entre mujeres y hombres en el empleo y la ocupaci\u00f3n, ha ido aumentando progresivamente el periodo de permiso de paternidad en Espa\u00f1a, pasando a 8 semanas en 2019, y a 12 semanas en 2020.<\/p>\n<p><strong>El 1 de enero de 2021, el permiso de paternidad se amplia a 16 semanas, cuyas seis primeras deben disfrutarse tras el parto, y las diez restantes se podr\u00e1n disfrutar de manera continuada o interrumpida, ya sea en r\u00e9gimen de jornada completa o parcial, seg\u00fan acuerdo entre la empresa y la persona trabajadora, durante el primer a\u00f1o desde el nacimiento.\u00a0 <\/strong><\/p>\n<p>\u00a9 La presente informaci\u00f3n es propiedad de <strong>Escura<\/strong>, <strong>abogados<\/strong> y <strong>economistas<\/strong>, quedando prohibida su reproducci\u00f3n sin permiso expreso.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last banner\" style=\"--awb-padding-top:20px;--awb-padding-right:20px;--awb-padding-bottom:20px;--awb-padding-left:20px;--awb-bg-image:url(&#039;http:\/\/www.escura.com\/wp-content\/uploads\/2019\/03\/area_recursos_humanosv2.jpg&#039;);--awb-bg-size:cover;--awb-margin-top:40px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy fusion-column-has-bg-image\" data-bg-url=\"http:\/\/www.escura.com\/wp-content\/uploads\/2019\/03\/area_recursos_humanosv2.jpg\"><div class=\"fusion-text fusion-text-2\"><h3><a href=\"https:\/\/www.escura.com\/recursos-humanos\/\" target=\"_blank\" rel=\"noopener noreferrer\">Consulta nuestra \u00e1rea de <strong>Recursos Humanos<\/strong><\/a><\/h3>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":28306,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-24137","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recursos-humanos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Escura. Abogados y Economistas<\/title>\n<meta name=\"description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.escura.com\/es\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entra en vigor el nuevo permiso de paternidad de 16 semanas desde el 1 de enero de 2021\" \/>\n<meta property=\"og:description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.escura.com\/es\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Escura | Abogados y Economistas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/escura.abogados\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-04T09:30:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/06\/CC0-480-min-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adminbe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:site\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminbe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\\\/\"},\"author\":{\"name\":\"adminbe\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/7a91eddf0c7dd9b28ddc69906b14e30e\"},\"headline\":\"Entra en vigor el nuevo permiso de paternidad de 16 semanas desde el 1 de enero de 2021\",\"datePublished\":\"2021-01-04T09:30:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\\\/\"},\"wordCount\":510,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/CC0-480-min-1.jpg\",\"articleSection\":[\"Recursos Humanos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\\\/\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\\\/\",\"name\":\"Escura. Abogados y Economistas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/CC0-480-min-1.jpg\",\"datePublished\":\"2021-01-04T09:30:04+00:00\",\"description\":\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/CC0-480-min-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/CC0-480-min-1.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entra en vigor el nuevo permiso de paternidad de 16 semanas desde el 1 de enero de 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"name\":\"Escura | Abogados y Economistas\",\"description\":\"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.escura.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\",\"name\":\"Escura. Abogados y economistas\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Escura. Abogados y economistas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/escura.abogados\",\"https:\\\/\\\/x.com\\\/escura_abogados\",\"https:\\\/\\\/www.instagram.com\\\/escura_abogados\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bufete-escura\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BufeteEscura\\\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/7a91eddf0c7dd9b28ddc69906b14e30e\",\"name\":\"adminbe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g\",\"caption\":\"adminbe\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Escura. Abogados y Economistas","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.escura.com\/es\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\/","og_locale":"es_ES","og_type":"article","og_title":"Entra en vigor el nuevo permiso de paternidad de 16 semanas desde el 1 de enero de 2021","og_description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","og_url":"https:\/\/www.escura.com\/es\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\/","og_site_name":"Escura | Abogados y Economistas","article_publisher":"https:\/\/www.facebook.com\/escura.abogados","article_published_time":"2021-01-04T09:30:04+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/06\/CC0-480-min-1.jpg","type":"image\/jpeg"}],"author":"adminbe","twitter_card":"summary_large_image","twitter_creator":"@escura_abogados","twitter_site":"@escura_abogados","twitter_misc":{"Escrito por":"adminbe","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.escura.com\/es\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\/#article","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\/"},"author":{"name":"adminbe","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/7a91eddf0c7dd9b28ddc69906b14e30e"},"headline":"Entra en vigor el nuevo permiso de paternidad de 16 semanas desde el 1 de enero de 2021","datePublished":"2021-01-04T09:30:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.escura.com\/es\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\/"},"wordCount":510,"commentCount":0,"publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"image":{"@id":"https:\/\/www.escura.com\/es\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/06\/CC0-480-min-1.jpg","articleSection":["Recursos Humanos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.escura.com\/es\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.escura.com\/es\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\/","url":"https:\/\/www.escura.com\/es\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\/","name":"Escura. Abogados y Economistas","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.escura.com\/es\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\/#primaryimage"},"image":{"@id":"https:\/\/www.escura.com\/es\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/06\/CC0-480-min-1.jpg","datePublished":"2021-01-04T09:30:04+00:00","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","breadcrumb":{"@id":"https:\/\/www.escura.com\/es\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.escura.com\/es\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\/#primaryimage","url":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/06\/CC0-480-min-1.jpg","contentUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/06\/CC0-480-min-1.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/www.escura.com\/es\/entra-en-vigor-el-nuevo-permiso-de-paternidad-de-16-semanas-desde-el-1-de-enero-de-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.escura.com\/es\/"},{"@type":"ListItem","position":2,"name":"Entra en vigor el nuevo permiso de paternidad de 16 semanas desde el 1 de enero de 2021"}]},{"@type":"WebSite","@id":"https:\/\/www.escura.com\/es\/#website","url":"https:\/\/www.escura.com\/es\/","name":"Escura | Abogados y Economistas","description":"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona","publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.escura.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.escura.com\/es\/#organization","name":"Escura. Abogados y economistas","url":"https:\/\/www.escura.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Escura. Abogados y economistas"},"image":{"@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/escura.abogados","https:\/\/x.com\/escura_abogados","https:\/\/www.instagram.com\/escura_abogados\/","https:\/\/www.linkedin.com\/company\/bufete-escura","https:\/\/www.youtube.com\/user\/BufeteEscura\/videos"]},{"@type":"Person","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/7a91eddf0c7dd9b28ddc69906b14e30e","name":"adminbe","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g","caption":"adminbe"}}]}},"_links":{"self":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/24137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/comments?post=24137"}],"version-history":[{"count":0,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/24137\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media\/28306"}],"wp:attachment":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media?parent=24137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/categories?post=24137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/tags?post=24137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}