{"id":23655,"date":"2020-04-30T19:28:57","date_gmt":"2020-04-30T17:28:57","guid":{"rendered":"https:\/\/www.escura.com\/consecuencias-brexit-en-espana\/"},"modified":"2020-04-30T19:28:57","modified_gmt":"2020-04-30T17:28:57","slug":"consecuencias-brexit-en-espana","status":"publish","type":"post","link":"https:\/\/www.escura.com\/es\/consecuencias-brexit-en-espana\/","title":{"rendered":"Consecuencias del Brexit en Espa\u00f1a"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><h3 style=\"text-align: right;\"><a href=\"http:\/\/www.escura.com\/wp-content\/uploads\/2020\/04\/99-20-Consecuencias-Brexit.pdf\">Consulte el PDF<\/a><\/h3>\n<p><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-17269\" src=\"http:\/\/www.escura.com\/wp-content\/uploads\/2020\/02\/CC0-445-min-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>Tras la confirmaci\u00f3n de la salida Reino Unido de la Uni\u00f3n Europea el pasado 31 de enero de 2020, <strong>se ha establecido un periodo de transici\u00f3n hasta el 31 de diciembre<\/strong> del presente a\u00f1o, con el objetivo de adaptar y negociar t\u00e9rminos entre todas las partes involucradas. Se establece la posibilidad de solicitar una pr\u00f3rroga al periodo de transici\u00f3n la cual deber\u00e1 solicitarse antes del 1 de julio de 2019.<\/p>\n<p>Desde <strong>ESCURA<\/strong> hemos preparado la siguiente circular para dar respuesta a las consultas recibidas sobre las consecuencias del Brexit en Espa\u00f1a en distintas materias:<\/p>\n<ul>\n<li><strong>SUCESIONES Y TESTAMENTOS:<\/strong><\/li>\n<\/ul>\n<p>Es aconsejable que los ciudadanos brit\u00e1nicos que tengan bienes en Espa\u00f1a revisen antes del 31 de diciembre de 2020 los testamentos que hayan firmado, a fin de comprobar qu\u00e9 disposiciones ser\u00e1n v\u00e1lidas y cu\u00e1les pueden dejar de serlo, una vez dejen de aplicarse las leyes europeas a dichos ciudadanos.<\/p>\n<p>Si no se ha hecho Testamento, es aconsejable hacerlo antes del 31 de diciembre de 2020, pues hasta esa fecha pueden disponerse cuestiones que las leyes europeas permiten y facilitan las herencias para los bienes en Espa\u00f1a.<\/p>\n<ul>\n<li><strong>MIGRACIONES:\u00a0<\/strong><\/li>\n<\/ul>\n<p>Durante el periodo de transici\u00f3n\u00a0los ciudadanos brit\u00e1nicos y sus familiares nacionales de terceros pa\u00edses residentes en Espa\u00f1a mantendr\u00e1n los derechos derivados del Derecho de la Uni\u00f3n (con excepci\u00f3n del Derecho de sufragio activo y pasivo en elecciones al Parlamento Europeo y el ejercicio de la iniciativa Legislativa Ciudadana de la UE). Una vez finalizado el periodo transitorio, el Acuerdo de Retirada prev\u00e9 que se mantendr\u00e1n sus derechos de residencia, trabajo, estudios y Seguridad Social.<\/p>\n<p>A los efectos de acreditar la residencia legal en Espa\u00f1a se deber\u00e1 obtener el certificado de registro -certificado verde- y tarjetas de familiares de ciudadano de la UE antes de que finalice el periodo transitorio.<\/p>\n<p>A los ciudadanos brit\u00e1nicos y sus familiares que inicien su residencia legal en Espa\u00f1a finalizado el periodo transitorio les aplicar\u00e1 lo que se establezca el Acuerdo que regule la relaci\u00f3n futura entre Reino Unido y la UE o, en su defecto, el r\u00e9gimen general de extranjer\u00eda en Espa\u00f1a.<\/p>\n<ul>\n<li><strong>PROTECCI\u00d3N DE DATOS:<\/strong><\/li>\n<\/ul>\n<p>El Reglamento Europeo de Protecci\u00f3n de Datos (RGPD) se seguir\u00e1 aplicando durante el periodo de transici\u00f3n hasta el 31 de diciembre de 2020. Tras este periodo de transici\u00f3n el Reglamento ya no ser\u00e1 directamente aplicable al Reino unido, sin embargo, formalmente el Reino unido seguir\u00e1 cumpliendo con las obligaciones establecidas en el Reglamento ya que la Ley interna en materia de Protecci\u00f3n de datos (Data Protection Act &#8211; DPA) fue adaptada al RGPD e incluso prev\u00e9 el escenario post -Brexit.<\/p>\n<p>Sin embargo, la salida de la UE del Reino Unido supone que este se convierta en un tercer pa\u00eds. Seg\u00fan el RGPD, la transferencia de datos personales a terceros pa\u00edses y organizaciones internacionales solo se permite en ciertas circunstancias concretas, por lo que la mayor\u00eda de las organizaciones del Reino Unido que proporcionan bienes o servicios a residentes de la UE tendr\u00e1n la obligaci\u00f3n de realizar las transferencias internacionales de datos bajo las condiciones establecidas en el RGPD, as\u00ed como designar un representante en la UE, dado que actualmente no existe a\u00fan ning\u00fan acuerdo en materia de transferencia internacional de datos post-Brexit.<\/p>\n<ul>\n<li><strong>SEGURIDAD SOCIAL<\/strong>:<\/li>\n<\/ul>\n<p>En relaci\u00f3n con el r\u00e9gimen de la Seguridad Social, la situaci\u00f3n actual se mantendr\u00e1 a lo largo del periodo transitorio, o bien hasta la firma de un acuerdo internacional entre la Uni\u00f3n Europea y Reino Unido, de materia bilateral entre ambos (o hasta el 31 de diciembre de 2021 como plazo m\u00e1ximo: 21 meses despu\u00e9s de la retirada). Algunos aspectos a tener en cuenta en materia de seguridad social son los siguientes:<\/p>\n<ul>\n<li>Todos los trabajadores del Reino Unido que presten servicios en Espa\u00f1a deber\u00e1n inscribirse como residentes de la Uni\u00f3n Europea bajo el EU Settlement Scheme para poder continuar con su residencia en el estado miembro de la UE en el que se encuentren.<\/li>\n<li>A efectos de las futuras pensiones contributivas de Espa\u00f1a, respecto a los trabajadores que est\u00e1n cotizando en el Reino Unido actualmente, en principio, se tendr\u00e1n en cuenta los per\u00edodos cotizados en Reino Unido, al menos hasta la fecha del final de este per\u00edodo transitorio (31 de diciembre de 2020). Si en dicha fecha, el trabajador espa\u00f1ol sigue cotizando en el Reino Unido, los periodos cotizados se computar\u00e1n igualmente si bien en esa situaci\u00f3n ser\u00eda de aplicaci\u00f3n lo dispuesto por el acuerdo bilateral alcanzado por Reino Unido y la UE.<\/li>\n<li>Los ciudadanos de la UE que residan en el Reino Unido tendr\u00e1n acceso a la atenci\u00f3n sanitaria en Reino Unido conforme a las mismas condiciones que los nacionales brit\u00e1nicos hasta el 31 de diciembre de 2020, con independencia de estar o no registrado en el EU Settlement Scheme. Lo mismo ocurrir\u00eda para aquellos trabajadores del Reino Unido que prestan sus servicios en el estado espa\u00f1ol.<\/li>\n<li>En caso de que, una vez acabado el per\u00edodo transitorio, el ciudadano de la UE perdiese el empleo, tendr\u00e1 derecho a percibir prestaciones de desempleo en el pa\u00eds que corresponda, pudiendo exportar dichas prestaciones a su pa\u00eds de origen.<\/li>\n<\/ul>\n<ul>\n<li><strong>CORPORATE<\/strong>:<\/li>\n<\/ul>\n<p>Se recomienda que todos aquellos contratos en los cuales alguna de las partes sea brit\u00e1nica, estipulen expresamente en los mismos tanto la ley como la jurisdicci\u00f3n aplicable al contrato, de esto modo se evitar\u00e1n problemas de ley aplicable y fuero una vez llegado el 31 de diciembre de 2020.<\/p>\n<p>Asimismo, se recomienda que todos aquellos contratos que apliquen o se remitan a una normativa europea sean revisados al objeto de determinar si dicha normativa seguir\u00e1 siendo de aplicaci\u00f3n llegado el 31 de diciembre de 2020.<\/p>\n<ul>\n<li><strong>LITIGIOS Y ARBITRAJE: <\/strong><\/li>\n<\/ul>\n<p>Luego del 31 de diciembre de 2020 ya no ser\u00e1 de aplicaci\u00f3n el Reglamento (UE) 1215\/2012 por lo cual se ver\u00e1n afectados los siguientes aspectos:<\/p>\n<ul>\n<li>La\u00a0<em>competencia<\/em>para las\u00a0obligaciones contractuales y extracontractuales\u00a0si el demandado reside en Reino Unido.<\/li>\n<li>El r<em>econocimiento de los contratos y resoluciones judiciales<\/em>, al no ser aplicable el reglamente los mismos no tendr\u00e1n fuerza ejecutiva, por lo que es importante fijar en el mismo el r\u00e9gimen aplicable.<\/li>\n<\/ul>\n<p>Tampoco ser\u00e1 de aplicaci\u00f3n el\u00a0<em>Reglamento (CE) 1393\/2007 sobre Cooperaci\u00f3n procesal civil<\/em>\u00a0y el\u00a0<em>Reglamento 1206\/2001<\/em>\u00a0para las pruebas practicadas en otros pa\u00edses. Por lo que los procedimientos ser\u00e1n m\u00e1s complejos.<\/p>\n<ul>\n<li><strong>OPERACIONES DE COMPRA Y VENTA DE MERCANC\u00cdA CON EL REINO UNIDO<\/strong>:<\/li>\n<\/ul>\n<p>Durante el periodo transitorio se seguir\u00e1 aplicando la legislaci\u00f3n comunitaria en el Reino Unido con referencia al mercado interior y uni\u00f3n aduanera. Por lo tanto, el Reino Unido continuar\u00e1, siendo tratado como estado miembro de la UE en lo referente a declaraciones de operaciones intracomunitarias. Es decir que, las empresas no tendr\u00e1n que realizar formalidades aduaneras, y no se pagar\u00e1n aranceles ni otros grav\u00e1menes.<\/p>\n<p>Una vez que termine el periodo transitorio, a efectos de IVA, las entregas al Reino Unido dejar\u00e1n de considerarse entregas intracomunitarias y se considerar\u00e1n exportaciones a tercer pa\u00eds, por lo tanto, habr\u00e1 que presentar una declaraci\u00f3n de exportaci\u00f3n. En el caso concreto de los env\u00edos de productos objeto de Impuestos Especiales al Reino Unido, despu\u00e9s del periodo transitorio, se realizar\u00e1n por el procedimiento previsto en la Ley de Impuestos Especiales para las exportaciones.<\/p>\n<p>\u00a9 La presente informaci\u00f3n es propiedad de <strong>Escura<\/strong>, <strong>abogados<\/strong> y <strong>economistas<\/strong>, quedando prohibida su reproducci\u00f3n sin permiso expreso.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":28100,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39,30,34,28,33,31,27],"tags":[],"class_list":["post-23655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-compliance-penal","category-empresa-corporate","category-derecho-de-familia","category-fiscal-contable","category-litigios-arbitraje","category-proteccion-datos","category-recursos-humanos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Escura. Abogados y Economistas<\/title>\n<meta name=\"description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.escura.com\/es\/consecuencias-brexit-en-espana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consecuencias del Brexit en Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.escura.com\/es\/consecuencias-brexit-en-espana\/\" \/>\n<meta property=\"og:site_name\" content=\"Escura | Abogados y Economistas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/escura.abogados\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-30T17:28:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/02\/CC0-445-min-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"662\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adminbe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:site\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminbe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/consecuencias-brexit-en-espana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/consecuencias-brexit-en-espana\\\/\"},\"author\":{\"name\":\"adminbe\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/7a91eddf0c7dd9b28ddc69906b14e30e\"},\"headline\":\"Consecuencias del Brexit en Espa\u00f1a\",\"datePublished\":\"2020-04-30T17:28:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/consecuencias-brexit-en-espana\\\/\"},\"wordCount\":1452,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/consecuencias-brexit-en-espana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/CC0-445-min-1.jpg\",\"articleSection\":[\"Compliance Penal\",\"Derecho de empresa (Corporate)\",\"Derecho de familia\",\"Fiscal - Contable\",\"Litigios\",\"Protecci\u00f3n de Datos\",\"Recursos Humanos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/consecuencias-brexit-en-espana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/consecuencias-brexit-en-espana\\\/\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/consecuencias-brexit-en-espana\\\/\",\"name\":\"Escura. Abogados y Economistas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/consecuencias-brexit-en-espana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/consecuencias-brexit-en-espana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/CC0-445-min-1.jpg\",\"datePublished\":\"2020-04-30T17:28:57+00:00\",\"description\":\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/consecuencias-brexit-en-espana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/consecuencias-brexit-en-espana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/consecuencias-brexit-en-espana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/CC0-445-min-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/CC0-445-min-1.jpg\",\"width\":1000,\"height\":662},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/consecuencias-brexit-en-espana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consecuencias del Brexit en Espa\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"name\":\"Escura | Abogados y Economistas\",\"description\":\"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.escura.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\",\"name\":\"Escura. Abogados y economistas\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Escura. Abogados y economistas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/escura.abogados\",\"https:\\\/\\\/x.com\\\/escura_abogados\",\"https:\\\/\\\/www.instagram.com\\\/escura_abogados\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bufete-escura\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BufeteEscura\\\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/7a91eddf0c7dd9b28ddc69906b14e30e\",\"name\":\"adminbe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g\",\"caption\":\"adminbe\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Escura. Abogados y Economistas","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.escura.com\/es\/consecuencias-brexit-en-espana\/","og_locale":"es_ES","og_type":"article","og_title":"Consecuencias del Brexit en Espa\u00f1a","og_description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","og_url":"https:\/\/www.escura.com\/es\/consecuencias-brexit-en-espana\/","og_site_name":"Escura | Abogados y Economistas","article_publisher":"https:\/\/www.facebook.com\/escura.abogados","article_published_time":"2020-04-30T17:28:57+00:00","og_image":[{"width":1000,"height":662,"url":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/02\/CC0-445-min-1.jpg","type":"image\/jpeg"}],"author":"adminbe","twitter_card":"summary_large_image","twitter_creator":"@escura_abogados","twitter_site":"@escura_abogados","twitter_misc":{"Escrito por":"adminbe","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.escura.com\/es\/consecuencias-brexit-en-espana\/#article","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/consecuencias-brexit-en-espana\/"},"author":{"name":"adminbe","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/7a91eddf0c7dd9b28ddc69906b14e30e"},"headline":"Consecuencias del Brexit en Espa\u00f1a","datePublished":"2020-04-30T17:28:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.escura.com\/es\/consecuencias-brexit-en-espana\/"},"wordCount":1452,"commentCount":0,"publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"image":{"@id":"https:\/\/www.escura.com\/es\/consecuencias-brexit-en-espana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/02\/CC0-445-min-1.jpg","articleSection":["Compliance Penal","Derecho de empresa (Corporate)","Derecho de familia","Fiscal - Contable","Litigios","Protecci\u00f3n de Datos","Recursos Humanos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.escura.com\/es\/consecuencias-brexit-en-espana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.escura.com\/es\/consecuencias-brexit-en-espana\/","url":"https:\/\/www.escura.com\/es\/consecuencias-brexit-en-espana\/","name":"Escura. Abogados y Economistas","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.escura.com\/es\/consecuencias-brexit-en-espana\/#primaryimage"},"image":{"@id":"https:\/\/www.escura.com\/es\/consecuencias-brexit-en-espana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/02\/CC0-445-min-1.jpg","datePublished":"2020-04-30T17:28:57+00:00","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","breadcrumb":{"@id":"https:\/\/www.escura.com\/es\/consecuencias-brexit-en-espana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.escura.com\/es\/consecuencias-brexit-en-espana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/consecuencias-brexit-en-espana\/#primaryimage","url":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/02\/CC0-445-min-1.jpg","contentUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/02\/CC0-445-min-1.jpg","width":1000,"height":662},{"@type":"BreadcrumbList","@id":"https:\/\/www.escura.com\/es\/consecuencias-brexit-en-espana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.escura.com\/es\/"},{"@type":"ListItem","position":2,"name":"Consecuencias del Brexit en Espa\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/www.escura.com\/es\/#website","url":"https:\/\/www.escura.com\/es\/","name":"Escura | Abogados y Economistas","description":"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona","publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.escura.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.escura.com\/es\/#organization","name":"Escura. Abogados y economistas","url":"https:\/\/www.escura.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Escura. Abogados y economistas"},"image":{"@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/escura.abogados","https:\/\/x.com\/escura_abogados","https:\/\/www.instagram.com\/escura_abogados\/","https:\/\/www.linkedin.com\/company\/bufete-escura","https:\/\/www.youtube.com\/user\/BufeteEscura\/videos"]},{"@type":"Person","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/7a91eddf0c7dd9b28ddc69906b14e30e","name":"adminbe","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/137bae7398ac3afb739b2fcea4266e889703e4bdaa4297b1c3b2d12cdf8f67a3?s=96&d=mm&r=g","caption":"adminbe"}}]}},"_links":{"self":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/23655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/comments?post=23655"}],"version-history":[{"count":0,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/23655\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media\/28100"}],"wp:attachment":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media?parent=23655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/categories?post=23655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/tags?post=23655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}