{"id":18225,"date":"2020-12-10T17:49:37","date_gmt":"2020-12-10T16:49:37","guid":{"rendered":"https:\/\/blog.escura.com\/?p=18225"},"modified":"2022-10-26T17:52:26","modified_gmt":"2022-10-26T15:52:26","slug":"novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres","status":"publish","type":"post","link":"https:\/\/www.escura.com\/es\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\/","title":{"rendered":"Novedades respecto al registro de planes de igualdad, y la igualdad retributiva entre hombres y mujeres"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><h3 style=\"text-align: right;\"><a href=\"http:\/\/www.escura.com\/wp-content\/uploads\/2020\/12\/201-19-novedades-registro-planes-igualdad-e-igualdad-retributiva-hombres-y-mujeres.pdf\">Consulte el PDF<\/a><\/h3>\n<p><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-16370\" src=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/CC0-139-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>El pasado 14 de octubre de 2020 se publicaron el <strong>Real Decreto 901\/2020 por el que se regulan los planes de igualdad y su registro<\/strong>, y<strong> el Real Decreto 902\/2020, de igualdad retributiva entre mujeres y hombres<\/strong>, tras el acuerdo alcanzado el pasado 30 de julio ente el Gobierno y los sindicatos, con el fin de dotar de efectividad el principio de igualdad de oportunidades y de trato entre hombres y mujeres en el \u00e1mbito del empleo.<\/p>\n<p>Respecto a las novedades que incluye el <strong>Real Decreto 901\/2020<\/strong>, encontramos:<\/p>\n<ul>\n<li>Su <strong>entrada en vigor<\/strong> el 14 de enero de 2021 con el <strong>objeto<\/strong> del desarrollo reglamentario de los planes de igualdad y su obligatoriedad en aquellas empresas de cincuenta o m\u00e1s trabajadores, as\u00ed como su diagn\u00f3stico, incluidas las obligaciones de registro, dep\u00f3sito y acceso.<\/li>\n<\/ul>\n<ul>\n<li>El <strong>procedimiento de negociaci\u00f3n de los planes de igualdad<\/strong> deber\u00e1 ser iniciado en el plazo m\u00e1ximo de tres meses siguientes al momento en que hubiesen alcanzado las personas de plantilla que lo hacen obligatorio, constituy\u00e9ndose en cualquier caso, una comisi\u00f3n negociadora en la que deber\u00e1n participar de forma paritaria la representaci\u00f3n de la empresa y de las personas trabajadoras, que tendr\u00e1 competencias para negociar, as\u00ed como sobre la negociaci\u00f3n de las medidas que integran el plan de igualdad, identificaci\u00f3n de las medidas prioritarias, e impulso del plan en la empresa, entre otras.<\/li>\n<\/ul>\n<ul>\n<li>El <strong>contenido de los planes de igualdad<\/strong>, que incluye el diagn\u00f3stico de la situaci\u00f3n, que deber\u00e1 incorpora cuestiones tales como el proceso de selecci\u00f3n y contrataci\u00f3n de personal, las condiciones d trabajo, retribuciones y la prevenci\u00f3n del acoso sexual y por raz\u00f3n de sexo, as\u00ed como un contenido m\u00ednimo del plan de igualdad, y medidas de correcci\u00f3n en caso de que el resultado del diagn\u00f3stico pusiera de manifiesto la infrarrepresentaci\u00f3n de personas de un sexo determinado en determinados puestos o niveles jer\u00e1rquicos. El plan de igualdad, que tendr\u00e1 un plazo m\u00e1ximo de cuatro a\u00f1os, deber\u00e1 contener una estructura concreta, as\u00ed como las medidas que resulten necesarias en virtud de los resultados del diagn\u00f3stico.<\/li>\n<\/ul>\n<ul>\n<li>Se llevar\u00e1 a cabo el <strong>registro de planes de igualdad <\/strong>de forma obligatoria, cualquiera que sea su origen o naturaleza, as\u00ed como un <strong>dep\u00f3sito de las medidas y protocolos para prevenir el acoso sexual y por raz\u00f3n de sexo<\/strong>.<\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><\/p>\n<p>En relaci\u00f3n con el <strong>Real Decreto 902\/2020<\/strong>, las novedades principales que se incorporan son:<\/p>\n<ul>\n<li>Su <strong>entrada en vigor<\/strong> el 14 de abril de 2021, y tendr\u00e1 por <strong>objeto<\/strong> establecer las medidas espec\u00edficas para hacer efectivo el derecho a la igualdad de trato y a la no discriminaci\u00f3n entre mujeres y hombres en materia retributiva, desarrollando los mecanismos para identificar y corregir la discriminaci\u00f3n en este \u00e1mbito y luchar contra la misma, de aplicaci\u00f3n en todas las relaciones laborales reguladas en el Estatuto de los Trabajadores.<\/li>\n<\/ul>\n<ul>\n<li>Se deber\u00e1 integrar el <strong>principio de transparencia retributiva<\/strong> con el fin de garantizar la aplicaci\u00f3n efectiva del principio de igualdad de trato y no discriminaci\u00f3n en materia retributiva entre mujeres y hombres, a trav\u00e9s de los registros retributivos, la auditoria retributiva y dem\u00e1s instrumentos regulados en el referido real decreto.<\/li>\n<\/ul>\n<ul>\n<li>En relaci\u00f3n con los instrumentos de transparencia retributiva, se incorporan, el <strong>registro retributivo<\/strong>, que deber\u00e1n tener todas las empresas respecto de la totalidad de su plantilla y deber\u00e1 incluir los valores medios de los salarios, los complementos salariales y las percepciones extrasalariales de la plantilla desagregados por sexo, y la <strong>auditoria retributiva<\/strong>, con el objeto de obtener la informaci\u00f3n necesaria para comprobar si el sistema retributivo de la empresa, de manera transversal y completa, cumple con la aplicaci\u00f3n efectiva del principio de igualdad entre mujeres y hombres en materia de retribuci\u00f3n.<\/li>\n<\/ul>\n<p>\u00a9 La presente informaci\u00f3n es propiedad de <strong>Escura<\/strong>, <strong>abogados<\/strong> y <strong>economistas<\/strong>, quedando prohibida su reproducci\u00f3n sin permiso expreso.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last banner\" style=\"--awb-padding-top:20px;--awb-padding-right:20px;--awb-padding-bottom:20px;--awb-padding-left:20px;--awb-bg-image:url(&#039;http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/area_recursos_humanosv2.jpg&#039;);--awb-bg-size:cover;--awb-margin-top:40px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy fusion-column-has-bg-image\" data-bg-url=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/area_recursos_humanosv2.jpg\"><div class=\"fusion-text fusion-text-2\"><h3><a href=\"https:\/\/www.escura.com\/es\/recursos-humanos\/\" target=\"_blank\" rel=\"noopener noreferrer\">Consulta nuestra \u00e1rea de <strong>Recursos Humanos<\/strong><\/a><\/h3>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[282,27],"tags":[],"class_list":["post-18225","post","type-post","status-publish","format-standard","hentry","category-plan-de-igualdad","category-recursos-humanos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Escura. Abogados y Economistas<\/title>\n<meta name=\"description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.35-181-91-225.plesk.page\/es\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novedades respecto al registro de planes de igualdad, y la igualdad retributiva entre hombres y mujeres\" \/>\n<meta property=\"og:description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.35-181-91-225.plesk.page\/es\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\/\" \/>\n<meta property=\"og:site_name\" content=\"Escura | Abogados y Economistas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/escura.abogados\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-10T16:49:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-26T15:52:26+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/CC0-139-150x150.jpg\" \/>\n<meta name=\"author\" content=\"escura\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:site\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"escura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.35-181-91-225.plesk.page\\\/es\\\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.35-181-91-225.plesk.page\\\/es\\\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\\\/\"},\"author\":{\"name\":\"escura\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/4edd59e125b9654539921a4ec1da53b1\"},\"headline\":\"Novedades respecto al registro de planes de igualdad, y la igualdad retributiva entre hombres y mujeres\",\"datePublished\":\"2020-12-10T16:49:37+00:00\",\"dateModified\":\"2022-10-26T15:52:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.35-181-91-225.plesk.page\\\/es\\\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\\\/\"},\"wordCount\":1029,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.35-181-91-225.plesk.page\\\/es\\\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/blog.escura.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/CC0-139-150x150.jpg\",\"articleSection\":[\"Plan de Igualdad\",\"Recursos Humanos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.35-181-91-225.plesk.page\\\/es\\\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.35-181-91-225.plesk.page\\\/es\\\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\\\/\",\"url\":\"https:\\\/\\\/www.35-181-91-225.plesk.page\\\/es\\\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\\\/\",\"name\":\"Escura. Abogados y Economistas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.35-181-91-225.plesk.page\\\/es\\\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.35-181-91-225.plesk.page\\\/es\\\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/blog.escura.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/CC0-139-150x150.jpg\",\"datePublished\":\"2020-12-10T16:49:37+00:00\",\"dateModified\":\"2022-10-26T15:52:26+00:00\",\"description\":\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.35-181-91-225.plesk.page\\\/es\\\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.35-181-91-225.plesk.page\\\/es\\\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.35-181-91-225.plesk.page\\\/es\\\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\\\/#primaryimage\",\"url\":\"http:\\\/\\\/blog.escura.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/CC0-139-150x150.jpg\",\"contentUrl\":\"http:\\\/\\\/blog.escura.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/CC0-139-150x150.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.35-181-91-225.plesk.page\\\/es\\\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novedades respecto al registro de planes de igualdad, y la igualdad retributiva entre hombres y mujeres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"name\":\"Escura | Abogados y Economistas\",\"description\":\"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.escura.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\",\"name\":\"Escura. Abogados y economistas\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Escura. Abogados y economistas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/escura.abogados\",\"https:\\\/\\\/x.com\\\/escura_abogados\",\"https:\\\/\\\/www.instagram.com\\\/escura_abogados\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bufete-escura\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BufeteEscura\\\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/4edd59e125b9654539921a4ec1da53b1\",\"name\":\"escura\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"caption\":\"escura\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Escura. Abogados y Economistas","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.35-181-91-225.plesk.page\/es\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\/","og_locale":"es_ES","og_type":"article","og_title":"Novedades respecto al registro de planes de igualdad, y la igualdad retributiva entre hombres y mujeres","og_description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","og_url":"https:\/\/www.35-181-91-225.plesk.page\/es\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\/","og_site_name":"Escura | Abogados y Economistas","article_publisher":"https:\/\/www.facebook.com\/escura.abogados","article_published_time":"2020-12-10T16:49:37+00:00","article_modified_time":"2022-10-26T15:52:26+00:00","og_image":[{"url":"http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/CC0-139-150x150.jpg","type":"","width":"","height":""}],"author":"escura","twitter_card":"summary_large_image","twitter_creator":"@escura_abogados","twitter_site":"@escura_abogados","twitter_misc":{"Escrito por":"escura","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.35-181-91-225.plesk.page\/es\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\/#article","isPartOf":{"@id":"https:\/\/www.35-181-91-225.plesk.page\/es\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\/"},"author":{"name":"escura","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/4edd59e125b9654539921a4ec1da53b1"},"headline":"Novedades respecto al registro de planes de igualdad, y la igualdad retributiva entre hombres y mujeres","datePublished":"2020-12-10T16:49:37+00:00","dateModified":"2022-10-26T15:52:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.35-181-91-225.plesk.page\/es\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\/"},"wordCount":1029,"commentCount":0,"publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"image":{"@id":"https:\/\/www.35-181-91-225.plesk.page\/es\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\/#primaryimage"},"thumbnailUrl":"http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/CC0-139-150x150.jpg","articleSection":["Plan de Igualdad","Recursos Humanos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.35-181-91-225.plesk.page\/es\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.35-181-91-225.plesk.page\/es\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\/","url":"https:\/\/www.35-181-91-225.plesk.page\/es\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\/","name":"Escura. Abogados y Economistas","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.35-181-91-225.plesk.page\/es\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\/#primaryimage"},"image":{"@id":"https:\/\/www.35-181-91-225.plesk.page\/es\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\/#primaryimage"},"thumbnailUrl":"http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/CC0-139-150x150.jpg","datePublished":"2020-12-10T16:49:37+00:00","dateModified":"2022-10-26T15:52:26+00:00","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","breadcrumb":{"@id":"https:\/\/www.35-181-91-225.plesk.page\/es\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.35-181-91-225.plesk.page\/es\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.35-181-91-225.plesk.page\/es\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\/#primaryimage","url":"http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/CC0-139-150x150.jpg","contentUrl":"http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/CC0-139-150x150.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.35-181-91-225.plesk.page\/es\/novedades-respecto-al-registro-de-planes-de-igualdad-y-la-igualdad-retributiva-entre-hombres-y-mujeres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.escura.com\/es\/"},{"@type":"ListItem","position":2,"name":"Novedades respecto al registro de planes de igualdad, y la igualdad retributiva entre hombres y mujeres"}]},{"@type":"WebSite","@id":"https:\/\/www.escura.com\/es\/#website","url":"https:\/\/www.escura.com\/es\/","name":"Escura | Abogados y Economistas","description":"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona","publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.escura.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.escura.com\/es\/#organization","name":"Escura. Abogados y economistas","url":"https:\/\/www.escura.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Escura. Abogados y economistas"},"image":{"@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/escura.abogados","https:\/\/x.com\/escura_abogados","https:\/\/www.instagram.com\/escura_abogados\/","https:\/\/www.linkedin.com\/company\/bufete-escura","https:\/\/www.youtube.com\/user\/BufeteEscura\/videos"]},{"@type":"Person","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/4edd59e125b9654539921a4ec1da53b1","name":"escura","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","caption":"escura"}}]}},"_links":{"self":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/18225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/comments?post=18225"}],"version-history":[{"count":1,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/18225\/revisions"}],"predecessor-version":[{"id":38914,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/18225\/revisions\/38914"}],"wp:attachment":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media?parent=18225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/categories?post=18225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/tags?post=18225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}