{"id":18059,"date":"2020-09-28T11:21:14","date_gmt":"2020-09-28T09:21:14","guid":{"rendered":"https:\/\/blog.escura.com\/?p=18059"},"modified":"2020-09-28T11:21:14","modified_gmt":"2020-09-28T09:21:14","slug":"devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre","status":"publish","type":"post","link":"https:\/\/www.escura.com\/es\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\/","title":{"rendered":"Devoluci\u00f3n del IVA soportado de pa\u00edses de la UE \u2013 Fin de plazo 30 de septiembre"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><h3 style=\"text-align: right;\"><a href=\"http:\/\/www.escura.com\/wp-content\/uploads\/2020\/09\/170-20-devolucion-del-IVA-soportado-paises-UE.pdf\">Consulte el PDF<\/a><\/h3>\n<p><strong><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-17951\" src=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/07\/Map_-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>ESCURA<\/strong> les informa sobre el <strong><u>procedimiento de devoluci\u00f3n del IVA soportado<\/u><\/strong> en otros Estados miembros de la UE por empresarios o profesionales establecidos en Espa\u00f1a.<\/p>\n<p>Los mencionados empresarios o profesionales que, en el ejercicio de su actividad empresarial o profesional, hayan soportado el IVA correspondiente a otro Estado miembro de la UE <u>disponen de un procedimiento espec\u00edfico para solicitar la devoluci\u00f3n del importe del impuesto<\/u>.<\/p>\n<p>El tr\u00e1mite para solicitar la devoluci\u00f3n se realiza a trav\u00e9s del <strong><u>modelo 360<\/u><\/strong>.<\/p>\n<p>El plazo para solicitar la devoluci\u00f3n de las cuotas soportadas durante el ejercicio 2019 finaliza el pr\u00f3ximo <strong><u>d\u00eda 30 de septiembre de 2020.<\/u><\/strong><\/p>\n<p><strong><u>No procede la presentaci\u00f3n de la solicitud<\/u><\/strong> cuando el solicitante:<\/p>\n<ul>\n<li>No tenga la condici\u00f3n de empresario o profesional.<\/li>\n<li>Haya realizado exclusivamente operaciones que no originan el derecho a la deducci\u00f3n.<\/li>\n<li>Realice exclusivamente operaciones que tributen por los reg\u00edmenes especiales de la agricultura, ganader\u00eda y pesca o del recargo de equivalencia.<\/li>\n<\/ul>\n<p>La presentaci\u00f3n del modelo se realiza, con car\u00e1cter obligatorio, <strong><u>por v\u00eda telem\u00e1tica<\/u><\/strong>.<\/p>\n<p>Se adjunta a trav\u00e9s del siguiente enlace la orden EHA\/789\/2010, de 16 de marzo, por la que se aprueba el modelo 360: <a href=\"http:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2010-5210\">http:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2010-5210<\/a><\/p>\n<p>\u00a9 La presente informaci\u00f3n es propiedad de <strong>Escura<\/strong>, <strong>abogados<\/strong> y <strong>economistas<\/strong>, quedando prohibida su reproducci\u00f3n sin permiso expreso.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last banner\" style=\"--awb-padding-top:20px;--awb-padding-right:20px;--awb-padding-bottom:20px;--awb-padding-left:20px;--awb-bg-image:url(&#039;http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/area_economico_fiscal.jpg&#039;);--awb-bg-size:cover;--awb-margin-top:40px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy fusion-column-has-bg-image\" data-bg-url=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/area_economico_fiscal.jpg\"><div class=\"fusion-text fusion-text-2\"><h3><a href=\"https:\/\/www.escura.com\/es\/economico-fiscal\/\" target=\"_blank\" rel=\"noopener noreferrer\">Consulta nuestra \u00e1rea de <strong>Econ\u00f3mico Fiscal<\/strong><\/a><\/h3>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":28307,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-18059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiscal-contable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Escura. Abogados y Economistas<\/title>\n<meta name=\"description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.escura.com\/es\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Devoluci\u00f3n del IVA soportado de pa\u00edses de la UE \u2013 Fin de plazo 30 de septiembre\" \/>\n<meta property=\"og:description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.escura.com\/es\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Escura | Abogados y Economistas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/escura.abogados\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-28T09:21:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/07\/Map_-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"903\" \/>\n\t<meta property=\"og:image:height\" content=\"424\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"escura\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:site\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"escura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\\\/\"},\"author\":{\"name\":\"escura\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/4edd59e125b9654539921a4ec1da53b1\"},\"headline\":\"Devoluci\u00f3n del IVA soportado de pa\u00edses de la UE \u2013 Fin de plazo 30 de septiembre\",\"datePublished\":\"2020-09-28T09:21:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\\\/\"},\"wordCount\":605,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Map_-1.jpg\",\"articleSection\":[\"Fiscal - Contable\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\\\/\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\\\/\",\"name\":\"Escura. Abogados y Economistas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Map_-1.jpg\",\"datePublished\":\"2020-09-28T09:21:14+00:00\",\"description\":\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Map_-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Map_-1.jpg\",\"width\":903,\"height\":424},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Devoluci\u00f3n del IVA soportado de pa\u00edses de la UE \u2013 Fin de plazo 30 de septiembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"name\":\"Escura | Abogados y Economistas\",\"description\":\"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.escura.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\",\"name\":\"Escura. Abogados y economistas\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Escura. Abogados y economistas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/escura.abogados\",\"https:\\\/\\\/x.com\\\/escura_abogados\",\"https:\\\/\\\/www.instagram.com\\\/escura_abogados\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bufete-escura\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BufeteEscura\\\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/4edd59e125b9654539921a4ec1da53b1\",\"name\":\"escura\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"caption\":\"escura\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Escura. Abogados y Economistas","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.escura.com\/es\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\/","og_locale":"es_ES","og_type":"article","og_title":"Devoluci\u00f3n del IVA soportado de pa\u00edses de la UE \u2013 Fin de plazo 30 de septiembre","og_description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","og_url":"https:\/\/www.escura.com\/es\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\/","og_site_name":"Escura | Abogados y Economistas","article_publisher":"https:\/\/www.facebook.com\/escura.abogados","article_published_time":"2020-09-28T09:21:14+00:00","og_image":[{"width":903,"height":424,"url":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/07\/Map_-1.jpg","type":"image\/jpeg"}],"author":"escura","twitter_card":"summary_large_image","twitter_creator":"@escura_abogados","twitter_site":"@escura_abogados","twitter_misc":{"Escrito por":"escura","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.escura.com\/es\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\/#article","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\/"},"author":{"name":"escura","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/4edd59e125b9654539921a4ec1da53b1"},"headline":"Devoluci\u00f3n del IVA soportado de pa\u00edses de la UE \u2013 Fin de plazo 30 de septiembre","datePublished":"2020-09-28T09:21:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.escura.com\/es\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\/"},"wordCount":605,"commentCount":0,"publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"image":{"@id":"https:\/\/www.escura.com\/es\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/07\/Map_-1.jpg","articleSection":["Fiscal - Contable"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.escura.com\/es\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.escura.com\/es\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\/","url":"https:\/\/www.escura.com\/es\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\/","name":"Escura. Abogados y Economistas","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.escura.com\/es\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\/#primaryimage"},"image":{"@id":"https:\/\/www.escura.com\/es\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/07\/Map_-1.jpg","datePublished":"2020-09-28T09:21:14+00:00","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","breadcrumb":{"@id":"https:\/\/www.escura.com\/es\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.escura.com\/es\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\/#primaryimage","url":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/07\/Map_-1.jpg","contentUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/07\/Map_-1.jpg","width":903,"height":424},{"@type":"BreadcrumbList","@id":"https:\/\/www.escura.com\/es\/devolucion-del-iva-soportado-de-paises-de-la-ue-fin-de-plazo-30-de-septiembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.escura.com\/es\/"},{"@type":"ListItem","position":2,"name":"Devoluci\u00f3n del IVA soportado de pa\u00edses de la UE \u2013 Fin de plazo 30 de septiembre"}]},{"@type":"WebSite","@id":"https:\/\/www.escura.com\/es\/#website","url":"https:\/\/www.escura.com\/es\/","name":"Escura | Abogados y Economistas","description":"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona","publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.escura.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.escura.com\/es\/#organization","name":"Escura. Abogados y economistas","url":"https:\/\/www.escura.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Escura. Abogados y economistas"},"image":{"@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/escura.abogados","https:\/\/x.com\/escura_abogados","https:\/\/www.instagram.com\/escura_abogados\/","https:\/\/www.linkedin.com\/company\/bufete-escura","https:\/\/www.youtube.com\/user\/BufeteEscura\/videos"]},{"@type":"Person","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/4edd59e125b9654539921a4ec1da53b1","name":"escura","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","caption":"escura"}}]}},"_links":{"self":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/18059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/comments?post=18059"}],"version-history":[{"count":0,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/18059\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media\/28307"}],"wp:attachment":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media?parent=18059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/categories?post=18059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/tags?post=18059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}