{"id":17864,"date":"2020-06-15T11:04:44","date_gmt":"2020-06-15T09:04:44","guid":{"rendered":"https:\/\/blog.escura.com\/?p=17864"},"modified":"2020-06-15T11:04:44","modified_gmt":"2020-06-15T09:04:44","slug":"procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2","status":"publish","type":"post","link":"https:\/\/www.escura.com\/es\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\/","title":{"rendered":"Procedimiento de actuaci\u00f3n para los servicios de prevenci\u00f3n de riesgos laborales frente a la exposici\u00f3n al SARS-CoV-2"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><h3 style=\"text-align: right;\"><a href=\"http:\/\/www.escura.com\/wp-content\/uploads\/2020\/06\/131-20-procedimiento-actuacion-para-servicios-prevencion-riesgos-laborales-frente-a-exposicion-covid.pdf\">Consulte el PDF<\/a><\/h3>\n<p><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-17865\" src=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/06\/CC0-482-min-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>El Ministerio de Sanidad ha publicado una gu\u00eda con fecha 8 de junio del 2020 en relaci\u00f3n con los procedimientos de actuaci\u00f3n para los servicios de prevenci\u00f3n de riesgos laborales frente a la exposici\u00f3n al SARS-CoV-2.<\/p>\n<p>La reincorporaci\u00f3n de los trabajadores a sus centros de trabajo en el marco del plan de desconfinamiento motiva la especial relevancia de los servicios de prevenci\u00f3n y la adopci\u00f3n de las medidas preventivas.<\/p>\n<p>Como establece la propia gu\u00eda, cualquier toma de decisi\u00f3n sobre las medidas preventivas a adoptar en cada empresa deber\u00e1 basarse en informaci\u00f3n recabada mediante la evaluaci\u00f3n de riesgo de exposici\u00f3n espec\u00edfica que se realizar\u00e1 siempre en consonancia con la informaci\u00f3n aportada por las autoridades sanitarias.<\/p>\n<p>Resaltar que la gu\u00eda anexa modelos de declaraciones pr\u00e1cticos. Puede consultar la integridad del texto en el siguiente enlace:<\/p>\n<p><a href=\"https:\/\/www.mscbs.gob.es\/profesionales\/saludPublica\/ccayes\/alertasActual\/nCov-China\/documentos\/PrevencionRRLL_COVID-19.pdf\">https:\/\/www.mscbs.gob.es\/profesionales\/saludPublica\/ccayes\/alertasActual\/nCov-China\/documentos\/PrevencionRRLL_COVID-19.pdf<\/a><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong><u>Destacamos los siguientes apartados de la gu\u00eda:<\/u><\/strong><\/p>\n<p>Medidas de car\u00e1cter organizativo<\/p>\n<p>Medidas de protecci\u00f3n colectiva<\/p>\n<p>Medidas de protecci\u00f3n personal<\/p>\n<p><strong>TRABAJADOR ESPECIALMENTE SENSIBLE<\/strong><\/p>\n<p><strong>DETECCI\u00d3N, NOTIFICACI\u00d3N, ESTUDIO Y MANEJO DE CASOS Y CONTACTOS<\/strong><\/p>\n<p>Detecci\u00f3n<\/p>\n<p>Clasificaci\u00f3n de los casos<\/p>\n<p>Notificaci\u00f3n de casos<\/p>\n<p>Manejo de los casos de COVID\u201019<\/p>\n<p>Estudio y manejo de contactos<\/p>\n<p><strong>COLABORACI\u00d3N EN LA GESTI\u00d3N DE LA INCAPACIDAD TEMPORAL<\/strong><\/p>\n<p><strong>MODELOS DE INFORMES<\/strong><\/p>\n<p>Caso sospechoso, confirmado o contacto estrecho<\/p>\n<p>Especial sensibilidad. Necesidad de IT<\/p>\n<p>Especial sensibilidad. No hay necesidad de IT<\/p>\n<p><strong>EQUIPO DE PROTECCI\u00d3N INDIVIDUAL (EPI)<\/strong><\/p>\n<p>Protecci\u00f3n respiratoria<\/p>\n<p>Guantes y ropa de protecci\u00f3n<\/p>\n<p>Guantes de protecci\u00f3n<\/p>\n<p>Ropa de protecci\u00f3n<\/p>\n<p>Protecci\u00f3n ocular y facial<\/p>\n<p>Colocaci\u00f3n y retirada de los EPI<\/p>\n<p>Desecho o descontaminaci\u00f3n<\/p>\n<p>Almacenaje y mantenimiento<\/p>\n<p><strong>GU\u00cdA PARA PROTECCI\u00d3N PERSONAL <\/strong><\/p>\n<p><strong>GU\u00cdA DE ACTUACI\u00d3N PARA LA GESTI\u00d3N DE LA VULNERABILIDAD Y EL RIESGO EN EL<\/strong><\/p>\n<p><strong>\u00c1MBITO SANITARIO Y SOCIOSANITARIO<\/strong><\/p>\n<p><strong>GU\u00cdA DE ACTUACI\u00d3N PARA LA GESTI\u00d3N DE LA VULNERABILIDAD Y EL RIESGO EN <\/strong><strong>\u00c1MBITOS NO SANITARIOS O SOCIOSANITARIOS <\/strong><\/p>\n<p>\u00a9 La presente informaci\u00f3n es propiedad de <strong>Escura<\/strong>, <strong>abogados<\/strong> y <strong>economistas<\/strong>, quedando prohibida su reproducci\u00f3n sin permiso expreso.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last banner\" style=\"--awb-padding-top:20px;--awb-padding-right:20px;--awb-padding-bottom:20px;--awb-padding-left:20px;--awb-bg-image:url(&#039;http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/area_recursos_humanosv2.jpg&#039;);--awb-bg-size:cover;--awb-margin-top:40px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy fusion-column-has-bg-image\" data-bg-url=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/area_recursos_humanosv2.jpg\"><div class=\"fusion-text fusion-text-2\"><h3><a href=\"https:\/\/www.escura.com\/es\/recursos-humanos\/\" target=\"_blank\" rel=\"noopener noreferrer\">Consulta nuestra \u00e1rea de <strong>Recursos Humanos<\/strong><\/a><\/h3>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-17864","post","type-post","status-publish","format-standard","hentry","category-recursos-humanos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Escura. Abogados y Economistas<\/title>\n<meta name=\"description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.escura.com\/es\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Procedimiento de actuaci\u00f3n para los servicios de prevenci\u00f3n de riesgos laborales frente a la exposici\u00f3n al SARS-CoV-2\" \/>\n<meta property=\"og:description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.escura.com\/es\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Escura | Abogados y Economistas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/escura.abogados\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-15T09:04:44+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/06\/CC0-482-min-150x150.jpg\" \/>\n<meta name=\"author\" content=\"escura\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:site\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"escura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\\\/\"},\"author\":{\"name\":\"escura\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/4edd59e125b9654539921a4ec1da53b1\"},\"headline\":\"Procedimiento de actuaci\u00f3n para los servicios de prevenci\u00f3n de riesgos laborales frente a la exposici\u00f3n al SARS-CoV-2\",\"datePublished\":\"2020-06-15T09:04:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\\\/\"},\"wordCount\":687,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/blog.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/CC0-482-min-150x150.jpg\",\"articleSection\":[\"Recursos Humanos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\\\/\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\\\/\",\"name\":\"Escura. Abogados y Economistas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/blog.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/CC0-482-min-150x150.jpg\",\"datePublished\":\"2020-06-15T09:04:44+00:00\",\"description\":\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\\\/#primaryimage\",\"url\":\"http:\\\/\\\/blog.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/CC0-482-min-150x150.jpg\",\"contentUrl\":\"http:\\\/\\\/blog.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/CC0-482-min-150x150.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Procedimiento de actuaci\u00f3n para los servicios de prevenci\u00f3n de riesgos laborales frente a la exposici\u00f3n al SARS-CoV-2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"name\":\"Escura | Abogados y Economistas\",\"description\":\"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.escura.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\",\"name\":\"Escura. Abogados y economistas\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Escura. Abogados y economistas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/escura.abogados\",\"https:\\\/\\\/x.com\\\/escura_abogados\",\"https:\\\/\\\/www.instagram.com\\\/escura_abogados\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bufete-escura\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BufeteEscura\\\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/4edd59e125b9654539921a4ec1da53b1\",\"name\":\"escura\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"caption\":\"escura\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Escura. Abogados y Economistas","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.escura.com\/es\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\/","og_locale":"es_ES","og_type":"article","og_title":"Procedimiento de actuaci\u00f3n para los servicios de prevenci\u00f3n de riesgos laborales frente a la exposici\u00f3n al SARS-CoV-2","og_description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","og_url":"https:\/\/www.escura.com\/es\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\/","og_site_name":"Escura | Abogados y Economistas","article_publisher":"https:\/\/www.facebook.com\/escura.abogados","article_published_time":"2020-06-15T09:04:44+00:00","og_image":[{"url":"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/06\/CC0-482-min-150x150.jpg","type":"","width":"","height":""}],"author":"escura","twitter_card":"summary_large_image","twitter_creator":"@escura_abogados","twitter_site":"@escura_abogados","twitter_misc":{"Escrito por":"escura","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.escura.com\/es\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\/#article","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\/"},"author":{"name":"escura","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/4edd59e125b9654539921a4ec1da53b1"},"headline":"Procedimiento de actuaci\u00f3n para los servicios de prevenci\u00f3n de riesgos laborales frente a la exposici\u00f3n al SARS-CoV-2","datePublished":"2020-06-15T09:04:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.escura.com\/es\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\/"},"wordCount":687,"commentCount":0,"publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"image":{"@id":"https:\/\/www.escura.com\/es\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\/#primaryimage"},"thumbnailUrl":"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/06\/CC0-482-min-150x150.jpg","articleSection":["Recursos Humanos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.escura.com\/es\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.escura.com\/es\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\/","url":"https:\/\/www.escura.com\/es\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\/","name":"Escura. Abogados y Economistas","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.escura.com\/es\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\/#primaryimage"},"image":{"@id":"https:\/\/www.escura.com\/es\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\/#primaryimage"},"thumbnailUrl":"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/06\/CC0-482-min-150x150.jpg","datePublished":"2020-06-15T09:04:44+00:00","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","breadcrumb":{"@id":"https:\/\/www.escura.com\/es\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.escura.com\/es\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\/#primaryimage","url":"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/06\/CC0-482-min-150x150.jpg","contentUrl":"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/06\/CC0-482-min-150x150.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.escura.com\/es\/procedimiento-de-actuacion-para-los-servicios-de-prevencion-de-riesgos-laborales-frente-a-la-exposicion-al-sars-cov-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.escura.com\/es\/"},{"@type":"ListItem","position":2,"name":"Procedimiento de actuaci\u00f3n para los servicios de prevenci\u00f3n de riesgos laborales frente a la exposici\u00f3n al SARS-CoV-2"}]},{"@type":"WebSite","@id":"https:\/\/www.escura.com\/es\/#website","url":"https:\/\/www.escura.com\/es\/","name":"Escura | Abogados y Economistas","description":"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona","publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.escura.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.escura.com\/es\/#organization","name":"Escura. Abogados y economistas","url":"https:\/\/www.escura.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Escura. Abogados y economistas"},"image":{"@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/escura.abogados","https:\/\/x.com\/escura_abogados","https:\/\/www.instagram.com\/escura_abogados\/","https:\/\/www.linkedin.com\/company\/bufete-escura","https:\/\/www.youtube.com\/user\/BufeteEscura\/videos"]},{"@type":"Person","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/4edd59e125b9654539921a4ec1da53b1","name":"escura","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","caption":"escura"}}]}},"_links":{"self":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/17864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/comments?post=17864"}],"version-history":[{"count":0,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/17864\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media?parent=17864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/categories?post=17864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/tags?post=17864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}