{"id":17832,"date":"2020-05-29T14:37:08","date_gmt":"2020-05-29T12:37:08","guid":{"rendered":"https:\/\/blog.escura.com\/?p=17832"},"modified":"2020-05-29T14:37:08","modified_gmt":"2020-05-29T12:37:08","slug":"que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor","status":"publish","type":"post","link":"https:\/\/www.escura.com\/es\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\/","title":{"rendered":"\u00bfQu\u00e9 medidas puedo implantar cuando finalice el ERTE por fuerza mayor?"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><h3 style=\"text-align: right;\"><a href=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/05\/124-20-medidas-a-implantar-cuando-finalice-ERTE-fuerza-mayor.pdf\">Consulte el PDF<\/a><\/h3>\n<p><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-17073\" src=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/11\/CC0-417-min-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>El levantamiento progresivo del Estado de Alarma est\u00e1 generando incertidumbre en aquellas empresas que se encontraban en situaci\u00f3n de ERTE por Fuerza Mayor, respecto a las medidas a las que pueden optar para poder llevar a cabo aquellas reestructuraciones de plantillas necesarias que les permita ajustarse a las exigencias de la nueva realidad empresarial, entre las que encontramos:<\/p>\n<ul>\n<li><strong>Expediente de Regulaci\u00f3n Temporal de Empleo por causas econ\u00f3micas, t\u00e9cnicas, organizativas o de producci\u00f3n (ERTE ETOP)<\/strong><strong>: <\/strong>Esta ser\u00e1, sin duda alguna, la medida estrella. De acuerdo con el art\u00edculo 47 del Estatuto de los Trabajadores, el empresario podr\u00e1 suspender el contrato de trabajo por causas econ\u00f3micas, t\u00e9cnicas, organizativas o de producci\u00f3n. Este mecanismo legal permite a la suspender o reducir la jornada de un n\u00famero indeterminado de contratos de forma temporal y en tanto persista la situaci\u00f3n coyuntural de la empresa. Durante el periodo de reducci\u00f3n de jornada o de suspensi\u00f3n, la empresa estar\u00e1 exenta de abonar los salarios en proporci\u00f3n a la jornada suspendida, si bien deber\u00e1 mantener el importe correspondiente a la cuota empresarial de seguridad social.<\/li>\n<\/ul>\n<ul>\n<li><strong>Modificaci\u00f3n substancial de las condiciones de trabajo: <\/strong>La empresa podr\u00e1, en virtud del art\u00edculo 41 del Estatuto de los Trabajadores, acordar modificaciones sustanciales de las condiciones de trabajo cuando existan probadas razones econ\u00f3micas, t\u00e9cnicas, organizativas o de producci\u00f3n. Tendr\u00e1n la consideraci\u00f3n de modificaciones sustanciales de las condiciones de trabajo, entre otras, las que afecten a las siguientes materias: ornada de trabajo, Horario y distribuci\u00f3n del tiempo de trabajo, R\u00e9gimen de trabajo a turnos, Sistema de remuneraci\u00f3n y cuant\u00eda salarial.<\/li>\n<\/ul>\n<ul>\n<li><strong>Vacaciones:<\/strong> Si bien las empresas no pueden imponer a sus trabajadores vacaciones durante el estado de alarma, ya que, en este caso, no existir\u00eda mutuo acuerdo y adem\u00e1s tampoco se estar\u00edan notificando estas con los 2 meses de antelaci\u00f3n a los que hace menci\u00f3n el art\u00edculo 38 del Estatuto de los Trabajadores, hay empresas que est\u00e1n llegando a acuerdos con sus trabajadores para que disfruten de algunos d\u00edas de vacaciones y, de esta manera, evitar tener que ir a un ERTE, donde el trabajador ver\u00eda mermados sus ingresos y tambi\u00e9n perder\u00eda algunos d\u00edas de vacaciones.<\/li>\n<\/ul>\n<ul>\n<li><strong>Distribuci\u00f3n irregular de la jornada: <\/strong>Siguiendo la redacci\u00f3n del art\u00edculo 34.2 del Estatuto de los Trabajadores, mediante convenio colectivo o, en su defecto, por acuerdo entre la empresa y los representantes de los trabajadores, se podr\u00e1 establecer la distribuci\u00f3n irregular de la jornada a lo largo del a\u00f1o. En defecto de pacto, la empresa podr\u00e1 distribuir de manera irregular a lo largo del a\u00f1o el diez por ciento de la jornada de trabajo.<\/li>\n<\/ul>\n<ul>\n<li><strong>Permiso Retribuido Recuperable:<\/strong> El Real Decreto 10\/2020 nos aport\u00f3 el permiso retribuido recuperable obligatorio como herramienta para solventar temporalmente la situaci\u00f3n de crisis extraordinaria que vivimos hace unos meses y seguimos acarreando. En este sentido, las empresas pueden, mediante acuerdo individual, pactar un permiso retribuido recuperable en defecto de las medidas anteriores.<\/li>\n<\/ul>\n<p>\u00a9 La presente informaci\u00f3n es propiedad de <strong>Escura<\/strong>, <strong>abogados<\/strong> y <strong>economistas<\/strong>, quedando prohibida su reproducci\u00f3n sin permiso expreso.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last banner\" style=\"--awb-padding-top:20px;--awb-padding-right:20px;--awb-padding-bottom:20px;--awb-padding-left:20px;--awb-bg-image:url(&#039;http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/area_recursos_humanosv2.jpg&#039;);--awb-bg-size:cover;--awb-margin-top:40px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy fusion-column-has-bg-image\" data-bg-url=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2019\/03\/area_recursos_humanosv2.jpg\"><div class=\"fusion-text fusion-text-2\"><h3><a href=\"https:\/\/www.escura.com\/es\/recursos-humanos\/\" target=\"_blank\" rel=\"noopener noreferrer\">Consulta nuestra \u00e1rea de <strong>Recursos Humanos<\/strong><\/a><\/h3>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":28515,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-17832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recursos-humanos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Escura. Abogados y Economistas<\/title>\n<meta name=\"description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.escura.com\/es\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 medidas puedo implantar cuando finalice el ERTE por fuerza mayor?\" \/>\n<meta property=\"og:description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.escura.com\/es\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\/\" \/>\n<meta property=\"og:site_name\" content=\"Escura | Abogados y Economistas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/escura.abogados\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-29T12:37:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.escura.com\/wp-content\/uploads\/2019\/11\/CC0-417-min.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"escura\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:site\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"escura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\\\/\"},\"author\":{\"name\":\"escura\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/4edd59e125b9654539921a4ec1da53b1\"},\"headline\":\"\u00bfQu\u00e9 medidas puedo implantar cuando finalice el ERTE por fuerza mayor?\",\"datePublished\":\"2020-05-29T12:37:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\\\/\"},\"wordCount\":850,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/CC0-417-min.jpg\",\"articleSection\":[\"Recursos Humanos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\\\/\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\\\/\",\"name\":\"Escura. Abogados y Economistas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/CC0-417-min.jpg\",\"datePublished\":\"2020-05-29T12:37:08+00:00\",\"description\":\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/CC0-417-min.jpg\",\"contentUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/CC0-417-min.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 medidas puedo implantar cuando finalice el ERTE por fuerza mayor?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"name\":\"Escura | Abogados y Economistas\",\"description\":\"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.escura.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\",\"name\":\"Escura. Abogados y economistas\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Escura. Abogados y economistas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/escura.abogados\",\"https:\\\/\\\/x.com\\\/escura_abogados\",\"https:\\\/\\\/www.instagram.com\\\/escura_abogados\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bufete-escura\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BufeteEscura\\\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/4edd59e125b9654539921a4ec1da53b1\",\"name\":\"escura\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"caption\":\"escura\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Escura. Abogados y Economistas","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.escura.com\/es\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 medidas puedo implantar cuando finalice el ERTE por fuerza mayor?","og_description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","og_url":"https:\/\/www.escura.com\/es\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\/","og_site_name":"Escura | Abogados y Economistas","article_publisher":"https:\/\/www.facebook.com\/escura.abogados","article_published_time":"2020-05-29T12:37:08+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.escura.com\/wp-content\/uploads\/2019\/11\/CC0-417-min.jpg","type":"image\/jpeg"}],"author":"escura","twitter_card":"summary_large_image","twitter_creator":"@escura_abogados","twitter_site":"@escura_abogados","twitter_misc":{"Escrito por":"escura","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.escura.com\/es\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\/#article","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\/"},"author":{"name":"escura","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/4edd59e125b9654539921a4ec1da53b1"},"headline":"\u00bfQu\u00e9 medidas puedo implantar cuando finalice el ERTE por fuerza mayor?","datePublished":"2020-05-29T12:37:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.escura.com\/es\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\/"},"wordCount":850,"commentCount":0,"publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"image":{"@id":"https:\/\/www.escura.com\/es\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2019\/11\/CC0-417-min.jpg","articleSection":["Recursos Humanos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.escura.com\/es\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.escura.com\/es\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\/","url":"https:\/\/www.escura.com\/es\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\/","name":"Escura. Abogados y Economistas","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.escura.com\/es\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\/#primaryimage"},"image":{"@id":"https:\/\/www.escura.com\/es\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2019\/11\/CC0-417-min.jpg","datePublished":"2020-05-29T12:37:08+00:00","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","breadcrumb":{"@id":"https:\/\/www.escura.com\/es\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.escura.com\/es\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\/#primaryimage","url":"https:\/\/www.escura.com\/wp-content\/uploads\/2019\/11\/CC0-417-min.jpg","contentUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2019\/11\/CC0-417-min.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/www.escura.com\/es\/que-medidas-puedo-implantar-cuando-finalice-el-erte-por-fuerza-mayor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.escura.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 medidas puedo implantar cuando finalice el ERTE por fuerza mayor?"}]},{"@type":"WebSite","@id":"https:\/\/www.escura.com\/es\/#website","url":"https:\/\/www.escura.com\/es\/","name":"Escura | Abogados y Economistas","description":"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona","publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.escura.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.escura.com\/es\/#organization","name":"Escura. Abogados y economistas","url":"https:\/\/www.escura.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Escura. Abogados y economistas"},"image":{"@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/escura.abogados","https:\/\/x.com\/escura_abogados","https:\/\/www.instagram.com\/escura_abogados\/","https:\/\/www.linkedin.com\/company\/bufete-escura","https:\/\/www.youtube.com\/user\/BufeteEscura\/videos"]},{"@type":"Person","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/4edd59e125b9654539921a4ec1da53b1","name":"escura","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","caption":"escura"}}]}},"_links":{"self":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/17832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/comments?post=17832"}],"version-history":[{"count":0,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/17832\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media\/28515"}],"wp:attachment":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media?parent=17832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/categories?post=17832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/tags?post=17832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}