{"id":17386,"date":"2020-03-15T12:57:43","date_gmt":"2020-03-15T11:57:43","guid":{"rendered":"https:\/\/blog.escura.com\/?p=17386"},"modified":"2020-03-15T12:57:43","modified_gmt":"2020-03-15T11:57:43","slug":"estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas","status":"publish","type":"post","link":"https:\/\/www.escura.com\/es\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\/","title":{"rendered":"Estado de alarma \u2013 principales resoluciones, acuerdos, anuncios y comunicados emitidos por las diversas autoridades de las diferentes Comunidades Aut\u00f3nomas y Ciudades Aut\u00f3nomas"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><h3 style=\"text-align: right;\"><a href=\"http:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/40-20-principales-comunicados-emitidos-por-comunidades-autonomas.pdf\">Consulte el PDF<\/a><\/h3>\n<p><strong><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-17387\" src=\"http:\/\/blog.escura.com\/wp-content\/uploads\/2020\/03\/madrid-2-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>\u25aa Andaluc\u00eda:<\/strong><\/p>\n<p><a href=\"https:\/\/www.juntadeandalucia.es\/boja\/2020\/506\/s1\">Orden de 13 de marzo de 2020, por la que se adoptan medidas preventivas de salud p\u00fablica en la Comunidad de Andaluc\u00eda como consecuencia de la situaci\u00f3n y evoluci\u00f3n del coronavirus (COVID-19).<\/a><\/p>\n<p><a href=\"https:\/\/www.juntadeandalucia.es\/boja\/2020\/506\/s1\">Acuerdo de 13 de marzo de 2020, del Consejo de Gobierno, por el que se toma en consideraci\u00f3n la aplicaci\u00f3n en el Sistema Universitario Andaluz de las medidas preventivas de salud p\u00fablica, desde el d\u00eda 16 al 30 de marzo de 2020, en cumplimiento de lo previsto en la Orden del Consejero de Salud y Familias en esta materia.<\/a><\/p>\n<p><strong>\u25aa Arag\u00f3n:<\/strong><\/p>\n<p><a href=\"http:\/\/www.boa.aragon.es\/cgi-bin\/EBOA\/BRSCGI?CMD=VERDOC&amp;BASE=BOLE&amp;PIECE=BOLE&amp;DOCS=1-34&amp;DOCR=34&amp;SEC=FIRMA&amp;RNG=200&amp;SEPARADOR=&amp;&amp;PUBL=20200313\">Orden SAN\/207\/2020, de 13 de marzo, de la Consejera de Sanidad, por la que se adoptan medidas preventivas y recomendaciones de salud p\u00fablica en la Comunidad Aut\u00f3noma de Arag\u00f3n por la situaci\u00f3n y evoluci\u00f3n del COVID-19.<\/a><\/p>\n<p><strong>\u25aa Asturias:<\/strong><\/p>\n<p><a href=\"https:\/\/sedemovil.asturias.es\/bopa\/2020\/03\/13\/20200313Su4.pdf\">Resoluci\u00f3n de 13 de marzo de 2020, de la Consejer\u00eda de Salud, por la que se adoptan medidas en materia de salud p\u00fablica en relaci\u00f3n con espect\u00e1culos p\u00fablicos, actividades recreativas, establecimientos, locales e instalaciones del Principado de Asturias.<\/a><\/p>\n<p><strong>\u25aa Catalu\u00f1a:<\/strong><\/p>\n<p><a href=\"https:\/\/portaljuridic.gencat.cat\/eli\/es-ct\/dl\/2020\/03\/12\/6\">Decret Llei 6\/2020, de 12 de mar\u00e7, de mesures urgents en mat\u00e8ria assistencial, pressupost\u00e0ria, financera, fiscal i de contractaci\u00f3 p\u00fablica, per tal de pal\u00b7liar els efectes de la pand\u00e8mia generada pel coronavirus SARS-CoV-2.<\/a><\/p>\n<p><a href=\"https:\/\/dogc.gencat.cat\/ca\/pdogc_canals_interns\/pdogc_resultats_fitxa\/?action=fitxa&amp;documentId=870691&amp;language=ca_ES\">Resoluci\u00f3 SLT\/737\/2020, de 13 de mar\u00e7, per la qual s&#8217;adopten mesures complement\u00e0ries per a la prevenci\u00f3 i el control de la infecci\u00f3 pel SARS-CoV-2 S.<\/a><\/p>\n<p><a href=\"https:\/\/portaldogc.gencat.cat\/utilsEADOP\/PDF\/8084A\/1789151.pdf\">Resoluci\u00f3 SLT\/720\/2020, de 13 de mar\u00e7, per la qual s&#8217;adopten noves mesures addicionals per a la prevenci\u00f3 i el control de la infecci\u00f3 pel SARS-CoV-2.<\/a><\/p>\n<p><a href=\"https:\/\/portaldogc.gencat.cat\/utilsEADOP\/PDF\/8083A\/1788965.pdf\">Resoluci\u00f3 SLT\/719\/2020, de 12 de mar\u00e7, per la qual s&#8217;adopten mesures addicionals per a la prevenci\u00f3 i el control de la infecci\u00f3 pel SARS-CoV-2.<\/a><\/p>\n<p><a href=\"https:\/\/portaldogc.gencat.cat\/utilsEADOP\/PDF\/8082A\/1788517.pdf\">Resoluci\u00f3 SLT\/704\/2020, d&#8217;11 de mar\u00e7, per la qual s&#8217;adopten mesures de distanciament social en relaci\u00f3 amb els esdeveniments multitudinaris per a la prevenci\u00f3 i el control de la infecci\u00f3 pel SARS-CoV-2.<\/a><\/p>\n<p><strong>\u25aa Cantabria:<\/strong><\/p>\n<p><a href=\"https:\/\/boc.cantabria.es\/boces\/verAnuncioAction.do?idAnuBlob=349011\">Resoluci\u00f3n, de 13 de marzo de 2020, del Consejero de Sanidad, por la que se adoptan medidas preventivas en la Comunidad Aut\u00f3noma de Cantabria como consecuencia de la evoluci\u00f3n epidemiol\u00f3gica del coronavirus (COVID-19).<\/a><\/p>\n<p><strong>\u25aa Castilla La Mancha:<\/strong><\/p>\n<p><a href=\"https:\/\/docm.castillalamancha.es\/portaldocm\/descargarArchivo.do?ruta=2020\/03\/13\/pdf\/2020_2290.pdf&amp;tipo=rutaDocm\">Decreto 8\/2020, de 12 de marzo, del Presidente de la Junta de Comunidades, sobre medidas extraordinarias a adoptar con motivo del coronavirus (SARS-CoV-2).<\/a><\/p>\n<p><strong>\u25aa Castilla y Le\u00f3n:<\/strong><\/p>\n<p><a href=\"http:\/\/bocyl.jcyl.es\/boletines\/2020\/03\/13\/pdf\/BOCYL-D-13032020-1.pdf\">Acuerdo 9\/2020, de 12 de marzo, de la Junta de Castilla y Le\u00f3n, sobre medidas a adoptar en los centros de trabajo dependientes de la Administraci\u00f3n de la Comunidad Aut\u00f3noma con motivo del COVID-19.<\/a><\/p>\n<p><a href=\"http:\/\/bocyl.jcyl.es\/boletines\/2020\/03\/14\/pdf\/BOCYL-D-14032020-1.pdf\">Correcci\u00f3n de errores del Acuerdo 9\/2020, de 11 de marzo, de la Junta de Castilla y Le\u00f3n, sobre medidas a adoptar en los centros de trabajo dependientes de la Administraci\u00f3n de la Comunidad Aut\u00f3noma con motivo del COVID-19.<\/a><\/p>\n<p><a href=\"http:\/\/bocyl.jcyl.es\/boletines\/2020\/03\/14\/pdf\/BOCYL-D-14032020-2.pdf\">Orden SAN\/306\/2020, de 13 de marzo, por la que se ampl\u00edan las medidas preventivas en relaci\u00f3n con el COVID-19 para toda la poblaci\u00f3n y el territorio de la Comunidad de Castilla y Le\u00f3n.<\/a><\/p>\n<p><a href=\"http:\/\/bocyl.jcyl.es\/boletines\/2020\/03\/14\/pdf\/BOCYL-D-14032020-4.pdf\">Orden EDU\/308\/2020, de 13 marzo, por la que se concreta el funcionamiento de los centros docentes no universitarios de la Comunidad de Castilla y Le\u00f3n, cuya actividad docente presencial y actividades extraescolares han sido suspendidas como consecuencia del coronavirus, COVID-19<\/a><\/p>\n<p><a href=\"http:\/\/bocyl.jcyl.es\/boletines\/2020\/03\/13\/pdf\/BOCYL-D-13032020-4.pdf\">Orden SAN\/300\/2020, de 12 de marzo, por la que se ampl\u00edan las medidas preventivas en relaci\u00f3n con el COVID-19 para toda la poblaci\u00f3n y el territorio de la Comunidad de Castilla y Le\u00f3n.<\/a><\/p>\n<p><a href=\"http:\/\/bocyl.jcyl.es\/boletines\/2020\/03\/12\/pdf\/BOCYL-D-12032020-1.pdf\">Orden SAN\/295\/2020, de 11 de marzo, por la que se adoptan medidas preventivas y recomendaciones en relaci\u00f3n con el COVID-19 para toda la poblaci\u00f3n y el territorio de la Comunidad de Castilla y Le\u00f3n.<\/a><\/p>\n<p><strong>\u25aa Extremadura:<\/strong><\/p>\n<p><a href=\"http:\/\/doe.gobex.es\/pda\/index.php\">Resoluci\u00f3n de 13 de marzo de 2020, del Vicepresidente Segundo y Consejero, por la que se ordena la publicaci\u00f3n en el Diario Oficial de Extremadura del Acuerdo del Consejo de Gobierno de la Junta de Extremadura de 12 de marzo de 2020, por el que se adoptan medidas preventivas de salud p\u00fablica en relaci\u00f3n con la actividad educativa en Extremadura como consecuencia de la situaci\u00f3n y evoluci\u00f3n del coronavirus (COVID-19).<\/a><\/p>\n<p><strong>\u25aa Galicia:<\/strong><\/p>\n<p><a href=\"https:\/\/www.xunta.gal\/dog\/Publicados\/excepcional\/2020\/20200313\/2256\/AnuncioG0244-130320-1_es.html\">Resoluci\u00f3n de 13 de marzo de 2020, de la Secretar\u00eda General T\u00e9cnica de la Conseller\u00eda de Presidencia, Administraciones P\u00fablicas y Justicia, por la que se da publicidad al Acuerdo del Consello de la Xunta de Galicia, de 13 de marzo de 2020, por el que se declara la situaci\u00f3n de emergencia sanitaria en el territorio de la Comunidad Aut\u00f3noma de Galicia y se activa el Plan territorial de emergencias de Galicia (Platerga) en su nivel IG (emergencia de inter\u00e9s gallego), como consecuencia de la evoluci\u00f3n de la epidemia del coronavirus COVID-19.<\/a><\/p>\n<p><strong>\u25aa Islas Baleares:<\/strong><\/p>\n<p><a href=\"http:\/\/www.caib.es\/eboibfront\/es\/2020\/11130\">Resoluci\u00f3n de la Directora General de Salud P\u00fablica y Participaci\u00f3n por la que establecen medidas de control en relaci\u00f3n a la celebraci\u00f3n en el territorio de las Illes Balears de determinados eventos con afluencia de p\u00fablico incluyendo eventos deportivos consistentes en pruebas deportivas no clasificatorias.<\/a><\/p>\n<p><a href=\"https:\/\/www.caib.es\/eboibfront\/es\/2020\/11132\">Acuerdo del Consejo de Gobierno de 13 de marzo de 2020 por el que se aprueba el Plan de Medidas Excepcionales para Limitar la Propagaci\u00f3n y el Contagio del COVID-19.<\/a><\/p>\n<p><a href=\"https:\/\/www.caib.es\/eboibfront\/es\/2020\/11132\">Decreto de organizaci\u00f3n de los servicios y funciones del Consell de Mallorca y de sus organismos aut\u00f3nomos para hacer frente a las medidas de contenci\u00f3n para la situaci\u00f3n creada por el coronavirus COVID-19.<\/a><\/p>\n<p><a href=\"https:\/\/www.caib.es\/eboibfront\/es\/2020\/11132\">Decreto de la presidenta del Consejo de Mallorca, de fecha 13 de marzo de 2020, sobre medidas preventivas, de protecci\u00f3n y organizativas de aplicaci\u00f3n al personal del Consejo de Mallorca, el IMAS y el resto de sus organismos aut\u00f3nomos y entes dependientes con motivo del coronavirus COVID-19.<\/a><\/p>\n<p><strong>\u25aa Madrid:<\/strong><\/p>\n<p><a href=\"http:\/\/www.bocm.es\/boletin\/CM_Orden_BOCM\/2020\/03\/10\/BOCM-20200310-1.PDF\">Orden 338\/2020, de 9 de marzo, de la Consejer\u00eda de Sanidad, por la que se adoptan medidas preventivas y recomendaciones de salud p\u00fablica en la Comunidad de Madrid como consecuencia de la situaci\u00f3n y evoluci\u00f3n del coronavirus (COVID-19).<\/a><\/p>\n<p><a href=\"http:\/\/www.bocm.es\/boletin\/CM_Orden_BOCM\/2020\/03\/11\/BOCM-20200311-1\">Orden 344\/2020, de 10 de marzo, de la Consejer\u00eda de Sanidad, por la que se adoptan medidas preventivas de salud p\u00fablica en la Comunidad de Madrid como consecuencia de la situaci\u00f3n y evoluci\u00f3n del coronavirus (COVID-19).<\/a><\/p>\n<p><a href=\"http:\/\/www.bocm.es\/boletin\/CM_Orden_BOCM\/2020\/03\/12\/BOCM-20200312-1.PDF\">Orden 348\/2020, de 11 de marzo, de la Consejer\u00eda de Sanidad, por la que se adoptan medidas preventivas de salud p\u00fablica en la Comunidad de Madrid como consecuencia de la situaci\u00f3n y evoluci\u00f3n del coronavirus (COVID-19).<\/a><\/p>\n<p><a href=\"http:\/\/www.bocm.es\/boletin\/CM_Orden_BOCM\/2020\/03\/13\/BOCM-20200313-181.PDF\">Orden 367\/2020, de 13 de marzo, de la Consejer\u00eda de Sanidad, por la que se adoptan medidas preventivas de salud p\u00fablica en la Comunidad de Madrid como consecuencia de la situaci\u00f3n y evoluci\u00f3n del coronavirus (COVID-19).<\/a><\/p>\n<p><a href=\"http:\/\/www.bocm.es\/boletin\/CM_Orden_BOCM\/2020\/03\/12\/BOCM-20200312-2.PDF\">Resoluci\u00f3n de 11 de marzo de 2020, de la Direcci\u00f3n General de Salud P\u00fablica de la Comunidad de Madrid, por la que se adoptan medidas en materia de salud p\u00fablica en relaci\u00f3n con la actividad de los centros ocupacionales que prestan atenci\u00f3n a personas con discapacidad intelectual y los servicios sociales de atenci\u00f3n temprana a menores.<\/a><\/p>\n<p><strong>\u25aa Navarra:<\/strong><\/p>\n<p><a href=\"https:\/\/bon.navarra.es\/es\/anuncio\/-\/texto\/2020\/52\/0\">Orden Foral 3\/2020, de 13 de marzo, de la Consejera de Salud, por la que se adoptan medidas preventivas e instrucciones de salud p\u00fablica como consecuencia de la situaci\u00f3n y evoluci\u00f3n del coronavirus (COVID-19).<\/a><\/p>\n<p><a href=\"https:\/\/bon.navarra.es\/es\/anuncio\/-\/texto\/2020\/51\/0\">Orden Foral 47\/2020, de 12 de marzo, del Consejero de Presidencia, Igualdad, Funci\u00f3n P\u00fablica e Interior por la que se autorizan medidas a adoptar en los centros de trabajo dependientes de la Administraci\u00f3n de la Comunidad Foral de Navarra y sus organismos aut\u00f3nomos con motivo del COVID-19.<\/a><\/p>\n<p><strong>\u25aa La Rioja:<\/strong><\/p>\n<p><a href=\"https:\/\/web.larioja.org\/bor-portada\/boranuncio?n=12496781-4-HTML-530469-X\">Resoluci\u00f3n de 11 de marzo de 2020, de la Secretar\u00eda General T\u00e9cnica de la Consejer\u00eda de Servicios Sociales y a la Ciudadan\u00eda, por la que se dispone la publicaci\u00f3n del Acuerdo del Consejo de Gobierno sobre medidas preventivas y recomendaciones relacionadas con la infecci\u00f3n del coronavirus (COVID-19).<\/a><\/p>\n<p><a href=\"https:\/\/web.larioja.org\/bor-portada\/boranuncio?n=12496442-7-HTML-530465-X\">Resoluci\u00f3n de 11 de marzo de 2020, de la Consejer\u00eda de Salud, sobre medidas preventivas y terap\u00e9uticas relacionadas con la infecci\u00f3n del coronavirus (COVID-19).<\/a><\/p>\n<p><a href=\"https:\/\/web.larioja.org\/bor-portada\/boranuncio?n=12496776-4-HTML-530468-X\">Resoluci\u00f3n 441\/2020, de 11 de marzo, de la Direcci\u00f3n General de Funci\u00f3n P\u00fablica, por la que se establecen medidas a adoptar en materia de gesti\u00f3n de personal en los centros de trabajo dependientes de la Administraci\u00f3n General de la Comunidad Aut\u00f3noma de La Rioja con motivo de la infecci\u00f3n del coronavirus (COVID-19).<\/a><\/p>\n<p><strong>\u25aa Valencia:<\/strong><\/p>\n<p><a href=\"https:\/\/www.dogv.gva.es\/datos\/2020\/03\/13\/pdf\/2020_2561.pdf\">Resoluci\u00f3n de 13 de marzo de 2020, de la Consellera de Sanidad Universal y Salud P\u00fablica, por la que se acuerdan medidas especiales de car\u00e1cter preventivo en materia de espect\u00e1culos p\u00fablicos, actividades recreativas, actividades socioculturales y establecimientos p\u00fablicos, para limitar la propagaci\u00f3n y contagio por el COVID-19.<\/a><\/p>\n<p><a href=\"https:\/\/www.dogv.gva.es\/datos\/2020\/03\/13\/pdf\/2020_2560.pdf\">Resoluci\u00f3n de 13 de marzo de 2020, de la Consellera de Sanidad Universal y Salud P\u00fablica, por la que se acuerdan medidas excepcionales para acontecimientos de car\u00e1cter cultural, recreativo o de ocio, de titularidad p\u00fablica y privada, en la Comunidad Valenciana, para limitar la propagaci\u00f3n y el contagio por el Covid-19.<\/a><\/p>\n<p><a href=\"https:\/\/www.dogv.gva.es\/datos\/2020\/03\/13\/pdf\/2020_2483.pdf\">Resoluci\u00f3n de 12 de marzo de 2020, de la Consellera de Sanidad Universal y Salud P\u00fablica, por la que se acuerdan medidas excepcionales en relaci\u00f3n con los centros de ocio especializados de Atenci\u00f3n a Mayores (CEAM), clubes sociales de jubilados, hogares del pensionista o similares, de cualquier titularidad, cuyo objetivo sea cultural o de ocio, para limitar la propagaci\u00f3n y el contagio del Covid-19.<\/a><\/p>\n<p><a href=\"https:\/\/www.dogv.gva.es\/datos\/2020\/03\/13\/pdf\/2020_2484.pdf\">Resoluci\u00f3n de 12 de marzo de 2020, de la Consellera de Sanidad Universal y Salud P\u00fablica, por la que se acuerdan medidas excepcionales en relaci\u00f3n con las actividades y viajes de ocio, culturales o similares, organizados por centros sociales y educativos de cualquier nivel, asociaci\u00f3n, entidad cultural u otros, dentro o fuera de la Comunitat Valenciana, para limitar la propagaci\u00f3n y el contagio del Covid-19.<\/a><\/p>\n<p><a href=\"https:\/\/www.dogv.gva.es\/datos\/2020\/03\/12\/pdf\/2020_2446.pdf\">Resoluci\u00f3n de 11 de marzo de 2020, de la Consellera de Sanidad Universal y Salud P\u00fablica, por la que se acuerdan medidas excepcionales para eventos festivos y de concentraci\u00f3n de personas, en la Comunitat Valenciana, para limitar la propagaci\u00f3n y el contagio por el Covid-19.<\/a><\/p>\n<p>\u25aa <strong>Ceuta<\/strong><\/p>\n<p><a href=\"https:\/\/www.ceuta.es\/ceuta\/component\/jdownloads\/viewdownload\/1619\/20190?Itemid\">Decreto del Consejero de Sanidad, Consumo y Gobernaci\u00f3n de la Ciudad de Ceuta, D. Francisco Javier Guerrero Gallego, de 13 de marzo de 2020, por el corrigen errores del anterior Decreto de 13 de marzo, por el que se dictan medidas excepcionales para limitar la propagaci\u00f3n y el contagio por el COVID-19.<\/a><\/p>\n<p>\u00a9 La presente informaci\u00f3n es propiedad de <strong>Escura<\/strong>, <strong>abogados<\/strong> y <strong>economistas<\/strong>, quedando prohibida su reproducci\u00f3n sin permiso expreso.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":28702,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,27],"tags":[],"class_list":["post-17386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiscal-contable","category-recursos-humanos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Escura. Abogados y Economistas<\/title>\n<meta name=\"description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.escura.com\/es\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estado de alarma \u2013 principales resoluciones, acuerdos, anuncios y comunicados emitidos por las diversas autoridades de las diferentes Comunidades Aut\u00f3nomas y Ciudades Aut\u00f3nomas\" \/>\n<meta property=\"og:description\" content=\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.escura.com\/es\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\/\" \/>\n<meta property=\"og:site_name\" content=\"Escura | Abogados y Economistas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/escura.abogados\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-15T11:57:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/madrid-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"649\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"escura\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:site\" content=\"@escura_abogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"escura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\\\/\"},\"author\":{\"name\":\"escura\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/4edd59e125b9654539921a4ec1da53b1\"},\"headline\":\"Estado de alarma \u2013 principales resoluciones, acuerdos, anuncios y comunicados emitidos por las diversas autoridades de las diferentes Comunidades Aut\u00f3nomas y Ciudades Aut\u00f3nomas\",\"datePublished\":\"2020-03-15T11:57:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\\\/\"},\"wordCount\":1950,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/madrid-2.jpg\",\"articleSection\":[\"Fiscal - Contable\",\"Recursos Humanos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\\\/\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\\\/\",\"name\":\"Escura. Abogados y Economistas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/madrid-2.jpg\",\"datePublished\":\"2020-03-15T11:57:43+00:00\",\"description\":\"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.escura.com\\\/es\\\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/madrid-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.escura.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/madrid-2.jpg\",\"width\":1000,\"height\":649},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estado de alarma \u2013 principales resoluciones, acuerdos, anuncios y comunicados emitidos por las diversas autoridades de las diferentes Comunidades Aut\u00f3nomas y Ciudades Aut\u00f3nomas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"name\":\"Escura | Abogados y Economistas\",\"description\":\"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.escura.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#organization\",\"name\":\"Escura. Abogados y economistas\",\"url\":\"https:\\\/\\\/www.escura.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Escura. Abogados y economistas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/escura.abogados\",\"https:\\\/\\\/x.com\\\/escura_abogados\",\"https:\\\/\\\/www.instagram.com\\\/escura_abogados\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bufete-escura\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BufeteEscura\\\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.escura.com\\\/es\\\/#\\\/schema\\\/person\\\/4edd59e125b9654539921a4ec1da53b1\",\"name\":\"escura\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g\",\"caption\":\"escura\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Escura. Abogados y Economistas","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.escura.com\/es\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\/","og_locale":"es_ES","og_type":"article","og_title":"Estado de alarma \u2013 principales resoluciones, acuerdos, anuncios y comunicados emitidos por las diversas autoridades de las diferentes Comunidades Aut\u00f3nomas y Ciudades Aut\u00f3nomas","og_description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","og_url":"https:\/\/www.escura.com\/es\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\/","og_site_name":"Escura | Abogados y Economistas","article_publisher":"https:\/\/www.facebook.com\/escura.abogados","article_published_time":"2020-03-15T11:57:43+00:00","og_image":[{"width":1000,"height":649,"url":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/madrid-2.jpg","type":"image\/jpeg"}],"author":"escura","twitter_card":"summary_large_image","twitter_creator":"@escura_abogados","twitter_site":"@escura_abogados","twitter_misc":{"Escrito por":"escura","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.escura.com\/es\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\/#article","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\/"},"author":{"name":"escura","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/4edd59e125b9654539921a4ec1da53b1"},"headline":"Estado de alarma \u2013 principales resoluciones, acuerdos, anuncios y comunicados emitidos por las diversas autoridades de las diferentes Comunidades Aut\u00f3nomas y Ciudades Aut\u00f3nomas","datePublished":"2020-03-15T11:57:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.escura.com\/es\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\/"},"wordCount":1950,"commentCount":0,"publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"image":{"@id":"https:\/\/www.escura.com\/es\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/madrid-2.jpg","articleSection":["Fiscal - Contable","Recursos Humanos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.escura.com\/es\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.escura.com\/es\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\/","url":"https:\/\/www.escura.com\/es\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\/","name":"Escura. Abogados y Economistas","isPartOf":{"@id":"https:\/\/www.escura.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.escura.com\/es\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\/#primaryimage"},"image":{"@id":"https:\/\/www.escura.com\/es\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/madrid-2.jpg","datePublished":"2020-03-15T11:57:43+00:00","description":"Bufete de abogados y economistas. Conoce nuestras areas y nuestro blog, uno de los de referencia en el asesoramiento legal de empresas. Calidad certificada en ISO y por las principales gu\u00edas jur\u00eddicas internacionales","breadcrumb":{"@id":"https:\/\/www.escura.com\/es\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.escura.com\/es\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\/#primaryimage","url":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/madrid-2.jpg","contentUrl":"https:\/\/www.escura.com\/wp-content\/uploads\/2020\/03\/madrid-2.jpg","width":1000,"height":649},{"@type":"BreadcrumbList","@id":"https:\/\/www.escura.com\/es\/estado-de-alarma-principales-resoluciones-acuerdos-anuncios-y-comunicados-emitidos-por-las-diversas-autoridades-de-las-diferentes-comunidades-autonomas-y-ciudades-autonomas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.escura.com\/es\/"},{"@type":"ListItem","position":2,"name":"Estado de alarma \u2013 principales resoluciones, acuerdos, anuncios y comunicados emitidos por las diversas autoridades de las diferentes Comunidades Aut\u00f3nomas y Ciudades Aut\u00f3nomas"}]},{"@type":"WebSite","@id":"https:\/\/www.escura.com\/es\/#website","url":"https:\/\/www.escura.com\/es\/","name":"Escura | Abogados y Economistas","description":"Escura es uno de los despachos de abogados de mayor prestigio en Barcelona, Madrid y Tarragona","publisher":{"@id":"https:\/\/www.escura.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.escura.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.escura.com\/es\/#organization","name":"Escura. Abogados y economistas","url":"https:\/\/www.escura.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Escura. Abogados y economistas"},"image":{"@id":"https:\/\/www.escura.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/escura.abogados","https:\/\/x.com\/escura_abogados","https:\/\/www.instagram.com\/escura_abogados\/","https:\/\/www.linkedin.com\/company\/bufete-escura","https:\/\/www.youtube.com\/user\/BufeteEscura\/videos"]},{"@type":"Person","@id":"https:\/\/www.escura.com\/es\/#\/schema\/person\/4edd59e125b9654539921a4ec1da53b1","name":"escura","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a721c427419b1a5c865549a2d42be09e26988a9b2c8088a346d420663fa98dd?s=96&d=mm&r=g","caption":"escura"}}]}},"_links":{"self":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/17386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/comments?post=17386"}],"version-history":[{"count":0,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/posts\/17386\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media\/28702"}],"wp:attachment":[{"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/media?parent=17386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/categories?post=17386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escura.com\/es\/wp-json\/wp\/v2\/tags?post=17386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}